{"id":100024,"date":"2020-08-20T15:32:19","date_gmt":"2020-08-20T13:32:19","guid":{"rendered":"https:\/\/aleasoft.com\/?p=100024"},"modified":"2020-08-21T11:56:51","modified_gmt":"2020-08-21T09:56:51","slug":"gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/","title":{"rendered":"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate"},"content":{"rendered":"<p><strong>AleaSoft, 20. August 2020. Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl. Die Preise auf den meisten europ\u00e4ischen Stromm\u00e4rkten stiegen in den ersten Tagen der dritten Augustwoche, beg\u00fcnstigt durch das Gas und eine geringe erneuerbare Energieerzeugung in Deutschland, aber es wird erwartet, dass sich dieser Trend \u00e4ndert und die Preise bis zum Ende der Woche sinken.<\/strong><\/p>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/'>Nachrichten auf Englisch<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 20. August 2020. Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl. Die Preise auf den meisten europ\u00e4ischen Stromm\u00e4rkten stiegen in den ersten Tagen der dritten Augustwoche, beg\u00fcnstigt durch das Gas und eine geringe erneuerbare Energieerzeugung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-100024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate\" \/>\n<meta property=\"og:description\" content=\"Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-20T13:32:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-21T09:56:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/08\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2303\" \/>\n\t<meta property=\"og:image:height\" content=\"1606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate\",\"datePublished\":\"2020-08-20T13:32:19+00:00\",\"dateModified\":\"2020-08-21T09:56:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/\",\"name\":\"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png\",\"datePublished\":\"2020-08-20T13:32:19+00:00\",\"dateModified\":\"2020-08-21T09:56:51+00:00\",\"description\":\"Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\\\/MWh. Brent bleibt stabil bei 45 $\\\/bbl.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png\",\"width\":2303,\"height\":1606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate - AleaSoft Energy Forecasting","description":"Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/","og_locale":"de_DE","og_type":"article","og_title":"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate","og_description":"Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl.","og_url":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2020-08-20T13:32:19+00:00","article_modified_time":"2020-08-21T09:56:51+00:00","og_image":[{"width":2303,"height":1606,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/08\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Verfasst von":"AleaSoft Energy Forecasting"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate","datePublished":"2020-08-20T13:32:19+00:00","dateModified":"2020-08-21T09:56:51+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/"},"wordCount":92,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/08\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png","articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/","url":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/","name":"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/08\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png","datePublished":"2020-08-20T13:32:19+00:00","dateModified":"2020-08-21T09:56:51+00:00","description":"Die Gaspreise setzen den Ende Juli begonnenen Aufw\u00e4rtstrend fort und verzeichnen bereits Werte \u00e4hnlich denen von Mitte April, \u00fcber 8 \u20ac\/MWh. Brent bleibt stabil bei 45 $\/bbl.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/08\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/08\/20200820-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png","width":2303,"height":1606},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/de\/gaspreise-setzen-ihre-erholung-fort-verzeichnen-hoechsten-werte-letzten-vier-monate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Gaspreise setzen ihre Erholung fort und verzeichnen die h\u00f6chsten Werte der letzten vier Monate"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts\/100024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/comments?post=100024"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts\/100024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/media\/99989"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/media?parent=100024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/categories?post=100024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/tags?post=100024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}