{"id":130620,"date":"2022-10-31T13:56:29","date_gmt":"2022-10-31T12:56:29","guid":{"rendered":"https:\/\/aleasoft.com\/?p=130620"},"modified":"2022-11-01T03:48:26","modified_gmt":"2022-11-01T02:48:26","slug":"solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/","title":{"rendered":"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 31. Oktober 2022. In der vierten Oktoberwoche stieg die Solarstromproduktion im Vergleich zur Vorwoche in allen analysierten europ\u00e4ischen M\u00e4rkten. Der gr\u00f6\u00dfte Zuwachs von 21 % wurde auf dem spanischen Markt verzeichnet, gefolgt von einem Anstieg von 19 % auf dem portugiesischen Markt. Auf dem franz\u00f6sischen und deutschen Markt erreichte die w\u00f6chentliche Windenergieproduktion ebenfalls h\u00f6here Werte als in der Vorwoche registriert. In Frankreich war die Windenergieproduktion am 24. Oktober die zweith\u00f6chste seit April.<\/strong><\/p>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/'>Nachrichten auf Englisch<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 31. Oktober 2022. In der vierten Oktoberwoche stieg die Solarstromproduktion im Vergleich zur Vorwoche in allen analysierten europ\u00e4ischen M\u00e4rkten. Der gr\u00f6\u00dfte Zuwachs von 21 % wurde auf dem spanischen Markt verzeichnet, gefolgt von einem Anstieg von 19 % auf dem portugiesischen Markt. Auf dem franz\u00f6sischen und deutschen Markt erreichte die w\u00f6chentliche Windenergieproduktion [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":130595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[7511],"class_list":["post-130620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-marktanalyse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten - AleaSoft Energy Forecasting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten\" \/>\n<meta property=\"og:description\" content=\"AleaSoft Energy Forecasting, 31. Oktober 2022. In der vierten Oktoberwoche stieg die Solarstromproduktion im Vergleich zur Vorwoche in allen analysierten europ\u00e4ischen M\u00e4rkten. Der gr\u00f6\u00dfte Zuwachs von 21 % wurde auf dem spanischen Markt verzeichnet, gefolgt von einem Anstieg von 19 % auf dem portugiesischen Markt. Auf dem franz\u00f6sischen und deutschen Markt erreichte die w\u00f6chentliche Windenergieproduktion [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-31T12:56:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-01T02:48:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\"},\"headline\":\"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten\",\"datePublished\":\"2022-10-31T12:56:29+00:00\",\"dateModified\":\"2022-11-01T02:48:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/\"},\"wordCount\":91,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png\",\"keywords\":[\"marktanalyse\"],\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/\",\"name\":\"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png\",\"datePublished\":\"2022-10-31T12:56:29+00:00\",\"dateModified\":\"2022-11-01T02:48:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png\",\"width\":2282,\"height\":1589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten - AleaSoft Energy Forecasting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/","og_locale":"de_DE","og_type":"article","og_title":"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten","og_description":"AleaSoft Energy Forecasting, 31. Oktober 2022. In der vierten Oktoberwoche stieg die Solarstromproduktion im Vergleich zur Vorwoche in allen analysierten europ\u00e4ischen M\u00e4rkten. Der gr\u00f6\u00dfte Zuwachs von 21 % wurde auf dem spanischen Markt verzeichnet, gefolgt von einem Anstieg von 19 % auf dem portugiesischen Markt. Auf dem franz\u00f6sischen und deutschen Markt erreichte die w\u00f6chentliche Windenergieproduktion [&hellip;]","og_url":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2022-10-31T12:56:29+00:00","article_modified_time":"2022-11-01T02:48:26+00:00","og_image":[{"width":2282,"height":1589,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Verfasst von":"AleaSoft Energy Forecasting","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61"},"headline":"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten","datePublished":"2022-10-31T12:56:29+00:00","dateModified":"2022-11-01T02:48:26+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/"},"wordCount":91,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png","keywords":["marktanalyse"],"articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/","url":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/","name":"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png","datePublished":"2022-10-31T12:56:29+00:00","dateModified":"2022-11-01T02:48:26+00:00","breadcrumb":{"@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221031-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png","width":2282,"height":1589},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/de\/solar-trotzt-dem-herbst-und-erhoeht-die-produktion-auf-den-europaeischen-maerkten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/"},{"@type":"ListItem","position":2,"name":"Solar trotzt dem Herbst und erh\u00f6ht die Produktion auf den europ\u00e4ischen M\u00e4rkten"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"}}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts\/130620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/comments?post=130620"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts\/130620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/media\/130595"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/media?parent=130620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/categories?post=130620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/tags?post=130620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}