{"id":78976,"date":"2019-04-03T00:00:00","date_gmt":"2019-04-02T22:00:00","guid":{"rendered":"https:\/\/aleasoft.com\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/"},"modified":"2024-03-05T10:02:05","modified_gmt":"2024-03-05T09:02:05","slug":"mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/","title":{"rendered":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien."},"content":{"rendered":"<p><a href='https:\/\/aleasoft.com\/de\/anwendungsfalle-beratung-energieprognosen\/ppa-dienstleistungen-synergien\/' class='alea-banner-link' data-alea-gtm-event-category='banner-horizontal' data-alea-gtm-event-label='ppa'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/banners_ppa_de.jpg' alt='Angebot zur langfristigen Strompreisprognose von PPAs' style=''\/><\/a><br \/>\n<a href=\"https:\/\/aleasoft.com\/with-20-years-developing-energy-forecasting-aleasoft-faces-new-challenges-renewables\/\">Nachrichten auf Englisch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachrichten auf Englisch<\/p>\n","protected":false},"author":1,"featured_media":67022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[572],"class_list":["post-78976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.<\/title>\n<meta name=\"description\" content=\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\" \/>\n<meta property=\"og:description\" content=\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-02T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T09:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/04\/20190403-aleasoft-solar-panels.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\",\"datePublished\":\"2019-04-02T22:00:00+00:00\",\"dateModified\":\"2024-03-05T09:02:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/\"},\"wordCount\":24,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/20190403-aleasoft-solar-panels.jpg\",\"keywords\":[\"nachrichten\"],\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/\",\"name\":\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/20190403-aleasoft-solar-panels.jpg\",\"datePublished\":\"2019-04-02T22:00:00+00:00\",\"dateModified\":\"2024-03-05T09:02:05+00:00\",\"description\":\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/20190403-aleasoft-solar-panels.jpg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/20190403-aleasoft-solar-panels.jpg\",\"width\":1280,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","description":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/","og_locale":"de_DE","og_type":"article","og_title":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","og_description":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","og_url":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2019-04-02T22:00:00+00:00","article_modified_time":"2024-03-05T09:02:05+00:00","og_image":[{"width":1280,"height":500,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/04\/20190403-aleasoft-solar-panels.jpg","type":"image\/jpeg"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Verfasst von":"AleaSoft Energy Forecasting","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","datePublished":"2019-04-02T22:00:00+00:00","dateModified":"2024-03-05T09:02:05+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/"},"wordCount":24,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/04\/20190403-aleasoft-solar-panels.jpg","keywords":["nachrichten"],"articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/","url":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/","name":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/04\/20190403-aleasoft-solar-panels.jpg","datePublished":"2019-04-02T22:00:00+00:00","dateModified":"2024-03-05T09:02:05+00:00","description":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/04\/20190403-aleasoft-solar-panels.jpg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/04\/20190403-aleasoft-solar-panels.jpg","width":1280,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/de\/mit-20-jahren-erfahrung-entwicklung-energieprognosen-stellt-sich-aleasoft-neuen-herausforderungen-erneuerbaren-energien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/de\/"},{"@type":"ListItem","position":2,"name":"Mit 20 Jahren Erfahrung in der Entwicklung von Energieprognosen stellt sich AleaSoft den neuen Herausforderungen der erneuerbaren Energien."}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts\/78976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/comments?post=78976"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/posts\/78976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/media\/67022"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/media?parent=78976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/categories?post=78976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/de\/wp-json\/wp\/v2\/tags?post=78976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}