{"id":97263,"date":"2020-07-20T17:47:42","date_gmt":"2020-07-20T15:47:42","guid":{"rendered":"https:\/\/aleasoft.com\/?page_id=97263"},"modified":"2026-06-10T23:51:59","modified_gmt":"2026-06-10T21:51:59","slug":"informes-periciales-arbitraje-mercados","status":"publish","type":"page","link":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/","title":{"rendered":"Informes periciales para demandas, arbitraje y mediaci\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"97263\" class=\"elementor elementor-97263\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1749c8 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1749c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57feceb\" data-id=\"57feceb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff7e9d elementor-widget elementor-widget-heading\" data-id=\"6ff7e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informes de mercados, regulatorios y periciales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46aa994 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-hidden-phone elementor-section-height-default\" data-id=\"46aa994\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-582ed12\" data-id=\"582ed12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5747f9 elementor-widget elementor-widget-heading\" data-id=\"d5747f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Informes de mercados, regulatorios y periciales<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee77f8 elementor-widget elementor-widget-heading\" data-id=\"4ee77f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">An\u00e1lisis experto para guiar tus decisiones estrat\u00e9gicas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-541c7f9\" data-id=\"541c7f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7362cb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7362cb3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-887f528\" data-id=\"887f528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-176bb5d elementor-widget elementor-widget-spacer\" data-id=\"176bb5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdb5dec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdb5dec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-208f4ea\" data-id=\"208f4ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d25e78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d25e78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5fda7e4\" data-id=\"5fda7e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4056ec8 elementor-widget elementor-widget-image\" data-id=\"4056ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg\" class=\"attachment-full size-full wp-image-155175\" alt=\"\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg 2048w, https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-300x200.jpg 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-1024x683.jpg 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-150x100.jpg 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-768x512.jpg 768w, https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-649218f\" data-id=\"649218f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c8656d elementor-widget elementor-widget-text-editor\" data-id=\"4c8656d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Realizamos informes t\u00e9cnicos para casos de consultor\u00edas relacionadas con temas de mediaci\u00f3n y arbitraje en el mercado el\u00e9ctrico o de gas:<\/p>\n<p><ul>\n \t<li>Informes periciales para mediaciones, arbitrajes y demandas asociadas a los mercados de electricidad y gas de Espa\u00f1a y Portugal.<\/li>\n \t<li>Informes t\u00e9cnicos para mediaciones relacionadas con la terminaci\u00f3n anticipada de contratos de suministro de energ\u00eda o PPA.<\/li>\n<\/ul><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ee6a3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"30ee6a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjkyMjg1IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar Informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-676d4d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"676d4d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73ce17c\" data-id=\"73ce17c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617636e elementor-widget elementor-widget-spacer\" data-id=\"617636e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34f2a38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34f2a38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-002f0f4\" data-id=\"002f0f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bddeaf1 elementor-widget elementor-widget-html\" data-id=\"bddeaf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\n    var aleadraw = function() {\n        window.dispatchEvent(new Event('resize'));\n    }\n    \n    var elements = document.getElementsByClassName(\"elementor-tab-title\");\n\nfor (var i=0; i<elements.length; i++) {\n    elements[i].addEventListener('click', aleadraw, false);\n    }\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-425a26e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"425a26e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bb7814\" data-id=\"6bb7814\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-537942f e-transform elementor-widget elementor-widget-image\" data-id=\"537942f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aleasoft.com\/es\/servicios\/previsiones-precios-energia\/largo-plazo\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1144\" height=\"208\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/05\/previsiones-largo-plazo.png\" class=\"attachment-full size-full wp-image-144154\" alt=\"\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/05\/previsiones-largo-plazo.png 1144w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/05\/previsiones-largo-plazo-300x55.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/05\/previsiones-largo-plazo-1024x186.png 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/05\/previsiones-largo-plazo-150x27.png 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/05\/previsiones-largo-plazo-768x140.png 768w\" sizes=\"(max-width: 1144px) 100vw, 1144px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe46e4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe46e4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8798650\" data-id=\"8798650\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c38c197 elementor-widget elementor-widget-spacer\" data-id=\"c38c197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb10c9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb10c9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5abcb8\" data-id=\"e5abcb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d72b0c elementor-widget elementor-widget-heading\" data-id=\"7d72b0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/es\/aleaconsulting\/\">Otros servicios de mercados de energ\u00eda que te pueden interesar<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25bf75c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25bf75c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83c08df\" data-id=\"83c08df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b2dfdc elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"4b2dfdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07d66d9\" data-id=\"07d66d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e0d0e6 elementor-widget elementor-widget-button\" data-id=\"7e0d0e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/casos-previsiones\/reportes-previsiones-precios-valoracion-carteras-auditorias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Auditor\u00edas de previsi\u00f3n de mercados<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e88a3d2\" data-id=\"e88a3d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0982a4 elementor-widget elementor-widget-button\" data-id=\"b0982a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/casos-previsiones\/consultoria-en-energia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">An\u00e1lisis para consultor\u00eda estrat\u00e9gica<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0106dcb elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"0106dcb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87b48c6\" data-id=\"87b48c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92796e2 elementor-widget elementor-widget-button\" data-id=\"92796e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/consultoria-estrategica\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ayuda para la toma de decisiones estrat\u00e9gicas en el sector renovable<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a8b93b7\" data-id=\"a8b93b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9650c75 elementor-widget elementor-widget-button\" data-id=\"9650c75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/casos-previsiones\/previsiones-futuros-gas-electricidad\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsiones de futuros de gas y electricidad<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f901fb8 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"f901fb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-afbcf38\" data-id=\"afbcf38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3fb03e elementor-widget elementor-widget-button\" data-id=\"a3fb03e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/previsiones-precios-energia\/largo-plazo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsiones de curvas de precios de largo plazo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2085165\" data-id=\"2085165\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30a8f76 elementor-widget elementor-widget-button\" data-id=\"30a8f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/previsiones-demanda-energia-electrica\/largo-plazo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsiones de demanda el\u00e9ctrica de largo plazo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c7d53da elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"c7d53da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-944e70c\" data-id=\"944e70c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc909fd elementor-widget elementor-widget-button\" data-id=\"bc909fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/previsiones-energia-renovable\/largo-plazo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsiones de energ\u00edas renovables de largo plazo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-130fc47\" data-id=\"130fc47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfc1e82 elementor-widget elementor-widget-button\" data-id=\"bfc1e82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/autoconsumo-gestion-demanda-smartcities\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Autoconsumo, gesti\u00f3n de la demanda, smart cities<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d979b8 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"6d979b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-800c88a\" data-id=\"800c88a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2136f59 elementor-widget elementor-widget-button\" data-id=\"2136f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/previsiones-energia-renovable\/corto-plazo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsiones de energ\u00edas renovables de corto plazo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08475b5\" data-id=\"08475b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd1d2be elementor-widget elementor-widget-button\" data-id=\"dd1d2be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/es\/servicios\/previsiones-energia-renovable\/medio-plazo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsiones de energ\u00edas renovables de medio plazo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08fd962 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08fd962\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d31430\" data-id=\"4d31430\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-259328c elementor-widget elementor-widget-heading\" data-id=\"259328c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/es\/noticias\/\">Noticias destacadas<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ab00cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0ab00cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e06a5f3\" data-id=\"e06a5f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95ddfaf elementor-widget elementor-widget-template\" data-id=\"95ddfaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"143554\" class=\"elementor elementor-143554\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2ecf43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2ecf43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ca4b18a\" data-id=\"ca4b18a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b17c057 elementor-widget elementor-widget-shortcode\" data-id=\"b17c057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><article class=\"noticia-card-fija \"><div class=\"noticia-card-imagen-wrapper\"><a href=\"https:\/\/aleasoft.com\/es\/entrevista-periodico-energia-antonio-delgado-rigal-20260330\/\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-scaled.jpg\" class=\"noticia-card-imagen wp-post-image\" alt=\"Entrevista de El Peri\u00f3dico de la Energ\u00eda a Antonio Delgado Rigal, Doctor en Inteligencia Artificial y CEO de AleaSoft Energy Forecasting\" loading=\"lazy\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-scaled.jpg 2048w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-300x225.jpg 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-1024x768.jpg 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-150x113.jpg 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-768x576.jpg 768w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/div><div class=\"card-contenido\"><h3 class=\"elementor-heading-title elementor-size-default card-titulo\"><a href=\"https:\/\/aleasoft.com\/es\/entrevista-periodico-energia-antonio-delgado-rigal-20260330\/\">Entrevista de El Peri\u00f3dico de la Energ\u00eda a Antonio Delgado Rigal, Doctor en Inteligencia Artificial y CEO de AleaSoft Energy Forecasting<\/a><\/h3><div class=\"card-bloque-inferior\"><p class=\"card-descripcion\">AleaSoft Energy Forecasting, 30 de marzo de 2026. Entrevista de Ram\u00f3n Roca, director de El Peri\u00f3dico\u2026<\/p><a href=\"https:\/\/aleasoft.com\/es\/entrevista-periodico-energia-antonio-delgado-rigal-20260330\/\" class=\"card-ver-mas\">Ver m\u00e1s &gt;&gt;<\/a><\/div><\/div><\/article><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e16b493\" data-id=\"e16b493\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-083694b elementor-widget elementor-widget-shortcode\" data-id=\"083694b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><article class=\"noticia-card-fija \"><div class=\"noticia-card-imagen-wrapper\"><a href=\"https:\/\/aleasoft.com\/es\/repunte-precios-gas-menos-eolica-tensionan-mercados-europeos\/\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"509\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260713-AleaSoft-Precios-mercados-europeos-electricidad.png\" class=\"noticia-card-imagen wp-post-image\" alt=\"El repunte en los precios del gas y una menor e\u00f3lica tensionan los precios de los mercados el\u00e9ctricos europeos en la segunda semana de julio\" loading=\"lazy\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260713-AleaSoft-Precios-mercados-europeos-electricidad.png 730w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260713-AleaSoft-Precios-mercados-europeos-electricidad-300x209.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260713-AleaSoft-Precios-mercados-europeos-electricidad-150x105.png 150w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div class=\"card-contenido\"><h3 class=\"elementor-heading-title elementor-size-default card-titulo\"><a href=\"https:\/\/aleasoft.com\/es\/repunte-precios-gas-menos-eolica-tensionan-mercados-europeos\/\">El repunte en los precios del gas y una menor e\u00f3lica tensionan los precios de los mercados el\u00e9ctricos europeos en la segunda semana de julio<\/a><\/h3><div class=\"card-bloque-inferior\"><p class=\"card-descripcion\">AleaSoft Energy Forecasting, 13 de julio de 2026. En la segunda semana de julio, los precios\u2026<\/p><a href=\"https:\/\/aleasoft.com\/es\/repunte-precios-gas-menos-eolica-tensionan-mercados-europeos\/\" class=\"card-ver-mas\">Ver m\u00e1s &gt;&gt;<\/a><\/div><\/div><\/article><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f921e82\" data-id=\"f921e82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29be01b elementor-widget elementor-widget-shortcode\" data-id=\"29be01b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><article class=\"noticia-card-fija \"><div class=\"noticia-card-imagen-wrapper\"><a href=\"https:\/\/aleasoft.com\/es\/financiacion-baterias-ppa-hibridos\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1672\" height=\"941\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos.png\" class=\"noticia-card-imagen wp-post-image\" alt=\"La financiaci\u00f3n de bater\u00edas impulsa una nueva etapa en los PPA: hibridaci\u00f3n, refinanciaci\u00f3n y nuevos contratos\" loading=\"lazy\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos.png 1672w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos-300x169.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos-1024x576.png 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos-150x84.png 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos-768x432.png 768w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/07\/20260710-AleaSoft-financiacion-baterias-ppa-hibridos-1536x864.png 1536w\" sizes=\"auto, (max-width: 1672px) 100vw, 1672px\" \/><\/a><\/div><div class=\"card-contenido\"><h3 class=\"elementor-heading-title elementor-size-default card-titulo\"><a href=\"https:\/\/aleasoft.com\/es\/financiacion-baterias-ppa-hibridos\/\">La financiaci\u00f3n de bater\u00edas impulsa una nueva etapa en los PPA: hibridaci\u00f3n, refinanciaci\u00f3n y nuevos contratos<\/a><\/h3><div class=\"card-bloque-inferior\"><p class=\"card-descripcion\">AleaSoft Energy Forecasting, 10 de julio de 2026. El avance del almacenamiento con bater\u00edas est\u00e1 transformando\u2026<\/p><a href=\"https:\/\/aleasoft.com\/es\/financiacion-baterias-ppa-hibridos\/\" class=\"card-ver-mas\">Ver m\u00e1s &gt;&gt;<\/a><\/div><\/div><\/article><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d669e98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d669e98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cc8c63\" data-id=\"4cc8c63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36b55b5 elementor-widget elementor-widget-spacer\" data-id=\"36b55b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informes de mercados, regulatorios y periciales Informes de mercados, regulatorios y periciales An\u00e1lisis experto para guiar tus decisiones estrat\u00e9gicas Realizamos informes t\u00e9cnicos para casos de consultor\u00edas relacionadas con temas de mediaci\u00f3n y arbitraje en el mercado el\u00e9ctrico o de gas: Informes periciales para mediaciones, arbitrajes y demandas asociadas a los mercados de electricidad y gas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":143011,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-97263","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informes periciales energ\u00eda: arbitraje y mediaci\u00f3n | AleaSoft<\/title>\n<meta name=\"description\" content=\"AleaSoft ofrece informes periciales energ\u00eda expertos para demandas, arbitrajes y mediaciones en el mercado el\u00e9ctrico y gas. Obt\u00e9n an\u00e1lisis t\u00e9cnicos rigurosos\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informes periciales energ\u00eda: arbitraje y mediaci\u00f3n | AleaSoft\" \/>\n<meta property=\"og:description\" content=\"\u00bfNecesitas informes periciales energ\u00eda para tus casos de arbitraje, mediaci\u00f3n o demandas? En AleaSoft, te proporcionamos an\u00e1lisis t\u00e9cnicos rigurosos y expertos para el mercado el\u00e9ctrico y gas. Asegura tus decisiones con datos fiables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T21:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Informes periciales para demandas, arbitraje y mediaci\u00f3n\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/services\\\/expert-reports-lawsuits-arbitration-mediation\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/\",\"name\":\"Informes periciales energ\u00eda: arbitraje y mediaci\u00f3n | AleaSoft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/personas-que-ayudan-8428076-scaled.jpg\",\"datePublished\":\"2020-07-20T15:47:42+00:00\",\"dateModified\":\"2026-06-10T21:51:59+00:00\",\"description\":\"AleaSoft ofrece informes periciales energ\u00eda expertos para demandas, arbitrajes y mediaciones en el mercado el\u00e9ctrico y gas. Obt\u00e9n an\u00e1lisis t\u00e9cnicos rigurosos\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/personas-que-ayudan-8428076-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/personas-que-ayudan-8428076-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/informes-periciales-arbitraje-mercados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios de previsiones de energ\u00eda\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/servicios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informes periciales para demandas, arbitraje y mediaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informes periciales energ\u00eda: arbitraje y mediaci\u00f3n | AleaSoft","description":"AleaSoft ofrece informes periciales energ\u00eda expertos para demandas, arbitrajes y mediaciones en el mercado el\u00e9ctrico y gas. Obt\u00e9n an\u00e1lisis t\u00e9cnicos rigurosos\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/","og_locale":"es_ES","og_type":"article","og_title":"Informes periciales energ\u00eda: arbitraje y mediaci\u00f3n | AleaSoft","og_description":"\u00bfNecesitas informes periciales energ\u00eda para tus casos de arbitraje, mediaci\u00f3n o demandas? En AleaSoft, te proporcionamos an\u00e1lisis t\u00e9cnicos rigurosos y expertos para el mercado el\u00e9ctrico y gas. Asegura tus decisiones con datos fiables.","og_url":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_modified_time":"2026-06-10T21:51:59+00:00","og_image":[{"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Informes periciales para demandas, arbitraje y mediaci\u00f3n","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/services\/expert-reports-lawsuits-arbitration-mediation\/","url":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/","name":"Informes periciales energ\u00eda: arbitraje y mediaci\u00f3n | AleaSoft","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg","datePublished":"2020-07-20T15:47:42+00:00","dateModified":"2026-06-10T21:51:59+00:00","description":"AleaSoft ofrece informes periciales energ\u00eda expertos para demandas, arbitrajes y mediaciones en el mercado el\u00e9ctrico y gas. Obt\u00e9n an\u00e1lisis t\u00e9cnicos rigurosos\u2026","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/03\/personas-que-ayudan-8428076-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/servicios\/informes-periciales-arbitraje-mercados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"Servicios de previsiones de energ\u00eda","item":"https:\/\/aleasoft.com\/es\/servicios\/"},{"@type":"ListItem","position":3,"name":"Informes periciales para demandas, arbitraje y mediaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/pages\/97263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=97263"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/pages\/97263\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/pages\/143011"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=97263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}