{"id":106399,"date":"2020-11-24T13:30:18","date_gmt":"2020-11-24T12:30:18","guid":{"rendered":"https:\/\/aleasoft.com\/?p=106399"},"modified":"2020-11-24T13:30:31","modified_gmt":"2020-11-24T12:30:31","slug":"subastas-renovables-impacto-financiacion-renovables","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/","title":{"rendered":"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables"},"content":{"rendered":"\n<p><strong>AleaSoft, 24 de noviembre de 2020. La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable. Desde los riesgos t\u00e9cnicos propios de cada tecnolog\u00eda hasta el riesgo de precios de mercado. La existencia de subastas de renovables puede tener un impacto en el precio del mercado el\u00e9ctrico que hay que analizar para tenerlo en cuenta en la visi\u00f3n del futuro del mercado el\u00e9ctrico en el que se base el modelo financiero del proyecto.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"246\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica-1024x246.jpg\" alt=\"\" class=\"wp-image-106400\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica-1024x246.jpg 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica-300x72.jpg 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica-150x36.jpg 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica-768x184.jpg 768w, https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg 1120w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Al igual que la mayor\u00eda de proyectos empresariales, la construcci\u00f3n y explotaci\u00f3n de un parque de generaci\u00f3n de electricidad a partir de una <strong>fuente de energ\u00eda renovable<\/strong> va a necesitar financiaci\u00f3n. La capacidad de un proyecto para obtener esta financiaci\u00f3n depender\u00e1 de muchos aspectos, entre los que se encuentran la viabilidad del proyecto y los retornos esperados.<\/p>\n\n\n\n<p>Estos aspectos pueden verse influenciados por muchos factores: el hecho de que el proyecto est\u00e9 acogido a un determinado r\u00e9gimen retributivo de una <strong>subasta de renovables<\/strong> o simplemente la presencia de subastas en el mercado, el <strong>riesgo de precios de mercado<\/strong> y los inherentes riesgos t\u00e9cnicos. De ah\u00ed la importancia de las auditorias de debida diligencia, m\u00e1s conocidas como <strong>due dillignece<\/strong>, en la financiaci\u00f3n de los proyectos renovables.<\/p>\n\n\n\n<p><h2>Webinar sobre las perspectivas de los mercados de energ\u00eda y la financiaci\u00f3n de renovables<\/h2><\/p>\n\n\n\n<p>El pr\u00f3ximo jueves 26 de noviembre tendr\u00e1 lugar el webinar \u201c<a href=\"https:\/\/aleasoft.com\/es\/webinars-sobre-mercados-sector-energia\/perspectivas-mercados-energia-europa-2021-1\/\">Perspectivas de los mercados de energ\u00eda en Europa a partir de 2021<\/a>\u201d, organizado por <strong>AleaSoft<\/strong>, donde se analizar\u00e1n todos los aspectos que pueden tener impacto en la financiaci\u00f3n de los proyectos de energ\u00edas renovables.<\/p>\n\n\n\n<p>En el webinar se repasar\u00e1n los resultados de las subastas que se realizaron en 2016 y 2017 en Espa\u00f1a y c\u00f3mo se han desarrollado los proyectos ganadores. Tambi\u00e9n se analizar\u00e1 el <a href=\"https:\/\/aleasoft.com\/es\/calendario-subastas-renovables-asegurar-objetivos-pniec-2025\/\">nuevo sistema de subastas renovables planteado recientemente por el Gobierno espa\u00f1ol<\/a>, que ya tiene un calendario orientativo que prev\u00e9 subastar 1500 MW de <strong>e\u00f3lica<\/strong> y 1800 MW de <strong>fotovoltaica<\/strong> cada a\u00f1o hasta 2025, cubriendo gran parte de los objetivos de capacidad renovable del <strong>PNIEC<\/strong>.<\/p>\n\n\n\n<p>Durante el webinar, se analizar\u00e1 cu\u00e1l ser\u00e1 la posible influencia de estas nuevas subastas en el panorama presente y futuro de la energ\u00edas renovables en Espa\u00f1a, con especial atenci\u00f3n en el <a href=\"https:\/\/aleasoft.com\/es\/subastas-renovables-con-pinzas\/\">impacto que pueden tener en los precios del mercado el\u00e9ctrico y en la consecuci\u00f3n de los objetivos del PNIEC<\/a>.<\/p>\n\n\n\n<p>Aparte de la posible influencia de las subastas, tambi\u00e9n se debatir\u00e1n los riegos t\u00e9cnicos de los proyectos renovables y c\u00f3mo pueden impactar en la viabilidad de un proyecto, adem\u00e1s de c\u00f3mo mitigarlos o asegurarlos, entre otras de las funciones de un asesor de <strong>Project Finance<\/strong>.<\/p>\n\n\n\n<p>Como es habitual en los webinars de <strong>AleaSoft<\/strong>, tambi\u00e9n se analizar\u00e1 la evoluci\u00f3n en los \u00faltimos meses de los <strong>mercados de energ\u00eda<\/strong> en Europa y sus perspectivas de recuperaci\u00f3n a partir del pr\u00f3ximo a\u00f1o 2021.<\/p>\n\n\n\n<p>En esta ocasi\u00f3n se contar\u00e1 con la participaci\u00f3n de tres ponentes de <strong>Vector Renewables<\/strong>: Javier Asensio Mar\u00edn, CEO de Vector Renewables, Hugo Alvarez L\u00f3pez, Global Head of Technical Advisory, y Carlos Almod\u00f3var Almaraz, Principal M&amp;A and Financial Advisory, adem\u00e1s de Oriol Salt\u00f3 i Bauz\u00e0, Manager de Data Analysis and Modelling en <strong>AleaSoft<\/strong>. En la mesa de an\u00e1lisis posterior a las ponencias se contar\u00e1 tambi\u00e9n con Antonio Delgado Rigal, CEO de AleaSoft.<\/p>\n\n\n\n<p><h2>Pr\u00f3ximo webinar de AleaSoft, en 2021<\/h2><\/p>\n\n\n\n<p>La segunda parte de este webinar est\u00e1 programada para el d\u00eda 14 de enero. Ser\u00e1 el primer webinar organizado por <strong>AleaSoft<\/strong> en 2021 y contar\u00e1 con la participaci\u00f3n de ponentes de la consultora <strong>PwC<\/strong>, para analizar los contratos <strong>PPA<\/strong> para <strong>grandes consumidores<\/strong>, adem\u00e1s de la evoluci\u00f3n de los mercados de energ\u00eda y la financiaci\u00f3n de los proyectos renovables.<\/p>\n\n\n\n<p>Fuente: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 24 de noviembre de 2020. La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable. Desde los riesgos t\u00e9cnicos propios de cada tecnolog\u00eda hasta el riesgo de precios de mercado. La existencia de subastas de renovables puede tener un impacto en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":106400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[],"class_list":["post-106399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables\" \/>\n<meta property=\"og:description\" content=\"La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-24T12:30:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-24T12:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables\",\"datePublished\":\"2020-11-24T12:30:18+00:00\",\"dateModified\":\"2020-11-24T12:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/\"},\"wordCount\":681,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/\",\"name\":\"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg\",\"datePublished\":\"2020-11-24T12:30:18+00:00\",\"dateModified\":\"2020-11-24T12:30:31+00:00\",\"description\":\"La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg\",\"width\":1120,\"height\":269},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subastas-renovables-impacto-financiacion-renovables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables - AleaSoft Energy Forecasting","description":"La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/","og_locale":"es_ES","og_type":"article","og_title":"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables","og_description":"La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable.","og_url":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2020-11-24T12:30:18+00:00","article_modified_time":"2020-11-24T12:30:31+00:00","og_image":[{"width":1120,"height":269,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg","type":"image\/jpeg"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables","datePublished":"2020-11-24T12:30:18+00:00","dateModified":"2020-11-24T12:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/"},"wordCount":681,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/","url":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/","name":"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg","datePublished":"2020-11-24T12:30:18+00:00","dateModified":"2020-11-24T12:30:31+00:00","description":"La financiaci\u00f3n de los proyectos renovables tiene muchas facetas que hay que tener en cuenta a la hora de dise\u00f1ar un proyecto viable.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/11\/20201124-AleaSoft-Planta-solar-fotovoltaica.jpg","width":1120,"height":269},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/subastas-renovables-impacto-financiacion-renovables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las subastas de renovables y su impacto en la financiaci\u00f3n de las renovables"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/106399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=106399"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/106399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media\/106400"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=106399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/categories?post=106399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/tags?post=106399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}