{"id":114319,"date":"2021-06-08T12:45:41","date_gmt":"2021-06-08T10:45:41","guid":{"rendered":"https:\/\/aleasoft.com\/?p=114319"},"modified":"2021-06-08T15:25:22","modified_gmt":"2021-06-08T13:25:22","slug":"entrevista-pv-magazine-antonio-delgado-rigal-junio-2021","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/","title":{"rendered":"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft"},"content":{"rendered":"\n<p><strong>AleaSoft, 8 de junio de 2021. Entrevista de Pilar S\u00e1nchez Molina, de pv&nbsp;magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Roundtables de pv&nbsp;magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET. En la entrevista se adelantan algunos de los temas que se profundizar\u00e1n durante la sesi\u00f3n de networking relacionados con el presente y futuro de los mercados de renovables y el\u00e9ctricos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-1024x768.png\" alt=\"\" class=\"wp-image-114321\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-1024x768.png 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-300x225.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-150x113.png 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-768x576.png 768w, https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-1536x1152.png 1536w, https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal-2048x1536.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Repetimos pregunta que formulamos ayer a Asier Ukar: Cada vez m\u00e1s actores entran en el mercado renovable, y vemos a grandes fondos, fabricantes de electrodom\u00e9sticos y grandes superficies como IPP, fabricantes o vendedores de m\u00f3dulos. \u00bfHay sitio para todos?<\/strong><\/p>\n\n\n\n<p>Sin lugar a dudas. Los objetivos que se ha planteado la Uni\u00f3n Europea son ambiciosos. Hay que tener en cuenta que no se trata solo de descarbonizar el sector el\u00e9ctrico. Hay otros sectores como el transporte y la industria que son grandes emisores y necesitan ser descarbonizados, por lo que hay mucho por hacer y mucha energ\u00eda renovable para generar y sustituir a los combustibles f\u00f3siles.<\/p>\n\n\n\n<p><strong>\u00bfEs bueno para el mercado que haya tantos actores?<\/strong><\/p>\n\n\n\n<p>La competencia es buena para cualquier mercado, por lo que el desarrollo de las <strong>energ\u00edas renovables<\/strong> se ver\u00e1 beneficiado con todos estos actores. Adem\u00e1s, las inversiones a realizar son muy importantes y va a ser necesario diversificar las fuentes de inversi\u00f3n.<\/p>\n\n\n\n<p><strong>Estamos viendo una subida descomunal en el transporte de los env\u00edos desde Asia, de los componentes\u2026 \u00bfC\u00f3mo afectan estas subidas de precio a las previsiones?<\/strong><\/p>\n\n\n\n<p>De momento los <strong>precios de los mercados el\u00e9ctricos<\/strong> a medio y largo plazo no se han visto afectados por esta circunstancia.<\/p>\n\n\n\n<p>La mayor afectaci\u00f3n en las previsiones futuras est\u00e1 viniendo actualmente del alto <strong>precio de las emisiones de CO<sub>2<\/sub><\/strong> y del <strong>gas<\/strong>.<\/p>\n\n\n\n<p><strong>\u00bfEs tan importante contar con previsiones? Parece que el mercado est\u00e1 maduro y se \u201cpuede apa\u00f1ar\u201d por s\u00ed solo.<\/strong><\/p>\n\n\n\n<p>Es fundamental. Es necesario contar con una <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-precios-de-energia\/?tab=largo-plazo\">visi\u00f3n de futuro de los precios de los mercados<\/a>, con <strong>bandas de confianza<\/strong> basadas en una <strong>m\u00e9trica probabil\u00edstica<\/strong>, para valorar el riesgo de invertir en un proyecto renovable, ya sea a trav\u00e9s de <strong>PPA<\/strong>, en <strong>subastas<\/strong> o en proyectos 100% merchant. Adem\u00e1s son un input imprescindible en los modelos financieros a la hora de buscar <strong>financiaci\u00f3n<\/strong> para los proyectos.<\/p>\n\n\n\n<p>Las previsiones con <strong>detalle horario<\/strong> permiten estimar los ingresos de la planta y tambi\u00e9n son una referencia a la hora de determinar la estructura de precios en la negociaci\u00f3n de un PPA. Tambi\u00e9n son utilizadas en las <strong>auditor\u00edas<\/strong> y <strong>due diligences<\/strong> como respaldo de las decisiones tomadas. Y una vez que la planta est\u00e1 en funcionamiento, son necesarias para definir las estrategias de venta de energ\u00eda en los mercados spot y de futuros.<\/p>\n\n\n\n<p>Hay que&nbsp; recordar que las previsiones adem\u00e1s de ser importantes para tomar decisiones de futuro son necesarias tambi\u00e9n para tener una traza de las decisiones que han sido tomadas en el pasado, y por eso en las auditor\u00edas son fundamentales.<\/p>\n\n\n\n<p><strong>En un a\u00f1o, hemos pasado de ver precios muy bajos a precios disparados en los mercados el\u00e9ctricos europeos. \u00bfAfectan estas oscilaciones tambi\u00e9n a los precios de los PPA?<\/strong><\/p>\n\n\n\n<p>Los precios de los PPA est\u00e1n influenciados por el comportamiento de los mercados spot y, sobre todo, por los mercados de futuros tanto de electricidad como de combustibles y CO<sub>2<\/sub>. Las variaciones que se registran en \u00e9stos impactan sobre los precios de los PPA. Pero los PPA son contratos a largo plazo, por lo que su evoluci\u00f3n est\u00e1 m\u00e1s ligada a los precios esperados en el futuro a medio y largo plazo. Estas estimaciones de precios a largo plazo, si est\u00e1n hechas correctamente, son mucho m\u00e1s estables que las fluctuaciones coyunturales de los precios a corto plazo porque el mercado el\u00e9ctrico est\u00e1 en equilibrio. Aunque estas situaciones de precios altos y bajos seguir\u00e1n ocurriendo, el <strong>equilibrio del mercado<\/strong> se mantendr\u00e1. Si los precios del mercado suben por mucho tiempo, la demanda disminuye por lo que a la larga los precios volver\u00e1n a bajar. Y si por el contrario los precios bajan, para los productores no es rentable producir y se desincentivan las inversiones, por lo que a la larga disminuir\u00e1 la oferta y los precios tender\u00e1n a subir.<\/p>\n\n\n\n<p><strong>\u00bfVa a afectar el cierre de centrales nucleares y t\u00e9rmicas de carb\u00f3n al&nbsp;pool en Espa\u00f1a?<\/strong><\/p>\n\n\n\n<p>En Espa\u00f1a la <strong>producci\u00f3n con carb\u00f3n<\/strong> ha disminuido de forma considerable desde principios del 2019, siendo actualmente muy reducida y no ha habido grandes afectaciones porque hay suficiente capacidad de generaci\u00f3n con otras tecnolog\u00edas.<\/p>\n\n\n\n<p>Si el <strong>cierre de las nucleares<\/strong> se hace de forma ordenada y se cumplen las expectativas de crecimiento de las energ\u00edas renovables no deber\u00eda haber grandes afectaciones tampoco en este caso.<\/p>\n\n\n\n<p>De todos modos, al ser el gas la tecnolog\u00eda de respaldo de la producci\u00f3n renovable, habr\u00e1 horas de precios altos porque los precios de los derechos de emisi\u00f3n de CO<sub>2<\/sub> pueden continuar subiendo y tambi\u00e9n se depender\u00e1 del precio de esta materia prima. Tambi\u00e9n hay que tener en cuenta que la producci\u00f3n con gas s\u00ed que genera emisiones, algo que no sucede con la nuclear, por lo que el cierre del parque nuclear retrasar\u00e1 la reducci\u00f3n de las emisiones de CO<sub>2<\/sub>.<\/p>\n\n\n\n<p><strong>Y las subastas, \u00bfafectar\u00e1n a la financiaci\u00f3n de PPA?<\/strong><\/p>\n\n\n\n<p>La financiaci\u00f3n de los PPA, en general, no se ver\u00e1 afectada por las subastas. S\u00ed que es cierto que los proyectos que hayan resultado ganadores en las subastas podr\u00e1n conseguir mejores condiciones de financiaci\u00f3n, porque de alguna forma son un PPA con el Estado, que tiene una alta calidad crediticia. Pero los PPA seguir\u00e1n siendo necesarios para los proyectos que no han ido a subasta y tambi\u00e9n para los <strong>grandes consumidores<\/strong>, tambi\u00e9n con el aval del Estado seg\u00fan garantiza el <strong>Estatuto de los consumidores electrointensivos<\/strong>, que pueden ver en ellos una herramienta para mitigar el <strong>riesgo de precios de mercado<\/strong> y para cumplir con sus objetivos medioambientales.<\/p>\n\n\n\n<p>Fuente: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n\n\n<p>&nbsp;<br>\n<a href='https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-precios-de-energia\/?tab=largo-plazo\/' class='alea-banner-link' data-alea-gtm-event-category='banner-horizontal' data-alea-gtm-event-label='lp'><img class='alignright' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/03\/servicio-previsiones-largo-plazo.jpg' alt='Previsiones de largo plazo' style='width: 100%; object-position: center;'\/><\/a><script type=\"text\/javascript\">\nwindow.addEventListener('load', function(event){\n        document.getElementById('alea-banner-elementor-template').remove();\n    }\n)\n<\/script><\/p>","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 8 de junio de 2021. Entrevista de Pilar S\u00e1nchez Molina, de pv&nbsp;magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Roundtables de pv&nbsp;magazine a celebrarse el 9 de junio entre las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":114321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[574],"class_list":["post-114319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Entrevista de Pilar S\u00e1nchez Molina, de pv magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Rountables de pv magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft\" \/>\n<meta property=\"og:description\" content=\"Entrevista de Pilar S\u00e1nchez Molina, de pv magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Rountables de pv magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-08T10:45:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-08T13:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2224\" \/>\n\t<meta property=\"og:image:height\" content=\"1668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft\",\"datePublished\":\"2021-06-08T10:45:41+00:00\",\"dateModified\":\"2021-06-08T13:25:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/\"},\"wordCount\":1087,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/20210608-Antonio-Delgado-Rigal.png\",\"keywords\":[\"noticias\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/\",\"name\":\"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/20210608-Antonio-Delgado-Rigal.png\",\"datePublished\":\"2021-06-08T10:45:41+00:00\",\"dateModified\":\"2021-06-08T13:25:22+00:00\",\"description\":\"Entrevista de Pilar S\u00e1nchez Molina, de pv magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Rountables de pv magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/20210608-Antonio-Delgado-Rigal.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/20210608-Antonio-Delgado-Rigal.png\",\"width\":2224,\"height\":1668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft - AleaSoft Energy Forecasting","description":"Entrevista de Pilar S\u00e1nchez Molina, de pv magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Rountables de pv magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft","og_description":"Entrevista de Pilar S\u00e1nchez Molina, de pv magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Rountables de pv magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET.","og_url":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2021-06-08T10:45:41+00:00","article_modified_time":"2021-06-08T13:25:22+00:00","og_image":[{"width":2224,"height":1668,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft","datePublished":"2021-06-08T10:45:41+00:00","dateModified":"2021-06-08T13:25:22+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/"},"wordCount":1087,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal.png","keywords":["noticias"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/","url":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/","name":"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal.png","datePublished":"2021-06-08T10:45:41+00:00","dateModified":"2021-06-08T13:25:22+00:00","description":"Entrevista de Pilar S\u00e1nchez Molina, de pv magazine, a Antonio Delgado Rigal, Doctor en Inteligencia Artificial, Fundador y CEO de AleaSoft, el cual participar\u00e1 en la sesi\u00f3n de networking en espa\u00f1ol que tendr\u00e1 lugar en el marco de las Rountables de pv magazine a celebrarse el 9 de junio entre las 12:00 y las 13:00 CET.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/20210608-Antonio-Delgado-Rigal.png","width":2224,"height":1668},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/entrevista-pv-magazine-antonio-delgado-rigal-junio-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"Entrevista de pv magazine a Antonio Delgado Rigal, CEO de AleaSoft"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/114319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=114319"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/114319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media\/114321"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=114319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/categories?post=114319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/tags?post=114319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}