{"id":125992,"date":"2022-03-14T15:13:14","date_gmt":"2022-03-14T14:13:14","guid":{"rendered":"https:\/\/aleasoft.com\/?p=125992"},"modified":"2022-03-14T15:13:17","modified_gmt":"2022-03-14T14:13:17","slug":"gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/","title":{"rendered":"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 14 de marzo de 2022. En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas. Sin embargo, hacia el final de la semana en algunos mercados se registraron valores horarios negativos gracias al incremento generalizado de la producci\u00f3n e\u00f3lica. En el conjunto de la semana, los precios de la mayor\u00eda de los mercados fueron superiores a los de la semana anterior. El Brent registr\u00f3 valores que no se ve\u00edan desde 2008 y el CO<sub>2<\/sub> el m\u00ednimo del a\u00f1o.<\/strong><\/p>\n<h2>Producci\u00f3n solar fotovoltaica y termosolar y producci\u00f3n e\u00f3lica<\/h2>\n<p>La segunda semana de marzo termin\u00f3 con un aumento en la <strong>producci\u00f3n solar<\/strong> del 32% en el mercado alem\u00e1n y de un 11% en el mercado italiano, en comparaci\u00f3n con la producci\u00f3n de la semana precedente. Por el contrario, se registr\u00f3 una reducci\u00f3n de la producci\u00f3n de entre el 6,5% y el 20% en el resto de los mercados analizados en <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n<p>Para la semana que comenz\u00f3 el 14 de marzo, <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-energia-solar\/\">las previsiones de <strong>AleaSoft Energy Forecasting<\/strong><\/a> apuntan a una reducci\u00f3n en la producci\u00f3n solar en los mercados de Alemania, Italia y Espa\u00f1a.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Produccion solar fotovoltaica termosolar electricidad Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Produccion-solar-fotovoltaica-termosolar-electricidad-Europa.png' alt='AleaSoft - Produccion solar fotovoltaica termosolar electricidad Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE y TERNA.<\/span><\/div><br \/>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Perfil produccion solar fotovoltaica Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Perfil-produccion-solar-fotovoltaica-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Perfil-produccion-solar-fotovoltaica-Europa.png' alt='AleaSoft - Perfil produccion solar fotovoltaica Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE y TERNA.<\/span><\/div><\/p>\n<p>En la semana del 7 de marzo, la <strong>producci\u00f3n e\u00f3lica<\/strong> aument\u00f3 en todos los mercados analizados en <strong>AleaSoft Energy Forecasting<\/strong> en comparaci\u00f3n con la semana anterior. Los mayores incrementos se alcanzaron en los mercados de Alemania y Francia, en los que la producci\u00f3n con esta tecnolog\u00eda fue superior al doble de la registrada durante la semana del 28 de febrero. En el resto de los mercados el incremento estuvo entre el 6,6% y el 30%.<\/p>\n<p>En la tercera semana de marzo, seg\u00fan <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-energia-eolica\/\">las previsiones de producci\u00f3n e\u00f3lica de <strong>AleaSoft Energy Forecasting<\/strong><\/a>, se incrementar\u00e1 la producci\u00f3n con esta tecnolog\u00eda en los mercados de Espa\u00f1a y Portugal. Sin embargo, en los mercados de Alemania, Francia e Italia se espera una reducci\u00f3n de la producci\u00f3n e\u00f3lica.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Produccion eolica electricidad Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Produccion-eolica-electricidad-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Produccion-eolica-electricidad-Europa.png' alt='AleaSoft - Produccion eolica electricidad Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE y TERNA.<\/span><\/div>\n<h2>Demanda el\u00e9ctrica<\/h2>\n<p>La <strong>demanda el\u00e9ctrica<\/strong> disminuy\u00f3 en la mayor\u00eda de los mercados el\u00e9ctricos europeos analizados en <strong>AleaSoft Energy Forecasting<\/strong> durante la segunda semana de marzo con respecto a la semana anterior. La mayor ca\u00edda se registr\u00f3 en el mercado de Gran Breta\u00f1a, la cual fue del 8,6%, seguida por los descensos del 6,4% de los Pa\u00edses Bajos y del 5,7% del mercado belga. En los mercados de Francia, Italia y Alemania, las bajadas fueron del 1,2%, 1,1% y 1,0% respectivamente. La menor variaci\u00f3n de la demanda se registr\u00f3 en el mercado espa\u00f1ol, con una bajada del 0,8%. Los descensos de la demanda en la mayor\u00eda de los mercados estuvieron favorecidos por unas temperaturas menos fr\u00edas. El \u00fanico mercado en el que la demanda aument\u00f3, un 4,7%, fue en el portugu\u00e9s, donde se celebr\u00f3 el Martes de Carnaval durante la semana anterior.<\/p>\n<p>Para la semana del 14 de marzo, <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-la-demanda-de-energia\/?tab=corto-plazo\">las previsiones de demanda de <strong>AleaSoft Energy Forecasting<\/strong><\/a> indican un incremento en los mercados de Pa\u00edses Bajos, B\u00e9lgica, Portugal y Gran Breta\u00f1a. Por otra parte, en el resto de los mercados analizados se prev\u00e9 que la demanda descienda.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Demanda electricidad paises Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Demanda-electricidad-paises-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Demanda-electricidad-paises-Europa.png' alt='AleaSoft - Demanda electricidad paises Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE, TERNA, National Grid y ELIA.<\/span><\/div>\n<h2>Mercados el\u00e9ctricos europeos<\/h2>\n<p>En la semana del 7 de marzo, los precios de casi todos los mercados el\u00e9ctricos europeos analizados en <strong>AleaSoft Energy Forecasting<\/strong> aumentaron respecto a la semana anterior. Las excepciones fueron el<strong> mercado Nord\u00a0Pool<\/strong> de los pa\u00edses n\u00f3rdicos y el <strong>mercado EPEX\u00a0SPOT<\/strong> de Alemania, con descensos del 1,8% y 7,9% respectivamente. Por otra parte, la mayor subida de precios fue la del<strong> mercado IPEX <\/strong>de Italia, del 25%, mientras que, el menor incremento fue el del mercado EPEX\u00a0SPOT de B\u00e9lgica, del 1,9%. En el resto de los mercados, los aumentos de precios estuvieron entre el 4,2% del <strong>mercado N2EX<\/strong> del Reino Unido y el 18% del <strong>mercado MIBEL<\/strong> de Espa\u00f1a y Portugal.<\/p>\n<p>En la segunda semana de marzo, los precios promedio superaron los 275\u00a0\u20ac\/MWh en casi todos los mercados el\u00e9ctricos analizados. La excepci\u00f3n fue el mercado Nord\u00a0Pool, que registr\u00f3 un promedio semanal de 148,25\u00a0\u20ac\/MWh. Por otra parte, el promedio m\u00e1s elevado fue el del mercado italiano, que alcanz\u00f3 un valor de 407,44\u00a0\u20ac\/MWh. En el resto de los mercados, los precios se situaron entre los 277,55\u00a0\u20ac\/MWh del mercado alem\u00e1n y los 372,68\u00a0\u20ac\/MWh del mercado espa\u00f1ol.<\/p>\n<p>Durante la semana del 7 de marzo, la evoluci\u00f3n de los precios de los mercados el\u00e9ctricos estuvo muy influenciada por el comportamiento de los precios del gas, los cuales alcanzaron un m\u00e1ximo el martes 8 de marzo para luego empezar a descender. Del mismo modo, los precios diarios m\u00e1s elevados de los mercados el\u00e9ctricos europeos se alcanzaron ese d\u00eda. En la mayor\u00eda de los mercados, los precios del 8 de marzo fueron los m\u00e1s altos como m\u00ednimo de los \u00faltimos diez a\u00f1os, excepto en los mercados brit\u00e1nico y n\u00f3rdico, donde se registraron precios m\u00e1s altos en diciembre de 2021. En el caso de Francia, Espa\u00f1a, Portugal e Italia, los precios superaron los 540\u00a0\u20ac\/MWh. En este \u00faltimo mercado, se alcanz\u00f3 el precio diario m\u00e1ximo, de 587,67\u00a0\u20ac\/MWh.<\/p>\n<p>Por otra parte, los descensos en los precios del gas junto con una elevada producci\u00f3n e\u00f3lica en la mayor\u00eda de los mercados favorecieron los descensos de precios en los \u00faltimos d\u00edas de la semana. El precio diario m\u00e1s bajo de la semana, de 80,44\u00a0\u20ac\/MWh, se registr\u00f3 el viernes 11 de marzo en Alemania.<\/p>\n<p>Por lo que respecta a los precios horarios, el martes 8 de marzo, de 19:00 a 20:00, se alcanz\u00f3 un precio horario de 700,00\u00a0\u20ac\/MWh en los mercados de Alemania, B\u00e9lgica, Espa\u00f1a, Francia y los Pa\u00edses Bajos. Este precio fue el m\u00e1s alto de la historia en el mercado espa\u00f1ol y al menos desde abril de 2011 en los Pa\u00edses Bajos. En los mercados alem\u00e1n, belga y franc\u00e9s fue el precio m\u00e1s alto desde marzo de 2008, marzo de 2011 y noviembre de 2016, respectivamente.<\/p>\n<p>Pero en la segunda semana de marzo tambi\u00e9n hubo precios bajos en los mercados el\u00e9ctricos europeos. El mercado belga registr\u00f3 precios horarios negativos los d\u00edas 11 y 13 de marzo, alcanzando un valor m\u00ednimo de \u201140,00\u00a0\u20ac\/MWh durante una hora del d\u00eda 11 y tres horas del d\u00eda 13 de marzo. Este precio horario es el m\u00e1s bajo registrado en este mercado en lo que va de a\u00f1o. El viernes 11 de marzo tambi\u00e9n se registraron precios horarios inferiores a 0,10\u00a0\u20ac\/MWh en los mercados alem\u00e1n y neerland\u00e9s.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Eolica paneles solares' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/11\/20211126-AleaSoft-Eolica-paneles-solares.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/11\/20211126-AleaSoft-Eolica-paneles-solares.png' alt='AleaSoft - Eolica paneles solares' width='740'\/><\/a><\/div>\n<p><a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-precios-de-energia\/\">Las previsiones de precios de <strong>AleaSoft Energy Forecasting<\/strong><\/a> indican que, en la semana del 14 de marzo los precios de los mercados el\u00e9ctricos europeos podr\u00edan descender, favorecidos por el descenso de la demanda en algunos mercados y por el aumento de la producci\u00f3n e\u00f3lica en el caso del mercado ib\u00e9rico, aunque depender\u00e1 de c\u00f3mo evolucionen los precios del gas.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Precios mercados europeos electricidad' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png' alt='AleaSoft - Precios mercados europeos electricidad' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de OMIE, , Nord Pool y GME.<\/span><\/div>\n<h2>Futuros de electricidad<\/h2>\n<p>En la segunda semana del mes de marzo, al cierre de la sesi\u00f3n del d\u00eda 11, los precios de los futuros de electricidad para el pr\u00f3ximo trimestre registraron bajadas en todos los mercados europeos analizados en <strong>AleaSoft Energy Forecasting<\/strong>, al compararlos con los precios de cierre del viernes anterior, el d\u00eda 4 de marzo. Se observaron decrementos de entre el 15% del <strong>mercado NASDAQ<\/strong> de los pa\u00edses n\u00f3rdicos hasta el 34% alcanzado en el <strong>mercado EEX<\/strong> de Espa\u00f1a.<\/p>\n<p>En el caso del producto del a\u00f1o 2023, el comportamiento fue m\u00e1s heterog\u00e9neo. En el mercado EEX de Alemania y Reino Unido, as\u00ed como en el <strong>mercado ICE<\/strong> de B\u00e9lgica y Pa\u00edses Bajos los precios subieron. Mientras tanto, en el resto de mercados se registraron bajadas. El mercado EEX de Espa\u00f1a, al igual que el <strong>mercado OMIP<\/strong> de Espa\u00f1a y Portugal, registraron la mayor bajada, la cual fue del 11%.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Tabla precio liquidacion mercados futuros electricidad Europa Q1 y Y1' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Tabla-precio-liquidacion-mercados-futuros-electricidad-Europa-Q1-y-Y1.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Tabla-precio-liquidacion-mercados-futuros-electricidad-Europa-Q1-y-Y1.png' alt='AleaSoft - Tabla precio liquidacion mercados futuros electricidad Europa Q1 y Y1' width='740'\/><\/a><\/div>\n<h2>Brent, combustibles y CO<sub>2<\/sub><\/h2>\n<p>Los precios de cierre de los futuros de <strong>petr\u00f3leo Brent<\/strong> para el Front\u2011Month en el <strong>mercado ICE<\/strong> se mantuvieron por encima de los 105\u00a0$\/bbl durante la segunda semana de marzo. El precio de cierre m\u00e1ximo semanal, de 127,98\u00a0$\/bbl, se alcanz\u00f3 el martes 8 de marzo. Este precio fue un 22% mayor al del martes anterior y el m\u00e1s alto desde julio de 2008. El mi\u00e9rcoles y el jueves los precios descendieron hasta registrar un precio de cierre de 109,33\u00a0$\/bbl el jueves 10 de marzo. Pero el viernes los precios volvieron a aumentar hasta alcanzar un precio de cierre de 112,67\u00a0$\/bbl, el cual todav\u00eda fue un 4,6% menor al del viernes anterior.<\/p>\n<p>El temor a cortes de suministro desde Rusia como represalia a las sanciones impuestas a este pa\u00eds, as\u00ed como la prohibici\u00f3n de la importaci\u00f3n de petr\u00f3leo con procedencia rusa en algunos pa\u00edses, favoreci\u00f3 el incremento de los precios de los futuros de petr\u00f3leo Brent. Por otra parte, la evoluci\u00f3n favorable de las conversaciones sobre el pacto nuclear de Ir\u00e1n, que permitir\u00eda levantar las sanciones a las exportaciones de crudo de este pa\u00eds, tambi\u00e9n ejerci\u00f3 su influencia sobre los precios. Pero estas conversaciones quedaron encalladas al final de la semana.<\/p>\n<p>En cuanto a los precios de los futuros de <strong>gas TTF<\/strong> en el mercado ICE para el Front\u2011Month, iniciaron la segunda semana de marzo con incrementos respecto a la sesi\u00f3n anterior. El lunes 7 de marzo el precio de cierre alcanz\u00f3 un m\u00e1ximo hist\u00f3rico de 227,20\u00a0\u20ac\/MWh y fue un 130% mayor al precio del mismo d\u00eda de la semana anterior. Posteriormente, los precios descendieron hasta alcanzar el jueves 10 de marzo el precio de cierre m\u00ednimo semanal, de 126,40\u00a0\u20ac\/MWh. El viernes, los precios se recuperaron hasta los 131,23\u00a0\u20ac\/MWh. Pero este precio fue un 32% menor al del viernes anterior.<\/p>\n<p>La evoluci\u00f3n del conflicto entre Rusia y Ucrania continu\u00f3 influenciando los precios de los futuros de gas TTF. Los elevados precios del gas est\u00e1n llevando a algunas empresas a considerar interrupciones en la producci\u00f3n e incluso a plantearse vender sus coberturas de gas.<\/p>\n<p>Por lo que respecta a los futuros de <strong>derechos de emisi\u00f3n de CO<sub>2<\/sub><\/strong> en el <strong>mercado EEX<\/strong> para el contrato de referencia de diciembre de 2022, el lunes 7 de marzo registraron el precio de cierre m\u00e1s bajo en lo que va de a\u00f1o, de 58,30\u00a0\u20ac\/t. Este precio fue un 29% menor al del lunes anterior. Sin embargo, el resto de la segunda semana de marzo los precios aumentaron. Como resultado, el precio de cierre del viernes 11 de marzo fue de 76,76\u00a0\u20ac\/t, un 18% mayor al del viernes anterior.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Precios gas carbon Brent CO2' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-gas-carbon-Brent-CO2.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-gas-carbon-Brent-CO2.png' alt='AleaSoft - Precios gas carbon Brent CO2' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ICE y EEX.<\/span><\/div>\n<h2>An\u00e1lisis de AleaSoft Energy Forecasting sobre las perspectivas de los mercados de energ\u00eda en Europa y la financiaci\u00f3n de proyectos renovables<\/h2>\n<p>En el <a href=\"https:\/\/aleasoft.com\/es\/webinars-sobre-mercados-sector-energia\/perspectivas-mercados-energia-europa-primavera-2022\/\">pr\u00f3ximo webinar de <strong>AleaSoft Energy Forecasting<\/strong><\/a>, se analizar\u00e1n los efectos que ha tenido la invasi\u00f3n rusa a Ucrania en los mercados de energ\u00eda europeos. Este webinar se llevar\u00e1 a cabo el jueves 17 de marzo, y en el mismo tambi\u00e9n participar\u00e1n ponentes de <strong>EY<\/strong>, que analizar\u00e1n las principales novedades en la regulaci\u00f3n del sector energ\u00e9tico espa\u00f1ol, la <strong>financiaci\u00f3n de proyectos de energ\u00edas renovables<\/strong>, la importancia de los <strong>PPA<\/strong> y el <strong>autoconsumo<\/strong> y las principales consideraciones a tener en cuenta en la <a href=\"https:\/\/aleasoft.com\/es\/casos-previsiones\/reportes-previsiones-precios-valoracion-carteras-auditorias\/\"><strong>valoraci\u00f3n de carteras<\/strong><\/a>.<\/p>\n<p>Los <strong>grandes consumidores<\/strong> y <strong>electrointensivos<\/strong> se est\u00e1n viendo muy afectados por los altos precios de la energ\u00eda. En estos momentos de incertidumbre, cobra mayor importancia la necesidad de tener una <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-precios-de-energia\/?tab=largo-plazo\">visi\u00f3n de largo plazo<\/a> a la hora de firmar un PPA como parte de una estrategia de compra de energ\u00eda que ayude a minimizar el riesgo de precios de mercado.<\/p>\n<p>Fuente: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 14 de marzo de 2022. En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas. Sin embargo, hacia el final de la semana en algunos mercados se registraron valores horarios negativos gracias al incremento generalizado de la producci\u00f3n e\u00f3lica. En el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[7508],"class_list":["post-125992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-analisis-mercados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos\" \/>\n<meta property=\"og:description\" content=\"En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-14T14:13:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T14:13:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos\",\"datePublished\":\"2022-03-14T14:13:14+00:00\",\"dateModified\":\"2022-03-14T14:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/\"},\"wordCount\":2174,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"keywords\":[\"an\u00e1lisis de mercados\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/\",\"name\":\"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"datePublished\":\"2022-03-14T14:13:14+00:00\",\"dateModified\":\"2022-03-14T14:13:17+00:00\",\"description\":\"En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"width\":2282,\"height\":1589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos - AleaSoft Energy Forecasting","description":"En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/","og_locale":"es_ES","og_type":"article","og_title":"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos","og_description":"En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas.","og_url":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2022-03-14T14:13:14+00:00","article_modified_time":"2022-03-14T14:13:17+00:00","og_image":[{"width":2282,"height":1589,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos","datePublished":"2022-03-14T14:13:14+00:00","dateModified":"2022-03-14T14:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/"},"wordCount":2174,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png","keywords":["an\u00e1lisis de mercados"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/","url":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/","name":"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png","datePublished":"2022-03-14T14:13:14+00:00","dateModified":"2022-03-14T14:13:17+00:00","description":"En la segunda semana de marzo varios mercados el\u00e9ctricos europeos registraron precios m\u00e1ximos hist\u00f3ricos arrastrados por los precios r\u00e9cord del gas.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220314-AleaSoft-Precios-mercados-europeos-electricidad.png","width":2282,"height":1589},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/gas-lleva-precios-mercados-electricos-europeos-maximos-historicos-eolica-arrastra-precios-negativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"El gas lleva los precios en los mercados el\u00e9ctricos europeos a m\u00e1ximos hist\u00f3ricos y la e\u00f3lica los arrastra a precios negativos"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/125992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=125992"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/125992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media\/126011"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=125992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/categories?post=125992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/tags?post=125992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}