{"id":154336,"date":"2025-02-10T13:26:31","date_gmt":"2025-02-10T12:26:31","guid":{"rendered":"https:\/\/aleasoft.com\/?p=154336"},"modified":"2025-02-10T16:23:58","modified_gmt":"2025-02-10T15:23:58","slug":"subida-gas-menos-viento-elevan-precios-mercados-europeos","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/","title":{"rendered":"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 10 de febrero de 2025. En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto de los dos \u00faltimos a\u00f1os. En este contexto, al que se sum\u00f3 una menor producci\u00f3n e\u00f3lica y una mayor demanda, los precios de los principales mercados el\u00e9ctricos europeos subieron, superando la mayor\u00eda los 120\u00a0\u20ac\/MWh de promedio semanal. La solar fotovoltaica alcanz\u00f3 r\u00e9cords de producci\u00f3n para un d\u00eda de febrero en Espa\u00f1a, Portugal y Francia.<\/strong><\/p>\n<h2>Producci\u00f3n solar fotovoltaica y producci\u00f3n e\u00f3lica<\/h2>\n<p>En la semana del 3 de febrero, la <strong>producci\u00f3n solar fotovoltaica<\/strong> aument\u00f3 en los principales mercados europeos con respecto a la semana anterior. En los mercados de la pen\u00ednsula ib\u00e9rica, Francia y Alemania aument\u00f3 por segunda semana consecutiva, mientras que en el mercado italiano mantuvo la tendencia al alza por cuarta semana. En esta ocasi\u00f3n, el mercado espa\u00f1ol registr\u00f3 el mayor incremento, del 40%, mientras que el mercado alem\u00e1n tuvo el menor aumento, del 17%. Los mercados de Portugal, Italia y Francia registraron subidas del 25%, 30% y 31%, respectivamente.<\/p>\n<p>Durante la semana, los mercados de Francia y la pen\u00ednsula ib\u00e9rica registraron r\u00e9cords hist\u00f3ricos de producci\u00f3n solar fotovoltaica para un d\u00eda de febrero. En el mercado franc\u00e9s esto sucedi\u00f3 el d\u00eda 3, con 68\u00a0GWh. El mercado portugu\u00e9s registr\u00f3 su r\u00e9cord de producci\u00f3n con esta tecnolog\u00eda para un d\u00eda de febrero, de 17\u00a0GWh, el d\u00eda 5. En el caso del mercado espa\u00f1ol, el jueves 6 de febrero registr\u00f3 su generaci\u00f3n fotovoltaica diaria m\u00e1s alta para un febrero, de 129\u00a0GWh.<\/p>\n<p>Para la semana del 10 de febrero, las <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-energia-solar\/\">previsiones de producci\u00f3n solar<\/a> de <strong>AleaSoft Energy Forecasting<\/strong> indican incrementos en el mercado alem\u00e1n, mientras que prev\u00e9n una disminuci\u00f3n en los mercados espa\u00f1ol e italiano.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Produccion fotovoltaica electricidad Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Produccion-fotovoltaica-electricidad-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Produccion-fotovoltaica-electricidad-Europa.png' alt='AleaSoft - Produccion fotovoltaica electricidad Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE y TERNA.<\/span><\/div><br \/>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Perfil produccion solar fotovoltaica Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Perfil-produccion-solar-fotovoltaica-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Perfil-produccion-solar-fotovoltaica-Europa.png' alt='AleaSoft - Perfil produccion solar fotovoltaica Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE y TERNA.<\/span><\/div><\/p>\n<p>En la primera semana de febrero, la <strong>producci\u00f3n e\u00f3lica<\/strong> disminuy\u00f3 en los principales mercados europeos en comparaci\u00f3n con la semana anterior. El mercado alem\u00e1n registr\u00f3 el menor descenso, del 20%, manteni\u00e9ndose a la baja por segunda semana consecutiva. Los mercados de la pen\u00ednsula ib\u00e9rica experimentaron las mayores ca\u00eddas, del 59% en Espa\u00f1a y 62% en Portugal. Los mercados italiano y franc\u00e9s registraron bajadas del 24% y 47%, respectivamente.<\/p>\n<p>Para la segunda semana de febrero, seg\u00fan las <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-energia-eolica\/\">previsiones de producci\u00f3n e\u00f3lica<\/a> de <strong>AleaSoft Energy Forecasting,<\/strong> la producci\u00f3n aumentar\u00e1 en el mercado alem\u00e1n, mientras que los mercados de Italia, Francia y la pen\u00ednsula ib\u00e9rica registrar\u00e1n descensos.<br \/>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Produccion eolica electricidad Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Produccion-eolica-electricidad-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Produccion-eolica-electricidad-Europa.png' alt='AleaSoft - Produccion eolica electricidad Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE y TERNA.<\/span><\/div><\/p>\n<h2>Demanda el\u00e9ctrica<\/h2>\n<p>En la primera semana de febrero, la <strong>demanda el\u00e9ctrica<\/strong> aument\u00f3 en la mayor\u00eda de los principales mercados el\u00e9ctricos europeos en comparaci\u00f3n con la semana anterior. El mercado franc\u00e9s registr\u00f3 la mayor subida, del 6,5%, mientras que el mercado espa\u00f1ol tuvo el menor incremento, del 0,5%. Los mercados italiano, brit\u00e1nico, belga, neerland\u00e9s y alem\u00e1n registraron aumentos que oscilaron entre el 1,5% en Italia y Gran Breta\u00f1a y el 3,9% en Alemania. El mercado portugu\u00e9s fue la excepci\u00f3n, ya que la demanda cay\u00f3 por segunda semana consecutiva, esta vez un 0,7%.<\/p>\n<p>Durante la semana, las <strong>temperaturas medias<\/strong> fueron m\u00e1s fr\u00edas que las de la semana anterior en todos los mercados. Los descensos de las temperaturas medias oscilaron entre los 0,8\u00b0C en Gran Breta\u00f1a y los 3,0\u00b0C en Alemania.<\/p>\n<p>Para la segunda semana de febrero, las <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-la-demanda-de-energia\/\">previsiones de demanda<\/a> de <strong>AleaSoft Energy Forecasting <\/strong>indican que, en los mercados de los Pa\u00edses Bajos, Gran Breta\u00f1a, Alemania y B\u00e9lgica la demanda aumentar\u00e1. Por otro lado, las previsiones apuntan a un descenso de la demanda en los mercados de Francia, Espa\u00f1a, Portugal e Italia.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Demanda electricidad paises Europa' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Demanda-electricidad-paises-Europa.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Demanda-electricidad-paises-Europa.png' alt='AleaSoft - Demanda electricidad paises Europa' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ENTSO-E, RTE, REN, REE, TERNA, National Grid y ELIA.<\/span><\/div>\n<h2>Mercados el\u00e9ctricos europeos<\/h2>\n<p>En la primera semana de febrero, los precios promedio de los principales mercados el\u00e9ctricos europeos aumentaron. El<strong> mercado N2EX<\/strong> del Reino Unido registr\u00f3 el menor incremento, del 2,0%, mientras que el <strong>mercado MIBEL<\/strong> de Espa\u00f1a y Portugal registr\u00f3 las mayores subidas porcentuales de precios, del 94% y el 95%, respectivamente. En el resto de los mercados analizados en <strong>AleaSoft Energy Forecasting<\/strong>, los precios subieron entre el 7,8% del <strong>mercado Nord\u00a0Pool<\/strong> de los pa\u00edses n\u00f3rdicos y el 52% del<strong> mercado EPEX\u00a0SPOT<\/strong> de Francia.<\/p>\n<p>En la semana del 3 de febrero, los promedios semanales fueron superiores a 120\u00a0\u20ac\/MWh en la mayor\u00eda de los mercados el\u00e9ctricos europeos analizados. La excepci\u00f3n fue el mercado n\u00f3rdico, que registr\u00f3 el promedio m\u00e1s bajo, de 51,73\u00a0\u20ac\/MWh. El <strong>mercado IPEX <\/strong>de Italia alcanz\u00f3 el mayor promedio semanal, de 153,81\u00a0\u20ac\/MWh. En el resto de los mercados analizados, los precios estuvieron entre los 123,35\u00a0\u20ac\/MWh del mercado portugu\u00e9s y los 140,18\u00a0\u20ac\/MWh del mercado belga.<\/p>\n<p>Por lo que respecta a los precios diarios, en la primera semana de febrero, los precios de la mayor\u00eda de los mercados el\u00e9ctricos analizados se mantuvieron por encima 105\u00a0\u20ac\/MWh. La excepci\u00f3n fue el mercado n\u00f3rdico, cuyos precios fueron inferiores a 90\u00a0\u20ac\/MWh. Este mercado alcanz\u00f3 un precio de 33,11\u00a0\u20ac\/MWh el d\u00eda 5 de febrero, que fue el precio m\u00e1s bajo de la semana en los mercados analizados. Por otra parte, los precios diarios superaron los 150\u00a0\u20ac\/MWh en algunas sesiones de la primera semana de febrero en los mercados alem\u00e1n, belga, franc\u00e9s, italiano y neerland\u00e9s. El mercado italiano registr\u00f3 el precio m\u00e1s elevado, de 155,76\u00a0\u20ac\/MWh, el d\u00eda 9 de febrero.<\/p>\n<p>En la semana del 3 de febrero, la ca\u00edda de la producci\u00f3n e\u00f3lica y el incremento del precio semanal del gas, as\u00ed como el aumento de la demanda en la mayor\u00eda de los mercados, propiciaron la subida de los precios en los mercados el\u00e9ctricos europeos.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Paneles solares' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/pexels-fotovoltaica-eolica5-scaled.jpg'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/pexels-fotovoltaica-eolica5-scaled.jpg' alt='AleaSoft - Paneles solares' width='740'\/><\/a><\/div>\n<p>Las <a href=\"https:\/\/aleasoft.com\/es\/productos-y-servicios\/previsiones-de-precios-de-energia\/\">previsiones de precios<\/a> de <strong>AleaSoft Energy Forecasting<\/strong> indican que, en la segunda semana de febrero, los precios bajar\u00e1n en la mayor\u00eda de los mercados el\u00e9ctricos europeos. El incremento de la producci\u00f3n e\u00f3lica y solar en mercados como el alem\u00e1n y el descenso de la demanda en Francia y Espa\u00f1a contribuir\u00e1n a estos descensos.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Precios mercados europeos electricidad' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png' alt='AleaSoft - Precios mercados europeos electricidad' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de OMIE, , Nord Pool y GME.<\/span><\/div>\n<h2>Brent, combustibles y CO<sub>2<\/sub><\/h2>\n<p>Los futuros de <strong>petr\u00f3leo Brent<\/strong> para el Front\u2011Month en el <strong>mercado ICE<\/strong> alcanzaron su precio de cierre m\u00e1ximo semanal, de 76,20\u00a0$\/bbl, el martes 4 de febrero. En las siguientes sesiones de la primera semana del mes, los precios de cierre se mantuvieron por debajo de 75\u00a0$\/bbl. El d\u00eda 6 de febrero, estos futuros registraron su precio de cierre m\u00ednimo semanal, de 74,29\u00a0$\/bbl. Seg\u00fan los datos analizados en <strong>AleaSoft Energy Forecasting<\/strong>, este precio fue el m\u00e1s bajo desde el 28 de diciembre de 2024. El viernes 7 de febrero, el precio de cierre fue de 74,66\u00a0$\/bbl, un 2,7% menor al del viernes anterior.<\/p>\n<p>A pesar del incremento de las sanciones al petr\u00f3leo iran\u00ed, los planes para incrementar la producci\u00f3n en Estados Unidos, as\u00ed como la preocupaci\u00f3n por las consecuencias de las pol\u00edticas arancelarias estadounidenses sobre la demanda global de petr\u00f3leo, continuaron favoreciendo el descenso de los precios de los futuros de petr\u00f3leo Brent en la primera semana de febrero. Adem\u00e1s, el incremento de las reservas de petr\u00f3leo estadounidenses, junto con el descenso de la demanda de gasolina en ese pa\u00eds, tambi\u00e9n ejercieron su influencia a la baja sobre los precios de estos futuros.<\/p>\n<p>En cuanto a los precios de cierre de los futuros de <strong>gas TTF<\/strong> en el mercado ICE para el Front\u2011Month, superaron los 50\u00a0\u20ac\/MWh en todas las sesiones de la primera semana de febrero. El martes 4 de febrero, estos futuros registraron su precio de cierre m\u00ednimo semanal, de 52,05\u00a0\u20ac\/MWh. Sin embargo, los precios aumentaron en las siguientes sesiones de la primera semana de febrero. Como resultado, el viernes 7 de febrero, estos futuros alcanzaron su precio de cierre m\u00e1ximo semanal, de 55,72\u00a0\u20ac\/MWh. Seg\u00fan los datos analizados en <strong>AleaSoft Energy Forecasting<\/strong>, este precio fue un 4,7% mayor al del viernes anterior y el m\u00e1s alto desde el 7 de febrero de 2023.<\/p>\n<p>El descenso de la producci\u00f3n e\u00f3lica y las bajas temperaturas propiciaron el incremento de la demanda de gas en la primera semana de febrero. Esto favoreci\u00f3 el incremento de los precios de los futuros de gas TTF. Adem\u00e1s, la preocupaci\u00f3n por el nivel de las reservas europeas, que al final de la primera semana de febrero se situ\u00f3 por debajo del 50%, tambi\u00e9n contribuy\u00f3 a las subidas de precios.<\/p>\n<p>Por lo que respecta a los futuros de <strong>derechos de emisi\u00f3n de CO<sub>2<\/sub><\/strong> en el <strong>mercado EEX<\/strong> para el contrato de referencia de diciembre de 2025, el lunes 3 de febrero los precios cayeron un 3,6% respecto a la \u00faltima sesi\u00f3n de la semana anterior. El martes tambi\u00e9n descendieron ligeramente. Ese d\u00eda, estos futuros registraron su precio de cierre m\u00ednimo semanal, de 80,88\u00a0\u20ac\/t. En el resto de las sesiones de la primera semana de febrero, los precios registraron una tendencia ascendente. Como resultado, el viernes 7 de febrero estos futuros registraron su precio de cierre m\u00e1ximo semanal, de 82,28\u00a0\u20ac\/t. Seg\u00fan los datos analizados en <strong>AleaSoft Energy Forecasting<\/strong>, este precio todav\u00eda fue un 2,0% menor al del viernes anterior.<br \/>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Precios gas carbon Brent CO2' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-gas-carbon-Brent-CO2.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-gas-carbon-Brent-CO2.png' alt='AleaSoft - Precios gas carbon Brent CO2' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft Energy Forecasting con datos de ICE y EEX.<\/span><\/div><\/p>\n<h2>An\u00e1lisis de AleaSoft Energy Forecasting sobre las perspectivas de los mercados de energ\u00eda y el almacenamiento en Europa<\/h2>\n<p>El pr\u00f3ximo jueves 13 de febrero tendr\u00e1 lugar el <a href=\"https:\/\/aleasoft.com\/es\/webinars-sobre-mercados-sector-energia\/mercados-almacenamiento-febrero-2025\/\">webinar n\u00famero 52<\/a> de la <a href=\"https:\/\/aleasoft.com\/es\/webinars-sobre-mercados-sector-energia\/\">serie de webinars mensuales<\/a> de <strong>AleaSoft Energy Forecasting<\/strong>. En esta ocasi\u00f3n, el ponente invitado ser\u00e1 Tom\u00e1s Garc\u00eda, Senior Director, Energy &amp; Infrastructure Advisory en <strong>JLL<\/strong>. Este webinar analizar\u00e1 la evoluci\u00f3n y perspectivas de los mercados de energ\u00eda europeos, as\u00ed como los \u201ccontracted revenues\u201d para proyectos <strong>BESS<\/strong>, mediante el <strong>mercado de capacidad<\/strong> y los <strong>Optimizer Agreements<\/strong>.<\/p>\n<p>Fuente: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 10 de febrero de 2025. En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto de los dos \u00faltimos a\u00f1os. En este contexto, al que se sum\u00f3 una menor producci\u00f3n e\u00f3lica y una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":154356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7573,568],"tags":[7569,7568,7567,7566,7571,7572,7570],"class_list":["post-154336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis-semanal","category-noticias","tag-demanda","tag-eolica","tag-fotovoltaica","tag-mercados","tag-precios-brent","tag-precios-co2","tag-precios-gas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto del \u00faltimo a\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero\" \/>\n<meta property=\"og:description\" content=\"En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto del \u00faltimo a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T12:26:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T15:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\\\/MWh en la primera semana de febrero\",\"datePublished\":\"2025-02-10T12:26:31+00:00\",\"dateModified\":\"2025-02-10T15:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/\"},\"wordCount\":1839,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"keywords\":[\"Demanda\",\"E\u00f3lica\",\"Fotovoltaica\",\"Mercados\",\"Precios Brent\",\"Precios CO2\",\"Precios gas\"],\"articleSection\":[\"An\u00e1lisis semanal\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/\",\"name\":\"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\\\/MWh en la primera semana de febrero - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"datePublished\":\"2025-02-10T12:26:31+00:00\",\"dateModified\":\"2025-02-10T15:23:58+00:00\",\"description\":\"En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto del \u00faltimo a\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"width\":2048,\"height\":1426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/subida-gas-menos-viento-elevan-precios-mercados-europeos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\\\/MWh en la primera semana de febrero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero - AleaSoft Energy Forecasting","description":"En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto del \u00faltimo a\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/","og_locale":"es_ES","og_type":"article","og_title":"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero","og_description":"En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto del \u00faltimo a\u00f1o.","og_url":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2025-02-10T12:26:31+00:00","article_modified_time":"2025-02-10T15:23:58+00:00","og_image":[{"width":2048,"height":1426,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero","datePublished":"2025-02-10T12:26:31+00:00","dateModified":"2025-02-10T15:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/"},"wordCount":1839,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png","keywords":["Demanda","E\u00f3lica","Fotovoltaica","Mercados","Precios Brent","Precios CO2","Precios gas"],"articleSection":["An\u00e1lisis semanal","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/","url":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/","name":"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png","datePublished":"2025-02-10T12:26:31+00:00","dateModified":"2025-02-10T15:23:58+00:00","description":"En la primera semana de febrero, los precios de los futuros de gas TTF continuaron aumentando y alcanzaron al final de la semana el precio de cierre m\u00e1s alto del \u00faltimo a\u00f1o.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250210-AleaSoft-Precios-mercados-europeos-electricidad.png","width":2048,"height":1426},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/subida-gas-menos-viento-elevan-precios-mercados-europeos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"Subida del gas y menos viento elevan los precios de los mercados el\u00e9ctricos europeos por encima de 120 \u20ac\/MWh en la primera semana de febrero"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/154336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=154336"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/154336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media\/154356"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=154336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/categories?post=154336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/tags?post=154336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}