{"id":78037,"date":"2019-03-19T00:00:00","date_gmt":"2019-03-18T23:00:00","guid":{"rendered":"https:\/\/aleasoft.com\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/"},"modified":"2022-05-20T00:42:17","modified_gmt":"2022-05-19T22:42:17","slug":"continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/","title":{"rendered":"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica"},"content":{"rendered":"<p><strong>AleaSoft, 18 de marzo de 2019. AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO<sub>2<\/sub> y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.<\/strong><\/p>\n<h3 style=\"font-size: 12pt;\">Brent, combustibles y CO<sub>2<\/sub><\/h3>\n<p>Los precios de futuros del <strong>petr\u00f3leo Brent<\/strong> para mayo de 2019 en el <strong>mercado ICE <\/strong>contin\u00faan al igual que la semana anterior estabilizados en una franja de precios entre 65\u00a0$\/bbl y 67\u00a0$\/bbl desde el 15 de febrero. En los \u00faltimos d\u00edas los precios han estado ligeramente por encima de los 67\u00a0$\/bbl pero sin una clara tendencia a llegar a los 67,55\u00a0$\/bbl del mi\u00e9rcoles 13 de marzo, que es un valor que no se alcanza desde el 19 de noviembre del a\u00f1o pasado. Las previsiones de la Agencia Internacional de la Energ\u00eda de un posible d\u00e9ficit de crudo en la segunda mitad de 2019, junto con la inestabilidad pol\u00edtica en Venezuela y la posibilidad de que los pa\u00edses de la OPEP extiendan sus recortes de producci\u00f3n, est\u00e1n manteniendo los precios del Brent en estos niveles y con posibilidades de que la ligera tendencia al alza de los \u00faltimos d\u00edas se mantenga durante la semana.<\/p>\n<p><a href='https:\/\/aleasoft.com\/es\/casos-previsiones\/ppa-y-sinergias\/' class='alea-banner-link' data-alea-gtm-event-category='banner-almost-square' data-alea-gtm-event-label='ppa'><img class='alignleft' src='' alt='Oferta de previsiones de precios a largo plazo para PPA' style=''\/><\/a>Los futuros de <strong>gas TTF<\/strong> en el mercado ICE para abril contin\u00faan con una tendencia a la baja desde el 25 de septiembre de 2018, o sea hace casi seis meses, fecha en que alcanzaron un precio m\u00e1ximo de 26,50\u00a0\u20ac\/MWh, mientras el viernes de la semana anterior, 15 de marzo, cerraron con 15,25\u00a0\u20ac\/MWh, que es el valor m\u00e1s bajo de los \u00faltimos dos a\u00f1os. En una semana los futuros del gas TTF para abril cayeron 1,50\u00a0\u20ac\/MWh y, con esta significativa pendiente de bajada, desde <strong>AleaSoft<\/strong> se considera que los precios deben seguir bajando por debajo de los 15\u00a0\u20ac\/MWh, teniendo en cuenta la llegada de la primavera con temperaturas m\u00e1s altas y menor demanda el\u00e9ctrica. De momento, la situaci\u00f3n de inestabilidad en Argelia no est\u00e1 influyendo en los precios del gas.<\/p>\n<p>Como se planteaba en comentarios anteriores de <strong>AleaSoft<\/strong>, la evoluci\u00f3n de los precios de futuros del <strong>carb\u00f3n API 2<\/strong> para el mes de abril en el mercado ICE se ha mantenido muy alineada con los precios de futuros del gas TTF para el mismo per\u00edodo. A principios de octubre del a\u00f1o pasado los precios del carb\u00f3n llegaron a estar por sobre los 100\u00a0$\/t; en estos momentos, al cierre del viernes 15 de marzo, el precio de los futuros del carb\u00f3n API 2 para abril lleg\u00f3 a bajar de los 70\u00a0$\/t, alcanzando los 69,65\u00a0$\/t. Valores por debajo de 70\u00a0$\/t no se ve\u00edan desde principios de agosto del 2017. Desde octubre del 2018 hasta la fecha actual la bajada ha sido de m\u00e1s de 30\u00a0$\/t. Seg\u00fan el an\u00e1lisis de <strong>AleaSoft<\/strong>, teniendo en cuenta la evoluci\u00f3n paralela de los precios del gas y del carb\u00f3n, el precio del carb\u00f3n puede seguir bajando hasta caer en niveles de 60\u00a0$\/t en las pr\u00f3ximas semanas, alcanzando valores de hace dos a\u00f1os.<\/p>\n<p>Durante este mes de marzo, en la evoluci\u00f3n de los precios de los futuros de <strong>derechos de emisiones de CO<sub>2<\/sub><\/strong> para el contrato de referencia de diciembre de 2019 en el <strong>mercado EEX<\/strong> se observan unos precios oscilando entre los 22\u00a0\u20ac\/t y 23\u00a0\u20ac\/t de forma estacionaria. El precio de liquidaci\u00f3n del viernes fue de 22,47\u00a0\u20ac\/t y este valor se corresponde al valor de equilibrio de este a\u00f1o 2019 que est\u00e1 cercano a los 22\u00a0\u20ac\/t y que en <strong>AleaSoft<\/strong> se plantea como una referencia para las pr\u00f3ximas semanas con una tendencia a bajar hasta los 20\u00a0\u20ac\/t.<\/p>\n<h3 style=\"font-size: 12pt;\">Mercados el\u00e9ctricos europeos<\/h3>\n<p>Los precios de los mercados el\u00e9ctricos en Europa han tenido un patr\u00f3n de ligera bajada continuada desde inicios de febrero. En marzo, la temperatura y la demanda el\u00e9ctrica han sido en general estables hasta la fecha. Como se ha planteado en comentarios anteriores de <strong>AleaSoft<\/strong>, con la llegada de la primavera las temperaturas ir\u00e1n subiendo y la demanda bajando. La ligera bajada de precios desde febrero se debe a la bajada experimentada por los combustibles y el CO<sub>2<\/sub>. Tambi\u00e9n ha influido una producci\u00f3n e\u00f3lica relativamente alta y una producci\u00f3n solar fotovoltaica y termosolar que va aumentando en la medida que van habiendo m\u00e1s horas de sol.<\/p>\n<p>En la evoluci\u00f3n de los precios de los principales mercados el\u00e9ctricos europeos esta semana, se observan las mismas tres franjas de semanas anteriores. En la franja m\u00e1s alta est\u00e1n los mercados <strong>N2EX<\/strong> de UK y el mercado italiano <strong>IPEX<\/strong> con precios entre 50 y 60\u00a0\u20ac\/MWh. Estos precios se mantendr\u00e1n estables para los pr\u00f3ximos d\u00edas.<\/p>\n<p>El mercado <strong>MIBEL<\/strong> de Espa\u00f1a y Portugal se encuentra en la franja media con valores alrededor de los 50\u00a0\u20ac\/MWh y, como hab\u00edamos planteado anteriormente, este valor de 50\u00a0\u20ac\/MWh puede ser una tendencia para los pr\u00f3ximos d\u00edas. En el an\u00e1lisis realizado por <strong>AleaSoft<\/strong> la semana pasada, los precios de Espa\u00f1a y Portugal estaban en la franja de precios m\u00e1s alta. La ca\u00edda a la franja media se ha debido a una mayor producci\u00f3n e\u00f3lica y solar, aunque hay que considerar tambi\u00e9n los factores primaverales de temperatura.<\/p>\n<p>En la franja con precios m\u00e1s bajos hay dos grupos. Los mercados <strong>EPEX\u00a0SPOT<\/strong> de los Pa\u00edses Bajos y <strong>Nord\u00a0Pool<\/strong> de los pa\u00edses n\u00f3rdicos contin\u00faan con valores medios de 40\u00a0\u20ac\/MWh, mientras que los mercados <strong>EPEX\u00a0SPOT<\/strong> de Francia y Alemania tienen los precios m\u00e1s bajos con una media para los \u00faltimos d\u00edas de unos 25\u00a0\u20ac\/MWh. En el caso de Alemania ha bajado hasta los 0,43\u00a0\u20ac\/MWh y Francia hasta los 8,76\u00a0\u20ac\/MWh el domingo 17 de marzo. Los precios de B\u00e9lgica en los \u00faltimos d\u00edas tambi\u00e9n han sido muy bajos, aunque no tanto como Francia y Alemania, llegando el domingo 17 a los 13,33\u00a0\u20ac\/MWh. Los precios de esta franja m\u00e1s baja deber\u00e1n subir para los pr\u00f3ximos d\u00edas.<\/p>\n<p>En las previsiones de <strong>AleaSoft<\/strong> para los pr\u00f3ximos d\u00edas se espera que bajen un poco las temperaturas, pero en general la demanda no tendr\u00e1 afectaci\u00f3n a nivel europeo manteni\u00e9ndose la estabilidad con la llegada de la primavera. Al igual que la semana pasada, para la \u00faltima semana de marzo y para abril las temperaturas ir\u00e1n subiendo gradualmente y la demanda continuar\u00e1 con la bajada estacional.<\/p>\n<p><a title=\"AleaSoft \u2013 Tabla precio mercados demanda electricidad temperatura Europa\" href=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-tabla-precio-mercados-demanda-electricidad-temperatura-europa.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2885 size-full\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-tabla-precio-mercados-demanda-electricidad-temperatura-europa.png\" alt=\"AleaSoft - Tabla precio mercados demanda electricidad temperatura Europa\" width=\"740\" height=\"530\" \/><\/a><\/p>\n<h3 style=\"font-size: 12pt;\">Futuros de electricidad<\/h3>\n<p>Durante la semana pasada del 11 de marzo los <strong>futuros de electricidad<\/strong> para abril de 2019 en los mercados europeos tuvieron una tendencia a la baja en general, con la excepci\u00f3n de los futuros de Espa\u00f1a, en los mercados <strong>OMIP<\/strong> y <strong>EEX<\/strong>, que al inicio de la semana subieron despu\u00e9s de que la Ministra para la Transici\u00f3n Ecol\u00f3gica, Teresa Ribera, anunciara que no se prorrogar\u00e1 la suspensi\u00f3n del impuesto del 7% a la generaci\u00f3n que se hab\u00eda aprobado en octubre del a\u00f1o pasado con una duraci\u00f3n de seis meses, y los futuros de Portugal en el mercado OMIP, que tambi\u00e9n subieron arrastrados por la subida de los precios de Espa\u00f1a. En el resto de mercados, el precio de liquidaci\u00f3n del viernes 15 de marzo fue entre 2\u00a0\u20ac\/MWh y 4\u00a0\u20ac\/MWh m\u00e1s bajo que el de la sesi\u00f3n del viernes 8 de marzo.<\/p>\n<p><a title=\"AleaSoft \u2013 Tabla liquidacion mercados futuros electricidad europa\" href=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-tabla-precio-liquidacion-mercados-futuros-electricidad-europa.png\"><img decoding=\"async\" class=\"aligncenter wp-image-2885 size-full\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-tabla-precio-liquidacion-mercados-futuros-electricidad-europa.png\" alt=\"AleaSoft - Tabla liquidacion mercados futuros electricidad europa\" width=\"740\" height=\"530\" \/><\/a><\/p>\n<p>En los mercados de Francia, Alemania, e Italia, el precio de liquidaci\u00f3n del viernes 15 de marzo para los futuros del pr\u00f3ximo mes es el m\u00ednimo desde que se negocia este producto.<\/p>\n<h3 style=\"font-size: 12pt;\">Producci\u00f3n e\u00f3lica y solar<\/h3>\n<p>La <strong>producci\u00f3n e\u00f3lica<\/strong> continu\u00f3 alta en los d\u00edas del 10 al 16 de marzo manteni\u00e9ndose el patr\u00f3n que comenz\u00f3 a inicios de este mes.<\/p>\n<p>Para la semana pr\u00f3xima en <strong>AleaSoft<\/strong> se prev\u00e9 que la producci\u00f3n e\u00f3lica disminuya en Francia y Alemania y que se mantenga en el resto de pa\u00edses europeos.<\/p>\n<p><a title=\"AleaSoft \u2013 Producci\u00f3n e\u00f3lica electricidad Europa\" href=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png\"><img decoding=\"async\" class=\"aligncenter wp-image-2885 size-full\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png\" alt=\"AleaSoft - Producci\u00f3n e\u00f3lica electricidad Europa\" width=\"740\" height=\"530\" \/><\/a><\/p>\n<p><span style=\"font-size: xx-small;\">Fuentes: Elaborado por AleaSoft con datos de ENTSOE, RTE, REN, REE y TERNA.<\/span><\/p>\n<p>La <strong>producci\u00f3n solar<\/strong>, que incluye tanto la tecnolog\u00eda <strong>fotovoltaica<\/strong> como la <strong>termosolar<\/strong>, ha sido alta en general en la semana del 10 al 16 de marzo. En el caso de Alemania, en <strong>AleaSoft<\/strong> se prev\u00e9 un aumento de la producci\u00f3n solar para el resto de marzo, para la pen\u00ednsula ib\u00e9rica y para Italia se mantendr\u00e1 en los mismos niveles.<\/p>\n<a href='https:\/\/aleasoft.com\/es\/casos-previsiones\/ppa-y-sinergias\/' class='alea-banner-link' data-alea-gtm-event-category='banner-horizontal' data-alea-gtm-event-label='ppa'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/banners_ppa_es.jpg' alt='Oferta de previsiones de precios a largo plazo para PPA' style=''\/><\/a>\n<p>En general, a medida que haya m\u00e1s horas de sol la tendencia al aumento de la producci\u00f3n solar seguir\u00e1 hasta el verano.<\/p>\n<p><a title=\"AleaSoft \u2013 Producci\u00f3n solar fotovoltaica termosolar electricidad Europa\" href=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-solar-fotovoltaica-termosolar-electricidad-europa.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2885 size-full\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-solar-fotovoltaica-termosolar-electricidad-europa.png\" alt=\"AleaSoft - Producci\u00f3n solar fotovoltaica termosolar electricidad Europa\" width=\"740\" height=\"530\" \/><\/a><\/p>\n<p><span style=\"font-size: xx-small;\">Fuentes: Elaborado por AleaSoft con datos de ENTSOE, REE y TERNA.<\/span><\/p>\n<p>Fuente: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n<p align=\"left\"><a style=\"color: #0047c8;\" title=\"PDF\" href=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-continua-bajada-precios-mercados-europeos-mayor-produccion-eolica.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar PDF<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 18 de marzo de 2019. AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo. Brent, combustibles y CO2 Los precios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":66464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[574],"class_list":["post-78037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica<\/title>\n<meta name=\"description\" content=\"AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica\" \/>\n<meta property=\"og:description\" content=\"AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-18T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T22:42:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2300\" \/>\n\t<meta property=\"og:image:height\" content=\"1604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica\",\"datePublished\":\"2019-03-18T23:00:00+00:00\",\"dateModified\":\"2022-05-19T22:42:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/\"},\"wordCount\":1492,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/20190318-aleasoft-produccin-elica-electricidad-europa.png\",\"keywords\":[\"noticias\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/\",\"name\":\"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/20190318-aleasoft-produccin-elica-electricidad-europa.png\",\"datePublished\":\"2019-03-18T23:00:00+00:00\",\"dateModified\":\"2022-05-19T22:42:17+00:00\",\"description\":\"AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/20190318-aleasoft-produccin-elica-electricidad-europa.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/20190318-aleasoft-produccin-elica-electricidad-europa.png\",\"width\":2300,\"height\":1604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica","description":"AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/","og_locale":"es_ES","og_type":"article","og_title":"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica","og_description":"AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.","og_url":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2019-03-18T23:00:00+00:00","article_modified_time":"2022-05-19T22:42:17+00:00","og_image":[{"width":2300,"height":1604,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica","datePublished":"2019-03-18T23:00:00+00:00","dateModified":"2022-05-19T22:42:17+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/"},"wordCount":1492,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png","keywords":["noticias"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/","url":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/","name":"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png","datePublished":"2019-03-18T23:00:00+00:00","dateModified":"2022-05-19T22:42:17+00:00","description":"AleaSoft analiza los mercados de combustibles, derechos de emisiones de CO2 y electricidad europeos, en una semana en que contin\u00faa la tendencia de la semana anterior con producci\u00f3n e\u00f3lica elevada y con precios m\u00e1s bajos en los principales mercados el\u00e9ctricos del continente europeo.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/03\/20190318-aleasoft-produccin-elica-electricidad-europa.png","width":2300,"height":1604},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/continua-bajada-precios-mercados-europeos-marzo-mayor-produccion-eolica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"Contin\u00faa la bajada de precios en los mercados europeos en marzo por mayor producci\u00f3n e\u00f3lica"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/78037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=78037"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/78037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media\/66464"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=78037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/categories?post=78037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/tags?post=78037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}