{"id":78216,"date":"2020-01-22T00:00:00","date_gmt":"2020-01-21T23:00:00","guid":{"rendered":"https:\/\/aleasoft.com\/hidrogeno-verde-combustible-futuro\/"},"modified":"2020-06-09T12:34:55","modified_gmt":"2020-06-09T10:34:55","slug":"hidrogeno-verde-combustible-futuro","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/","title":{"rendered":"El hidr\u00f3geno verde es el combustible del futuro"},"content":{"rendered":"<p><strong>AleaSoft, 21 de enero de 2020. El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.<\/strong><\/p>\n<p>El <strong>hidr\u00f3geno <\/strong>es el elemento m\u00e1s abundante en el universo. Se usa como insumo en la refinaci\u00f3n de petr\u00f3leo, la producci\u00f3n de amon\u00edaco y metanol y la fabricaci\u00f3n de acero. La demanda mundial actual de hidr\u00f3geno es de m\u00e1s de 70 millones de toneladas anuales.<\/p>\n<p>El suministro de hidr\u00f3geno a usuarios industriales es ahora un negocio importante en todo el mundo. La demanda de hidr\u00f3geno, que se ha multiplicado por m\u00e1s de tres desde 1975, contin\u00faa aumentando, abastecida casi en su totalidad por combustibles f\u00f3siles, con un 6% del <strong>gas natural<\/strong> global y un 2% del <strong>carb\u00f3n<\/strong> global destinado a la producci\u00f3n de hidr\u00f3geno.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - demanda mundial hidrogeno puro' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-demanda-mundial-hidrogeno-puro.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-demanda-mundial-hidrogeno-puro.png' alt='AleaSoft - demanda mundial hidrogeno puro' width='740'\/><\/a><span style='font-size: small;'>Fuente: Elaborado por AleaSoft con datos de la IEA.<\/span><\/div>\n<p>El n\u00famero de pa\u00edses con pol\u00edticas que apoyan directamente la inversi\u00f3n en tecnolog\u00edas de hidr\u00f3geno est\u00e1 aumentando, junto con el n\u00famero de sectores a los que se dirigen. Hay alrededor de 50 objetivos, mandatos e incentivos de pol\u00edticas vigentes hoy que apoyan directamente el hidr\u00f3geno, la mayor\u00eda de ellos enfocados al sector del transporte.<\/p>\n<h3 style=\"font-size: 12pt;\">Producci\u00f3n de hidr\u00f3geno<\/h3>\n<p>Casi la totalidad del hidr\u00f3geno actual se produce a partir de hidrocarburos como el gas natural y el carb\u00f3n. Como consecuencia, la producci\u00f3n de hidr\u00f3geno es responsable de la emisi\u00f3n de alrededor de 830 millones de toneladas de di\u00f3xido de carbono por a\u00f1o, equivalente a las emisiones de CO<sub>2<\/sub> del Reino Unido y Francia combinadas.<\/p>\n<p>Sin embargo, existe una alternativa no contaminante, el llamado <strong>hidr\u00f3geno verde<\/strong>. Se trata del hidr\u00f3geno obtenido a trav\u00e9s de la electr\u00f3lisis del agua. Para este proceso se requiere electricidad, por lo&nbsp;que, si se utiliza la generaci\u00f3n de una fuente renovable, se habr\u00e1 obtenido hidr\u00f3geno sin emisiones en el proceso.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - hidrogeno verde electrolisis' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-hidrogeno-verde-electrolisis.gif'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-hidrogeno-verde-electrolisis.gif' alt='AleaSoft - hidrogeno verde electrolisis' width='740'\/><\/a><span style='font-size: small;'>Obtenci\u00f3n de hidr\u00f3geno verde por electr\u00f3lisis de agua a partir de fuentes de energ\u00eda renovable.<\/span><\/div><br \/>\n<span style=\"font-size: xx-small;\">Fuente: Wood Mackenzie<\/span><\/p>\n<p>Con la disminuci\u00f3n de los costes de la electricidad renovable, en particular de la energ\u00eda solar <strong>fotovoltaica<\/strong> y la <strong>e\u00f3lica<\/strong>, el inter\u00e9s por el hidr\u00f3geno verde est\u00e1 creciendo y se han realizado varios proyectos de demostraci\u00f3n en los \u00faltimos a\u00f1os. Sin embargo, el desaf\u00edo no es peque\u00f1o. Migrar toda la producci\u00f3n de hidr\u00f3geno actual representar\u00eda una <strong>demanda de electricidad<\/strong> de 3600&nbsp;TWh, m\u00e1s que la generaci\u00f3n de electricidad anual de toda la Uni\u00f3n Europea.<\/p>\n<p>La construcci\u00f3n de electrolizadores en ubicaciones con buenas condiciones de recursos renovables podr\u00eda convertirse en una opci\u00f3n de suministro de bajo coste para el hidr\u00f3geno, incluso despu\u00e9s de tener en cuenta los costes de transmisi\u00f3n y distribuci\u00f3n del transporte de hidr\u00f3geno desde ubicaciones renovables, a menudo remotas, a los usuarios finales.<\/p>\n<h3 style=\"font-size: 12pt;\">Producci\u00f3n de electricidad con hidr\u00f3geno<\/h3>\n<p>Para la obtenci\u00f3n de electricidad a partir del hidr\u00f3geno se realiza precisamente la reacci\u00f3n inversa que para la obtenci\u00f3n de hidr\u00f3geno. En este caso se hace reaccionar con ox\u00edgeno, obteniendo electricidad y agua. Al dispositivo encargado de realizar esta reacci\u00f3n se le llama <strong>pila de combustible<\/strong>. Una de las primeras aplicaciones pr\u00e1cticas de las pilas de combustible fue en <a style=\"color: #0047c8;\" href=\"https:\/\/aleasoft.com\/es\/papel-hidrogeno-carrera-espacial-transicion-energetica\/\">veh\u00edculos espaciales, donde adem\u00e1s del suministro el\u00e9ctrico, el agua resultante puede usarse por los astronautas para beber, o para refrigerar los sistemas de la nave<\/a><\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - pila combustible' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-pila-combustible.gif'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-pila-combustible.gif' alt='AleaSoft - pila combustible' width='740'\/><\/a><span style='font-size: small;'>Principio de funcionamiento de una pila de combustible de hidr\u00f3geno.<\/span><\/div><br \/>\n<span style=\"font-size: xx-small;\">Fuente: geek.com<\/span><\/p>\n<p>De esta forma, la generaci\u00f3n de electricidad con pilas de combustible a partir de hidr\u00f3geno es 100% limpia, y adem\u00e1s como subproducto se genera agua potable.<\/p>\n<h3 style=\"font-size: 12pt;\">El hidr\u00f3geno en la gesti\u00f3n de las energ\u00edas renovables<\/h3>\n<p>Una de las principales limitaciones que tienen las <strong>fuentes de energ\u00edas renovables<\/strong> es que su generaci\u00f3n depende de variables meteorol\u00f3gicas que tienen un comportamiento no gestionable. La generaci\u00f3n <strong>e\u00f3lica<\/strong> depende de la intensidad del viento en las localizaciones de los parques, que es una variable de gran aleatoriedad. La generaci\u00f3n <strong>fotovoltaica<\/strong> depende de los perfiles de radiaci\u00f3n solar. Eso conduce a que estas fuentes de energ\u00eda no puedan garantizar una determinada producci\u00f3n en un determinado momento, sino que alternar\u00e1n periodos de alta y de baja producci\u00f3n dependiendo de las condiciones meteorol\u00f3gicas de cada instante.<\/p>\n<a href='https:\/\/aleasoft.com\/es\/casos-previsiones\/ppa-y-sinergias\/' class='alea-banner-link' data-alea-gtm-event-category='banner-horizontal' data-alea-gtm-event-label='ppa'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/banners_ppa_es.jpg' alt='Oferta de previsiones de precios a largo plazo para PPA' style=''\/><\/a>\n<p>Una forma de aprovechar mejor los picos de alta generaci\u00f3n de electricidad de estas fuentes renovables, es utilizar el excedente para producir hidr\u00f3geno. Luego, el hidr\u00f3geno producido podr\u00eda venderse directamente o emplearse para generar electricidad en el momento en que la producci\u00f3n de la fuente renovable sea escasa.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - costo produccion hidrogeno fotovoltaica eolica renovables' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-costo-produccion-hidrogeno-fotovoltaica-eolica-renovables.jpg'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-costo-produccion-hidrogeno-fotovoltaica-eolica-renovables.jpg' alt='AleaSoft - costo produccion hidrogeno fotovoltaica eolica renovables' width='740'\/><\/a><span style='font-size: small;'>Coste del hidr\u00f3geno creado con energ\u00edas fotovoltaica y e\u00f3lica a largo plazo<\/span><\/div><br \/>\n<span style=\"font-size: xx-small;\">Fuente: IEA<\/span><\/p>\n<p>Es en este sentido en el que la generaci\u00f3n de hidr\u00f3geno representar\u00eda el elemento regulador del <strong>equilibrio en el precio del mercado el\u00e9ctrico<\/strong>. En un escenario de mucha producci\u00f3n renovable, ya sea e\u00f3lica, fotovoltaica o de otra fuente, el precio m\u00ednimo del mercado lo marcar\u00eda el valor a partir del cual ser\u00eda m\u00e1s rentable utilizar la electricidad para producir hidr\u00f3geno. <a style=\"color: #0047c8;\" href=\"https:\/\/aleasoft.com\/es\/entrevista-energias-renovables-antonio-delgado-rigal-director-general-aleasoft\/\">Una bajada de precio implicar\u00eda la producci\u00f3n masiva de hidr\u00f3geno, lo cual representar\u00eda un incremento en la demanda<\/a> y finalmente se llegar\u00eda a un equilibrio de mercado.<\/p>\n<h3 style=\"font-size: 12pt;\">El hidr\u00f3geno como forma de almacenamiento de energ\u00eda<\/h3>\n<p>El almacenamiento de la energ\u00eda es uno de los principales retos que enfrentar\u00e1 el sector en los pr\u00f3ximos a\u00f1os. Las tecnolog\u00edas de bater\u00edas han evolucionado mucho, pero la cuesti\u00f3n del almacenamiento a largo plazo no la resuelven a\u00fan. Es este escenario donde el hidr\u00f3geno podr\u00eda ser de gran utilidad. No solo por su capacidad de almacenar energ\u00eda por largos per\u00edodos de tiempo, sino tambi\u00e9n porque ser\u00e1 mucho m\u00e1s f\u00e1cil de manejar, dado que su peso ser\u00e1 menor, porque la densidad de energ\u00eda de los tanques de hidr\u00f3geno comprimido es superior a las de las bater\u00edas de litio-ion.<\/p>\n<h3 style=\"font-size: 12pt;\">El hidr\u00f3geno en el sector del transporte<\/h3>\n<p>El sector del transporte es probablemente el \u00e1rea donde el hidr\u00f3geno podr\u00e1 imponerse de forma m\u00e1s efectiva. Los coches el\u00e9ctricos de celda de combustible de hidr\u00f3geno (FCEV) reducir\u00edan la contaminaci\u00f3n del aire local porque, al igual que los coches el\u00e9ctricos de bater\u00eda (BEV), tienen cero emisiones de gases contaminantes.<\/p>\n<p>Ya existen coches en el mercado que utilizan esta tecnolog\u00eda y tienen prestaciones similares e incluso superiores a varios coches a bater\u00edas. El aspecto en el que el coche de hidr\u00f3geno s\u00ed no tendr\u00e1 competencia es en el repostaje. Reabastecer a un coche de hidr\u00f3geno es mucho m\u00e1s r\u00e1pido que recargar un coche a bater\u00edas.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - coche electrico hidrogeno pila combustible espanna' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-coche-electrico-hidrogeno-pila-combustible-espanna.jpg'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-coche-electrico-hidrogeno-pila-combustible-espanna.jpg' alt='AleaSoft - coche electrico hidrogeno pila combustible espanna' width='740'\/><\/a><span style='font-size: small;'>Primer veh\u00edculo de pila de hidr\u00f3geno matriculado en Espa\u00f1a. Hyundai Nexo.<\/span><\/div><br \/>\n<span style=\"font-size: xx-small;\">Fuente: CNH2<\/span><\/p>\n<p>Pero el campo de actuaci\u00f3n del hidr\u00f3geno no se resume a los turismos. En veh\u00edculos de mayor tama\u00f1o como autobuses o incluso en aviones, la alternativa el\u00e9ctrica con bater\u00edas muchas veces se descarta por el peso que implican las bater\u00edas. El hidr\u00f3geno representa una forma mucho m\u00e1s ligera de transportar la capacidad de alimentar un motor el\u00e9ctrico. En junio de 2019 las empresas europeas que forman el Consorcio H2Bus se unieron con el objetivo de trabajar en conjunto para desplegar una flota de 1000 autobuses el\u00e9ctricos de celda de combustible que se incorporar\u00e1n a las flotas de varios gestores europeos de transporte. Adem\u00e1s, instalar\u00e1n, en cada una de las ciudades europeas donde operen, la infraestructura de recarga de hidr\u00f3geno necesaria para hacerlos competitivos comercialmente.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - autobus hidrogeno pila combustible londres' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-autobus-hidrogeno-pila-combustible-londres.jpg'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-aleasoft-autobus-hidrogeno-pila-combustible-londres.jpg' alt='AleaSoft - autobus hidrogeno pila combustible londres' width='740'\/><\/a><span style='font-size: small;'>Autob\u00fas de pila de combustible de hidr\u00f3geno en Londres.<\/span><\/div><br \/>\n<span style=\"font-size: xx-small;\">Fuente: hibridosyelectricos.com<\/span><\/p>\n<p>El hidr\u00f3geno adem\u00e1s se puede convertir en combustibles a base de hidr\u00f3geno, incluidos metano sint\u00e9tico, metanol, amon\u00edaco y combustibles l\u00edquidos sint\u00e9ticos, que tienen una gama de usos potenciales de transporte.<\/p>\n<h3 style=\"font-size: 12pt;\">La revoluci\u00f3n del hidr\u00f3geno<\/h3>\n<p>El hidr\u00f3geno verde es el combustible del futuro. La capacidad de emplear un combustible con una huella de CO<sub>2<\/sub> nula representa una revoluci\u00f3n en el sector de la energ\u00eda y el transporte. La gasolina, el gas, el carb\u00f3n y todo el resto de combustibles ser\u00e1n desplazados paulatinamente por el hidr\u00f3geno. Desde el uso industrial hasta el dom\u00e9stico, el camino a seguir es la utilizaci\u00f3n del hidr\u00f3geno como combustible principal. Adem\u00e1s, como ya se mencion\u00f3, en \u00faltima instancia ser\u00e1 el elemento regulador del equilibrio del mercado el\u00e9ctrico.<\/p>\n<p><strong>Fuente: AleaSoft Energy Forecasting<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 21 de enero de 2020. El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568],"tags":[],"class_list":["post-78216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El hidr\u00f3geno verde es el combustible del futuro - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El hidr\u00f3geno verde es el combustible del futuro\" \/>\n<meta property=\"og:description\" content=\"El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T10:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1394\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"El hidr\u00f3geno verde es el combustible del futuro\",\"datePublished\":\"2020-01-21T23:00:00+00:00\",\"dateModified\":\"2020-06-09T10:34:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/\"},\"wordCount\":1639,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/\",\"name\":\"El hidr\u00f3geno verde es el combustible del futuro - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg\",\"datePublished\":\"2020-01-21T23:00:00+00:00\",\"dateModified\":\"2020-06-09T10:34:55+00:00\",\"description\":\"El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg\",\"width\":1394,\"height\":511},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/hidrogeno-verde-combustible-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El hidr\u00f3geno verde es el combustible del futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El hidr\u00f3geno verde es el combustible del futuro - AleaSoft Energy Forecasting","description":"El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/","og_locale":"es_ES","og_type":"article","og_title":"El hidr\u00f3geno verde es el combustible del futuro","og_description":"El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.","og_url":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2020-01-21T23:00:00+00:00","article_modified_time":"2020-06-09T10:34:55+00:00","og_image":[{"width":1394,"height":511,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg","type":"image\/jpeg"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"El hidr\u00f3geno verde es el combustible del futuro","datePublished":"2020-01-21T23:00:00+00:00","dateModified":"2020-06-09T10:34:55+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/"},"wordCount":1639,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/","url":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/","name":"El hidr\u00f3geno verde es el combustible del futuro - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg","datePublished":"2020-01-21T23:00:00+00:00","dateModified":"2020-06-09T10:34:55+00:00","description":"El hidr\u00f3geno ser\u00e1 el combustible del futuro y paso a paso sustituir\u00e1 a todos los combustibles f\u00f3siles actuales. En AleaSoft se ha realizado un an\u00e1lisis de la repercusi\u00f3n del hidr\u00f3geno en el sector de la energ\u00eda como factor clave en la transici\u00f3n ecol\u00f3gica y un resumen de la utilizaci\u00f3n presente y futura de este gas en varios sectores de la econom\u00eda.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/20200121-AleaSoft-hydrogen-production-cost-photovoltaic-wind-renewable-energy-1.jpg","width":1394,"height":511},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/es\/hidrogeno-verde-combustible-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/es\/"},{"@type":"ListItem","position":2,"name":"El hidr\u00f3geno verde es el combustible del futuro"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/78216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/comments?post=78216"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/posts\/78216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media\/80470"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/media?parent=78216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/categories?post=78216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/es\/wp-json\/wp\/v2\/tags?post=78216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}