{"id":130527,"date":"2022-10-24T10:58:24","date_gmt":"2022-10-24T08:58:24","guid":{"rendered":"https:\/\/aleasoft.com\/?p=130527"},"modified":"2022-10-25T04:53:25","modified_gmt":"2022-10-25T02:53:25","slug":"le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/","title":{"rendered":"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 24 octobre 2022. Le plafond de 180 \u20ac\/MWh sur les revenus de la production d&rsquo;\u00e9lectricit\u00e9 avec des technologies inframarginales \u00e9tabli par l&rsquo;Union europ\u00e9enne affectera les contrats PPA sign\u00e9s par les centrales d&rsquo;\u00e9nergie renouvelable. Bien que, dans le cas de l&rsquo;Espagne, cette mesure devrait \u00eatre de peu d&rsquo;importance tant que le m\u00e9canisme de r\u00e9duction reste en vigueur.<\/strong><\/p>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/'>Nouvelle en anglais<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 24 octobre 2022. Le plafond de 180 \u20ac\/MWh sur les revenus de la production d&rsquo;\u00e9lectricit\u00e9 avec des technologies inframarginales \u00e9tabli par l&rsquo;Union europ\u00e9enne affectera les contrats PPA sign\u00e9s par les centrales d&rsquo;\u00e9nergie renouvelable. Bien que, dans le cas de l&rsquo;Espagne, cette mesure devrait \u00eatre de peu d&rsquo;importance tant que le m\u00e9canisme de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":130489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-130527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA - AleaSoft Energy Forecasting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA\" \/>\n<meta property=\"og:description\" content=\"AleaSoft Energy Forecasting, 24 octobre 2022. Le plafond de 180 \u20ac\/MWh sur les revenus de la production d&rsquo;\u00e9lectricit\u00e9 avec des technologies inframarginales \u00e9tabli par l&rsquo;Union europ\u00e9enne affectera les contrats PPA sign\u00e9s par les centrales d&rsquo;\u00e9nergie renouvelable. Bien que, dans le cas de l&rsquo;Espagne, cette mesure devrait \u00eatre de peu d&rsquo;importance tant que le m\u00e9canisme de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T08:58:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T02:53:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221024-AleaSoft-Eolica-paneles-solares.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\"},\"headline\":\"Le plafond europ\u00e9en de 180 \u20ac\\\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA\",\"datePublished\":\"2022-10-24T08:58:24+00:00\",\"dateModified\":\"2022-10-25T02:53:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/\"},\"wordCount\":78,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221024-AleaSoft-Eolica-paneles-solares.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/\",\"name\":\"Le plafond europ\u00e9en de 180 \u20ac\\\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221024-AleaSoft-Eolica-paneles-solares.jpg\",\"datePublished\":\"2022-10-24T08:58:24+00:00\",\"dateModified\":\"2022-10-25T02:53:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221024-AleaSoft-Eolica-paneles-solares.jpg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/20221024-AleaSoft-Eolica-paneles-solares.jpg\",\"width\":1200,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le plafond europ\u00e9en de 180 \u20ac\\\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA - AleaSoft Energy Forecasting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/","og_locale":"fr_FR","og_type":"article","og_title":"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA","og_description":"AleaSoft Energy Forecasting, 24 octobre 2022. Le plafond de 180 \u20ac\/MWh sur les revenus de la production d&rsquo;\u00e9lectricit\u00e9 avec des technologies inframarginales \u00e9tabli par l&rsquo;Union europ\u00e9enne affectera les contrats PPA sign\u00e9s par les centrales d&rsquo;\u00e9nergie renouvelable. Bien que, dans le cas de l&rsquo;Espagne, cette mesure devrait \u00eatre de peu d&rsquo;importance tant que le m\u00e9canisme de [&hellip;]","og_url":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2022-10-24T08:58:24+00:00","article_modified_time":"2022-10-25T02:53:25+00:00","og_image":[{"width":1200,"height":709,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221024-AleaSoft-Eolica-paneles-solares.jpg","type":"image\/jpeg"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"\u00c9crit par":"AleaSoft Energy Forecasting","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61"},"headline":"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA","datePublished":"2022-10-24T08:58:24+00:00","dateModified":"2022-10-25T02:53:25+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/"},"wordCount":78,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221024-AleaSoft-Eolica-paneles-solares.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/","url":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/","name":"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221024-AleaSoft-Eolica-paneles-solares.jpg","datePublished":"2022-10-24T08:58:24+00:00","dateModified":"2022-10-25T02:53:25+00:00","breadcrumb":{"@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221024-AleaSoft-Eolica-paneles-solares.jpg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/10\/20221024-AleaSoft-Eolica-paneles-solares.jpg","width":1200,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/fr\/le-plafond-europeen-de-180-e-mwh-pour-les-renouvelables-doit-etre-inclus-dans-les-ppa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/"},{"@type":"ListItem","position":2,"name":"Le plafond europ\u00e9en de 180 \u20ac\/MWh pour les renouvelables doit \u00eatre inclus dans les PPA"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"}}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/130527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/comments?post=130527"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/130527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media\/130489"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media?parent=130527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/categories?post=130527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/tags?post=130527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}