{"id":154550,"date":"2025-02-17T14:58:52","date_gmt":"2025-02-17T13:58:52","guid":{"rendered":"https:\/\/aleasoft.com\/?p=154550"},"modified":"2025-02-19T05:51:03","modified_gmt":"2025-02-19T04:51:03","slug":"marches-europeens-lelectricite-rise-exception-mibel-vent","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/fr\/marches-europeens-lelectricite-rise-exception-mibel-vent\/","title":{"rendered":"Les march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&rsquo;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&rsquo;\u00e9nergie \u00e9olienne."},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 17 f\u00e9vrier 2025. Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh. Toutefois, sur le march\u00e9 ib\u00e9rique, l&rsquo;augmentation de la production d&rsquo;\u00e9nergie \u00e9olienne et la diminution de la demande d&rsquo;\u00e9lectricit\u00e9 ont favoris\u00e9 la baisse des prix. Le march\u00e9 fran\u00e7ais a de nouveau battu le record de production d&rsquo;\u00e9nergie photovolta\u00efque pour une journ\u00e9e de f\u00e9vrier. Le lundi 10 f\u00e9vrier, les contrats \u00e0 terme de gaz TTF ont atteint leur valeur la plus \u00e9lev\u00e9e depuis d\u00e9but f\u00e9vrier 2023, au-dessus de 58 \u20ac\/MWh.<\/strong><\/p>\n<h2>Production d&rsquo;\u00e9nergie solaire photovolta\u00efque et \u00e9olienne<\/h2>\n<p>Au cours de la semaine du 10 f\u00e9vrier, la <strong>production d&rsquo;<\/strong> <strong>\u00e9nergie solaire photovolta\u00efque<\/strong> a diminu\u00e9 sur les principaux march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 par rapport \u00e0 la semaine pr\u00e9c\u00e9dente. Cette tendance \u00e0 la baisse fait suite \u00e0 deux semaines cons\u00e9cutives d&rsquo;augmentation de la production hebdomadaire d&rsquo;\u00e9nergie solaire photovolta\u00efque. Les march\u00e9s allemand et portugais ont enregistr\u00e9 les plus fortes baisses de production de cette technologie par rapport \u00e0 la premi\u00e8re semaine de f\u00e9vrier, respectivement 38 % et 17 %. Le march\u00e9 espagnol a enregistr\u00e9 la plus faible baisse, soit 0,4 %.<\/p>\n<p>Le march\u00e9 fran\u00e7ais a atteint un record historique de production d&rsquo;\u00e9nergie solaire photovolta\u00efque pour une journ\u00e9e de f\u00e9vrier, malgr\u00e9 une baisse de 2,8 % de la production hebdomadaire par rapport \u00e0 la semaine pr\u00e9c\u00e9dente. Le samedi 15 f\u00e9vrier, la production d&rsquo;\u00e9nergie solaire photovolta\u00efque en France a atteint 79 GWh, d\u00e9passant le pr\u00e9c\u00e9dent record de 68 GWh, enregistr\u00e9 le 3 f\u00e9vrier.<\/p>\n<p>Au cours de la semaine du 17 f\u00e9vrier, selon les <a href=\"https:\/\/aleasoft.com\/fr\/produits-et-services\/prevision-energie-solaire\/\">pr\u00e9visions de production solaire<\/a> d&rsquo;<strong>AleaSoft Energy Forecasting<\/strong>, la production solaire photovolta\u00efque augmentera en Espagne, en Allemagne et en Italie, inversant la tendance \u00e0 la baisse de la semaine pr\u00e9c\u00e9dente.<\/p>\n<p><div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Photovoltaic energy production electricity Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Photovoltaic-energy-production-electricity-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Photovoltaic-energy-production-electricity-Europe.png' alt='AleaSoft - Photovoltaic energy production electricity Europe' width='740'\/><\/a><span style='font-size: small;'>Source : Pr\u00e9par\u00e9 par AleaSoft Energy Forecasting \u00e0 partir des donn\u00e9es de ENTSO-E, RTE, REN, REE et TERNA.<\/span><\/div><br \/>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Solar photovoltaic production profile Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Solar-photovoltaic-production-profile-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Solar-photovoltaic-production-profile-Europe.png' alt='AleaSoft - Solar photovoltaic production profile Europe' width='740'\/><\/a><span style='font-size: small;'>Source : Pr\u00e9par\u00e9 par AleaSoft Energy Forecasting \u00e0 partir des donn\u00e9es de ENTSO-E, RTE, REN, REE et TERNA.<\/span><\/div><\/p>\n<p>Au cours de la semaine du 10 f\u00e9vrier, la <strong>production \u00e9olienne<\/strong> hebdomadaire a diminu\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens, poursuivant la tendance \u00e0 la baisse de la semaine pr\u00e9c\u00e9dente. Le march\u00e9 fran\u00e7ais a enregistr\u00e9 la plus forte baisse (23 %), tandis qu&rsquo;en Italie et en Allemagne, la production \u00e9olienne a chut\u00e9 de 13 % et 10 % respectivement. Les march\u00e9s de la p\u00e9ninsule ib\u00e9rique ont fait exception, la production d&rsquo;\u00e9nergie \u00e9olienne ayant augment\u00e9 de 40 % au Portugal et de 12 % en Espagne.<\/p>\n<p>Dans la semaine du 17 f\u00e9vrier, selon les <a href=\"https:\/\/aleasoft.com\/fr\/produits-et-services\/prevision-energie-solaire\/\">pr\u00e9visions de production d&rsquo;\u00e9nergie \u00e9olienne<\/a> d&rsquo;<strong>AleaSoft Energy Forecasting<\/strong>, la production d&rsquo;\u00e9nergie \u00e9olienne augmentera en France et en Espagne, mais diminuera en Allemagne, en Italie et au Portugal.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Wind energy production electricity Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Wind-energy-production-electricity-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Wind-energy-production-electricity-Europe.png' alt='AleaSoft - Wind energy production electricity Europe' width='740'\/><\/a><span style='font-size: small;'>Source : Pr\u00e9par\u00e9 par AleaSoft Energy Forecasting \u00e0 partir des donn\u00e9es de ENTSO-E, RTE, REN, REE et TERNA.<\/span><\/div>\n<h2>Demande d&rsquo;\u00e9lectricit\u00e9<\/h2>\n<p>Au cours de la semaine du 10 f\u00e9vrier, l&rsquo;\u00e9volution de la <strong>demande d&rsquo;\u00e9lectricit\u00e9 d&rsquo;<\/strong> une semaine \u00e0 l&rsquo;autre a montr\u00e9 une tendance h\u00e9t\u00e9rog\u00e8ne sur les principaux march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9, contrairement \u00e0 la tendance \u00e0 la hausse observ\u00e9e la semaine pr\u00e9c\u00e9dente. La Grande-Bretagne est arriv\u00e9e en t\u00eate des march\u00e9s o\u00f9 la demande a augment\u00e9, avec une hausse de 5,2 %. Elle est suivie par le march\u00e9 n\u00e9erlandais, o\u00f9 la demande a augment\u00e9 de 2,9 %. Les march\u00e9s belge et allemand ont enregistr\u00e9 des hausses respectives de 2,1 % et 1,4 %. Sur ces quatre march\u00e9s, la demande a augment\u00e9 pour la deuxi\u00e8me semaine cons\u00e9cutive. En revanche, les march\u00e9s fran\u00e7ais, espagnol, portugais et italien ont enregistr\u00e9 une baisse de la demande. Le march\u00e9 fran\u00e7ais a enregistr\u00e9 la plus forte baisse, 5,5 %, suivi par le march\u00e9 espagnol, o\u00f9 la baisse a \u00e9t\u00e9 de 3,9 %. Sur les march\u00e9s portugais et italien, la demande a baiss\u00e9 respectivement de 2,2% et de 0,7%. Dans le cas du Portugal, la tendance \u00e0 la baisse s&rsquo;est poursuivie pour la troisi\u00e8me semaine cons\u00e9cutive.<\/p>\n<p>Les variations de la demande au cours de la deuxi\u00e8me semaine de f\u00e9vrier sont en corr\u00e9lation avec l&rsquo;\u00e9volution des <strong>temp\u00e9ratures moyennes<\/strong>. Dans les pays o\u00f9 la demande a augment\u00e9, les temp\u00e9ratures moyennes ont baiss\u00e9 entre 0,3 \u00b0C et 2,2 \u00b0C. Dans les pays o\u00f9 la demande a diminu\u00e9, les temp\u00e9ratures moyennes ont augment\u00e9 de 0,9 \u00b0C \u00e0 2,8 \u00b0C.<\/p>\n<p>Pour la semaine du 17 f\u00e9vrier, selon les <a href=\"https:\/\/aleasoft.com\/fr\/services\/previsions-demande-energie-electrique\/\"><strong>pr\u00e9visions de demande<\/strong><\/a> d&rsquo; <strong>AleaSoft Energy Forecasting<\/strong>, la demande diminuera sur la plupart des grands march\u00e9s europ\u00e9ens, \u00e0 l&rsquo;exception du Portugal, o\u00f9 la demande augmentera.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Electricity demand European countries' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Electricity-demand-European-countries.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Electricity-demand-European-countries.png' alt='AleaSoft - Electricity demand European countries' width='740'\/><\/a><span style='font-size: small;'>Source : Pr\u00e9par\u00e9 par AleaSoft Energy Forecasting \u00e0 partir des donn\u00e9es de ENTSO-E, RTE, REN, REE, TERNA, National Grid et ELIA.<\/span><\/div>\n<h2>March\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9<\/h2>\n<p>Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix moyens sur la plupart des principaux march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont augment\u00e9 par rapport \u00e0 la semaine pr\u00e9c\u00e9dente. Les prix ont maintenu une tendance \u00e0 la hausse au cours des premiers jours de la semaine, mais ils ont baiss\u00e9 pendant le week-end, limitant l&rsquo;augmentation des moyennes hebdomadaires. L&rsquo;exception \u00e0 la hausse a \u00e9t\u00e9 le <strong>march\u00e9 MIBEL<\/strong> du Portugal et de l&rsquo;Espagne, avec des baisses de 4,7 % et 4,8 %, respectivement. Par ailleurs, le <strong>march\u00e9<\/strong> fran\u00e7ais <strong><\/strong> a enregistr\u00e9 la plus faible augmentation, soit 1,9 %, tandis que le <strong>march\u00e9 Nord Pool<\/strong> des pays nordiques a enregistr\u00e9 la plus forte augmentation de prix en pourcentage, soit 72 %. Sur les autres march\u00e9s analys\u00e9s par <strong>AleaSoft Energy Forecasting<\/strong>, les prix ont augment\u00e9 de 3,6 % sur le <strong>march\u00e9 IPEX<\/strong> en Italie et de 8,6 % sur le march\u00e9  aux Pays-Bas.<\/p>\n<p>Au cours de la semaine du 10 f\u00e9vrier, les moyennes hebdomadaires \u00e9taient sup\u00e9rieures \u00e0 140 \u20ac\/MWh sur la plupart des grands march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9. Les march\u00e9s nordique, portugais et espagnol ont fait exception, avec des moyennes respectives de 88,82 \u20ac\/MWh, 117,50 \u20ac\/MWh et 117,64 \u20ac\/MWh. Le march\u00e9 italien a atteint la moyenne hebdomadaire la plus \u00e9lev\u00e9e, soit 159,40 \u20ac\/MWh. Sur les autres march\u00e9s analys\u00e9s, les prix ont vari\u00e9 de 140,73 \u20ac\/MWh sur le march\u00e9 fran\u00e7ais \u00e0 149,72 \u20ac\/MWh sur le march\u00e9 belge.<\/p>\n<p>En ce qui concerne les prix journaliers, au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix sur la plupart des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 analys\u00e9s sont rest\u00e9s sup\u00e9rieurs \u00e0 115 \u20ac\/MWh. Les march\u00e9s nordique et ib\u00e9rique ont fait exception. Le march\u00e9 nordique a atteint un prix de 50,69 \u20ac\/MWh le 11 f\u00e9vrier, soit le prix le plus bas de la semaine sur les march\u00e9s analys\u00e9s. En revanche, les prix journaliers ont d\u00e9pass\u00e9 170 \u20ac\/MWh lors de certaines s\u00e9ances de la deuxi\u00e8me semaine de f\u00e9vrier sur les march\u00e9s allemand, italien et n\u00e9erlandais. Le march\u00e9 allemand a enregistr\u00e9 le prix le plus \u00e9lev\u00e9 de la semaine, 179,14 \u20ac\/MWh, le vendredi 14 f\u00e9vrier. Ce jour-l\u00e0, le march\u00e9 nordique a atteint un prix de 142,00 \u20ac\/MWh, le plus \u00e9lev\u00e9 depuis d\u00e9cembre 2022 sur ce march\u00e9.<\/p>\n<p>Dans la semaine du 10 f\u00e9vrier, la baisse de la production d&rsquo;\u00e9nergie solaire et \u00e9olienne, ainsi que l&rsquo;augmentation de la demande sur certains march\u00e9s tels que le <strong>march\u00e9 N2EX<\/strong> du Royaume-Uni et les march\u00e9s allemand, belge et n\u00e9erlandais, ont entra\u00een\u00e9 une hausse des prix sur le march\u00e9 europ\u00e9en de l&rsquo;\u00e9lectricit\u00e9. En outre, bien que les prix du gaz aient \u00e9t\u00e9 plus bas au cours de la seconde moiti\u00e9 de la semaine, le prix moyen hebdomadaire \u00e9tait l\u00e9g\u00e8rement sup\u00e9rieur \u00e0 celui de la semaine pr\u00e9c\u00e9dente. En revanche, la baisse de la demande et l&rsquo;augmentation de la production d&rsquo;\u00e9nergie \u00e9olienne dans la p\u00e9ninsule ib\u00e9rique ont entra\u00een\u00e9 une baisse des prix sur le march\u00e9 MIBEL.<br \/>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Solar Panels' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/pexels-fotovoltaica-eolica1-scaled.jpg'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/pexels-fotovoltaica-eolica1-scaled.jpg' alt='AleaSoft - Solar Panels' width='740'\/><\/a><\/div><\/p>\n<p>Les <a href=\"https:\/\/aleasoft.com\/fr\/services\/previsions-prix-energie\/\">pr\u00e9visions de prix<\/a> d&rsquo; <strong>AleaSoft Energy Forecasting <\/strong>indiquent qu&rsquo;au cours de la troisi\u00e8me semaine de f\u00e9vrier, les prix baisseront sur les march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9, sous l&rsquo;influence de l&rsquo;augmentation de la production d&rsquo;\u00e9nergie solaire et de la baisse de la demande sur la plupart des march\u00e9s. L&rsquo;augmentation de la production d&rsquo;\u00e9nergie \u00e9olienne en France et en Espagne contribuera \u00e9galement \u00e0 ces baisses.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - European electricity market prices' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png' alt='AleaSoft - European electricity market prices' width='740'\/><\/a><span style='font-size: small;'>Source : Pr\u00e9par\u00e9 par AleaSoft Energy Forecasting \u00e0 partir des donn\u00e9es de OMIE, , Nord Pool et GME.<\/span><\/div>\n<h2>Brent, carburants et CO<sub>2<\/sub><\/h2>\n<p>Les contrats \u00e0 terme sur le <strong>p\u00e9trole Brent<\/strong> pour le Front-Month sur le <strong>march\u00e9 ICE<\/strong> ont atteint leur prix de r\u00e8glement hebdomadaire maximum, 77,00 $\/bbl, le mardi 11 f\u00e9vrier. Selon les donn\u00e9es analys\u00e9es par <strong>AleaSoft Energy Forecasting<\/strong>, il s&rsquo;agit du prix le plus \u00e9lev\u00e9 depuis la fin du mois de janvier. Cependant, au cours des s\u00e9ances suivantes de la deuxi\u00e8me semaine du mois, les prix de r\u00e8glement ont baiss\u00e9. Le vendredi 14 f\u00e9vrier, ces contrats \u00e0 terme ont enregistr\u00e9 leur prix de r\u00e8glement hebdomadaire minimum, 74,74 dollars le baril, soit 0,1 % de plus que le vendredi pr\u00e9c\u00e9dent.<\/p>\n<p>Les inqui\u00e9tudes concernant l&rsquo;impact des politiques tarifaires am\u00e9ricaines sur la demande mondiale de p\u00e9trole ont persist\u00e9 au cours de la deuxi\u00e8me semaine de f\u00e9vrier. En outre, les r\u00e9serves de p\u00e9trole am\u00e9ricaines ont augment\u00e9. Ces facteurs ont exerc\u00e9 une pression \u00e0 la baisse sur les prix \u00e0 terme du p\u00e9trole Brent. Ces prix ont \u00e9galement \u00e9t\u00e9 affect\u00e9s par l&rsquo;annonce de n\u00e9gociations de paix potentielles pour l&rsquo;Ukraine, qui pourraient entra\u00eener une augmentation de l&rsquo;offre de p\u00e9trole russe.<\/p>\n<p>Quant aux contrats \u00e0 terme sur le <strong>gaz TTF<\/strong> sur le march\u00e9 ICE pour le premier mois, ils ont commenc\u00e9 la semaine en poursuivant la tendance \u00e0 la hausse de la semaine pr\u00e9c\u00e9dente. Le lundi 10 f\u00e9vrier, ces contrats \u00e0 terme ont atteint leur prix de r\u00e8glement hebdomadaire maximum, soit 58,04 \u20ac\/MWh. Selon les donn\u00e9es analys\u00e9es par <strong>AleaSoft Energy Forecasting<\/strong>, il s&rsquo;agit du prix le plus \u00e9lev\u00e9 depuis le 7 f\u00e9vrier 2023. Au cours des autres s\u00e9ances de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont baiss\u00e9. Par cons\u00e9quent, le vendredi 14 f\u00e9vrier, ces contrats \u00e0 terme ont enregistr\u00e9 leur prix de r\u00e8glement hebdomadaire minimum, 50,68 \u20ac\/MWh. Ce prix \u00e9tait inf\u00e9rieur de 9,0 % \u00e0 celui du vendredi pr\u00e9c\u00e9dent.<\/p>\n<p>Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, des temp\u00e9ratures plus \u00e9lev\u00e9es et une augmentation de l&rsquo;offre de gaz naturel liqu\u00e9fi\u00e9 ont contribu\u00e9 \u00e0 ralentir le d\u00e9clin des r\u00e9serves de gaz europ\u00e9ennes. La proposition de l&rsquo;Allemagne, de la France et de l&rsquo;Italie d&rsquo;assouplir les exigences en mati\u00e8re de stockage de gaz pour l&rsquo;hiver prochain a \u00e9galement exerc\u00e9 une pression \u00e0 la baisse sur les prix \u00e0 terme du gaz TTF. En outre, la fin possible de la guerre en Ukraine favoriserait une augmentation de l&rsquo;offre de gaz russe, de sorte que l&rsquo;annonce de conversations entre les pr\u00e9sidents russe et am\u00e9ricain a \u00e9galement contribu\u00e9 \u00e0 la baisse des prix.<\/p>\n<p>Les contrats \u00e0 terme sur les <strong>quotas d&rsquo;\u00e9mission de CO<sub>2<\/sub><\/strong> sur le <strong>march\u00e9 EEX<\/strong> pour le contrat de r\u00e9f\u00e9rence de d\u00e9cembre 2025 ont atteint leur prix de r\u00e8glement hebdomadaire maximum, 82,94 \u20ac\/t, le lundi 10 f\u00e9vrier. Selon les donn\u00e9es analys\u00e9es par <strong>AleaSoft Energy Forecasting<\/strong>, il s&rsquo;agit du prix le plus \u00e9lev\u00e9 de la premi\u00e8re quinzaine de f\u00e9vrier. Par la suite, les prix ont baiss\u00e9 jusqu&rsquo;au jeudi 13 f\u00e9vrier. Ce jour-l\u00e0, ces contrats \u00e0 terme ont enregistr\u00e9 leur prix de r\u00e8glement hebdomadaire minimum, soit 78,05 \u20ac\/t. La derni\u00e8re s\u00e9ance de la semaine a \u00e9t\u00e9 marqu\u00e9e par une l\u00e9g\u00e8re reprise. Par cons\u00e9quent, le vendredi 14 f\u00e9vrier, le prix de r\u00e8glement \u00e9tait de 79,75 \u20ac\/t, soit 3,1 % de moins que le vendredi pr\u00e9c\u00e9dent.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Prices gas coal Brent oil CO2' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png' alt='AleaSoft - Prices gas coal Brent oil CO2' width='740'\/><\/a><span style='font-size: small;'>Source : Pr\u00e9par\u00e9 par AleaSoft Energy Forecasting \u00e0 partir des donn\u00e9es de ICE et EEX.<\/span><\/div>\n<h2>Analyse d&rsquo;AleaSoft Energy Forecasting sur les perspectives des march\u00e9s de l&rsquo;\u00e9nergie et des batteries en Europe<\/h2>\n<p>Le jeudi 13 f\u00e9vrier, <strong>AleaSoft Energy Forecasting<\/strong> a organis\u00e9 le <a href=\"https:\/\/aleasoft.com\/webinars\/markets-storage-february-2025\/\">52\u00e8me webinaire<\/a> de sa <a href=\"https:\/\/aleasoft.com\/fr\/webinars\/\">s\u00e9rie de webinaires mensuels<\/a>. \u00c0 cette occasion, l&rsquo;orateur invit\u00e9 \u00e9tait Tom\u00e1s Garc\u00eda, Senior Director, Energy &amp; Infrastructure Advisory chez <strong>JLL<\/strong>. Outre l&rsquo;\u00e9volution et les perspectives des march\u00e9s europ\u00e9ens de l&rsquo;\u00e9nergie, le webinaire a analys\u00e9 les \u00ab\u00a0revenus contractuels\u00a0\u00bb pour les projets <strong>BESS<\/strong>, par le biais du <strong>march\u00e9 des capacit\u00e9s<\/strong> et des <strong>accords d&rsquo;optimisation<\/strong>.<\/p>\n<p>Source: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 17 f\u00e9vrier 2025. Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh. Toutefois, sur le march\u00e9 ib\u00e9rique, l&rsquo;augmentation de la production d&rsquo;\u00e9nergie \u00e9olienne et la diminution de la demande d&rsquo;\u00e9lectricit\u00e9 ont favoris\u00e9 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":154521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[7575,7578,7577,7580,7579,7581,7576],"class_list":["post-154550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-demande","tag-marches","tag-photovoltaique","tag-prix-brent","tag-prix-co2","tag-prix-gaz","tag-vent"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&#039;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&#039;\u00e9nergie \u00e9olienne. - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&#039;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&#039;\u00e9nergie \u00e9olienne.\" \/>\n<meta property=\"og:description\" content=\"Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T13:58:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T04:51:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\"},\"headline\":\"Les march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&rsquo;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&rsquo;\u00e9nergie \u00e9olienne.\",\"datePublished\":\"2025-02-17T13:58:52+00:00\",\"dateModified\":\"2025-02-19T04:51:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/\"},\"wordCount\":2181,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250217-AleaSoft-European-electricity-market-prices.png\",\"keywords\":[\"Demande\",\"March\u00e9s\",\"Photovolta\u00efque\",\"Prix Brent\",\"Prix CO2\",\"Prix gaz\",\"Vent\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/\",\"name\":\"Les march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l'exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l'\u00e9nergie \u00e9olienne. - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250217-AleaSoft-European-electricity-market-prices.png\",\"datePublished\":\"2025-02-17T13:58:52+00:00\",\"dateModified\":\"2025-02-19T04:51:03+00:00\",\"description\":\"Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\\\/MWh.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250217-AleaSoft-European-electricity-market-prices.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250217-AleaSoft-European-electricity-market-prices.png\",\"width\":2282,\"height\":1589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/marches-europeens-lelectricite-rise-exception-mibel-vent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&rsquo;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&rsquo;\u00e9nergie \u00e9olienne.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l'exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l'\u00e9nergie \u00e9olienne. - AleaSoft Energy Forecasting","description":"Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/","og_locale":"fr_FR","og_type":"article","og_title":"Les march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l'exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l'\u00e9nergie \u00e9olienne.","og_description":"Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh.","og_url":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2025-02-17T13:58:52+00:00","article_modified_time":"2025-02-19T04:51:03+00:00","og_image":[{"width":2282,"height":1589,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"\u00c9crit par":"AleaSoft Energy Forecasting","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/fr\/marches-europeens-lelectricite-rise-exception-mibel-vent\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61"},"headline":"Les march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&rsquo;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&rsquo;\u00e9nergie \u00e9olienne.","datePublished":"2025-02-17T13:58:52+00:00","dateModified":"2025-02-19T04:51:03+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/marches-europeens-lelectricite-rise-exception-mibel-vent\/"},"wordCount":2181,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png","keywords":["Demande","March\u00e9s","Photovolta\u00efque","Prix Brent","Prix CO2","Prix gaz","Vent"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/fr\/marches-europeens-lelectricite-rise-exception-mibel-vent\/","url":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/","name":"Les march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l'exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l'\u00e9nergie \u00e9olienne. - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png","datePublished":"2025-02-17T13:58:52+00:00","dateModified":"2025-02-19T04:51:03+00:00","description":"Au cours de la deuxi\u00e8me semaine de f\u00e9vrier, les prix ont augment\u00e9 sur la plupart des grands march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 et les moyennes hebdomadaires ont d\u00e9pass\u00e9 140 \u20ac\/MWh.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/02\/20250217-AleaSoft-European-electricity-market-prices.png","width":2282,"height":1589},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/marches-europeens-lelectricite-rise-exception-mibel-vent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont continu\u00e9 \u00e0 augmenter au cours de la deuxi\u00e8me semaine de f\u00e9vrier, \u00e0 l&rsquo;exception du march\u00e9 ib\u00e9rique gr\u00e2ce \u00e0 l&rsquo;\u00e9nergie \u00e9olienne."}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"}}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/154550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/comments?post=154550"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/154550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media\/154521"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media?parent=154550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/categories?post=154550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/tags?post=154550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}