{"id":78648,"date":"2019-10-21T00:00:00","date_gmt":"2019-10-20T22:00:00","guid":{"rendered":"https:\/\/aleasoft.com\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/"},"modified":"2022-05-18T16:39:46","modified_gmt":"2022-05-18T14:39:46","slug":"prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/","title":{"rendered":"Les prix de la plupart des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 augmentent en raison d&rsquo;une production d&rsquo;\u00e9nergie renouvelable inf\u00e9rieure"},"content":{"rendered":"<p><strong>AleaSoft, 21 octobre 2019. Les prix de la plupart des march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d&rsquo;\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l&rsquo;analyse effectu\u00e9e par AleaSoft. Dans le cas du march\u00e9 du MIBEL en Espagne et au Portugal, l\u2019augmentation de la production d\u2019\u00e9nergie \u00e9olienne a favoris\u00e9 la baisse des prix. Les contrats \u00e0 terme sur le Brent, le gaz, le charbon et le CO2 ont cl\u00f4tur\u00e9 la semaine sur une tendance \u00e0 la baisse.<\/strong><\/p>\n<p><a href='https:\/\/aleasoft.com\/fr\/cas-previsions\/services-ppa-synergies\/' class='alea-banner-link' data-alea-gtm-event-category='banner-horizontal' data-alea-gtm-event-label='ppa'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/banners_ppa_fr.jpg' alt='Offre de pr\u00e9visions de prix \u00e0 long terme pour PPA' style=''\/><\/a><br \/>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/'>Nouvelle en anglais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 21 octobre 2019. Les prix de la plupart des march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d&rsquo;\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l&rsquo;analyse effectu\u00e9e par AleaSoft. Dans le cas du march\u00e9 du MIBEL en Espagne et au Portugal, l\u2019augmentation de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":72721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[628],"class_list":["post-78648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les prix de la plupart des march\u00e9s de l&#039;\u00e9lectricit\u00e9 augmentent en raison d&#039;une production d&#039;\u00e9nergie renouvelable inf\u00e9rieure - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Les prix de la plupart des march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d&#039;\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l&#039;analyse effectu\u00e9e par AleaSoft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les prix de la plupart des march\u00e9s de l&#039;\u00e9lectricit\u00e9 augmentent en raison d&#039;une production d&#039;\u00e9nergie renouvelable inf\u00e9rieure\" \/>\n<meta property=\"og:description\" content=\"Les prix de la plupart des march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d&#039;\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l&#039;analyse effectu\u00e9e par AleaSoft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-20T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-18T14:39:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/10\/20191021-aleasoft-precios-mercados-europeos-electricidad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2303\" \/>\n\t<meta property=\"og:image:height\" content=\"1606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Les prix de la plupart des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 augmentent en raison d&rsquo;une production d&rsquo;\u00e9nergie renouvelable inf\u00e9rieure\",\"datePublished\":\"2019-10-20T22:00:00+00:00\",\"dateModified\":\"2022-05-18T14:39:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/\"},\"wordCount\":119,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-aleasoft-precios-mercados-europeos-electricidad.png\",\"keywords\":[\"nouvelles\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/\",\"name\":\"Les prix de la plupart des march\u00e9s de l'\u00e9lectricit\u00e9 augmentent en raison d'une production d'\u00e9nergie renouvelable inf\u00e9rieure - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-aleasoft-precios-mercados-europeos-electricidad.png\",\"datePublished\":\"2019-10-20T22:00:00+00:00\",\"dateModified\":\"2022-05-18T14:39:46+00:00\",\"description\":\"Les prix de la plupart des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d'\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l'analyse effectu\u00e9e par AleaSoft.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-aleasoft-precios-mercados-europeos-electricidad.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191021-aleasoft-precios-mercados-europeos-electricidad.png\",\"width\":2303,\"height\":1606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les prix de la plupart des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 augmentent en raison d&rsquo;une production d&rsquo;\u00e9nergie renouvelable inf\u00e9rieure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les prix de la plupart des march\u00e9s de l'\u00e9lectricit\u00e9 augmentent en raison d'une production d'\u00e9nergie renouvelable inf\u00e9rieure - AleaSoft Energy Forecasting","description":"Les prix de la plupart des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d'\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l'analyse effectu\u00e9e par AleaSoft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/","og_locale":"fr_FR","og_type":"article","og_title":"Les prix de la plupart des march\u00e9s de l'\u00e9lectricit\u00e9 augmentent en raison d'une production d'\u00e9nergie renouvelable inf\u00e9rieure","og_description":"Les prix de la plupart des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d'\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l'analyse effectu\u00e9e par AleaSoft.","og_url":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2019-10-20T22:00:00+00:00","article_modified_time":"2022-05-18T14:39:46+00:00","og_image":[{"width":2303,"height":1606,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/10\/20191021-aleasoft-precios-mercados-europeos-electricidad.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"\u00c9crit par":"AleaSoft Energy Forecasting","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/fr\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Les prix de la plupart des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 augmentent en raison d&rsquo;une production d&rsquo;\u00e9nergie renouvelable inf\u00e9rieure","datePublished":"2019-10-20T22:00:00+00:00","dateModified":"2022-05-18T14:39:46+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/"},"wordCount":119,"publisher":{"@id":"https:\/\/aleasoft.com\/fr\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/10\/20191021-aleasoft-precios-mercados-europeos-electricidad.png","keywords":["nouvelles"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/","url":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/","name":"Les prix de la plupart des march\u00e9s de l'\u00e9lectricit\u00e9 augmentent en raison d'une production d'\u00e9nergie renouvelable inf\u00e9rieure - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/10\/20191021-aleasoft-precios-mercados-europeos-electricidad.png","datePublished":"2019-10-20T22:00:00+00:00","dateModified":"2022-05-18T14:39:46+00:00","description":"Les prix de la plupart des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 ont augment\u00e9 la semaine derni\u00e8re en raison de la baisse de la production d'\u00e9nergie utilisant des technologies renouvelables, \u00e9oliennes et solaires, selon l'analyse effectu\u00e9e par AleaSoft.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/10\/20191021-aleasoft-precios-mercados-europeos-electricidad.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/10\/20191021-aleasoft-precios-mercados-europeos-electricidad.png","width":2303,"height":1606},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/fr\/prix-plupart-marches-electricite-augmentent-raison-production-energie-renouvelable-inferieure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les prix de la plupart des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 augmentent en raison d&rsquo;une production d&rsquo;\u00e9nergie renouvelable inf\u00e9rieure"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/fr\/#website","url":"https:\/\/aleasoft.com\/fr\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/fr\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/fr\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/78648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/comments?post=78648"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/78648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media\/72721"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media?parent=78648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/categories?post=78648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/tags?post=78648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}