{"id":78656,"date":"2019-11-04T00:00:00","date_gmt":"2019-11-03T23:00:00","guid":{"rendered":"https:\/\/aleasoft.com\/baisse-prix-marches-europeens-electricite-octobre\/"},"modified":"2020-02-12T19:02:48","modified_gmt":"2020-02-12T18:02:48","slug":"baisse-prix-marches-europeens-electricite-octobre","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/","title":{"rendered":"Baisse des prix des march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 en octobre"},"content":{"rendered":"<p><strong>AleaSoft, 4 novembre 2019. Le mois d&rsquo;octobre s&rsquo;est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d&rsquo;\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. En Italie, la production d\u2019\u00e9nergie solaire a \u00e9galement augment\u00e9. Ces donn\u00e9es et l\u2019augmentation de la production d\u2019\u00e9nergie \u00e9olienne dans certains pays ont favoris\u00e9 la chute des prix des march\u00e9s de l\u2019\u00e9lectricit\u00e9. Bien que, selon l&rsquo;analyse effectu\u00e9e par AleaSoft, les baisses annuelles des prix du gaz et du charbon soient la cause principale de la chute des prix des march\u00e9s de l&rsquo;\u00e9lectricit\u00e9.<\/strong><\/p>\n<a href='https:\/\/aleasoft.com\/fr\/cas-previsions\/services-ppa-synergies\/' class='alea-banner-link' data-alea-gtm-event-category='banner-horizontal' data-alea-gtm-event-label='ppa'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2021\/06\/banners_ppa_fr.jpg' alt='Offre de pr\u00e9visions de prix \u00e0 long terme pour PPA' style=''\/><\/a>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/baisse-prix-marches-europeens-electricite-octobre\/'>Nouvelle en anglais<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 4 novembre 2019. Le mois d&rsquo;octobre s&rsquo;est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d&rsquo;\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. En Italie, la production d\u2019\u00e9nergie solaire a \u00e9galement augment\u00e9. Ces donn\u00e9es et l\u2019augmentation de la production d\u2019\u00e9nergie \u00e9olienne dans certains pays ont favoris\u00e9 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[628],"class_list":["post-78656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Baisse des prix des march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 en octobre - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Le mois d&#039;octobre s&#039;est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d&#039;\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l&#039;ann\u00e9e pr\u00e9c\u00e9dente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baisse des prix des march\u00e9s europ\u00e9ens de l&#039;\u00e9lectricit\u00e9 en octobre\" \/>\n<meta property=\"og:description\" content=\"Le mois d&#039;octobre s&#039;est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d&#039;\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l&#039;ann\u00e9e pr\u00e9c\u00e9dente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-03T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-12T18:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/11\/20191104-aleasoft-european-electricity-market-prices.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2373\" \/>\n\t<meta property=\"og:image:height\" content=\"1639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"Baisse des prix des march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 en octobre\",\"datePublished\":\"2019-11-03T23:00:00+00:00\",\"dateModified\":\"2020-02-12T18:02:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/20191104-aleasoft-european-electricity-market-prices.png\",\"keywords\":[\"nouvelles\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/\",\"name\":\"Baisse des prix des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 en octobre - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/20191104-aleasoft-european-electricity-market-prices.png\",\"datePublished\":\"2019-11-03T23:00:00+00:00\",\"dateModified\":\"2020-02-12T18:02:48+00:00\",\"description\":\"Le mois d'octobre s'est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d'\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/20191104-aleasoft-european-electricity-market-prices.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/20191104-aleasoft-european-electricity-market-prices.png\",\"width\":2373,\"height\":1639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/fr\\\/baisse-prix-marches-europeens-electricite-octobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baisse des prix des march\u00e9s europ\u00e9ens de l&#8217;\u00e9lectricit\u00e9 en octobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baisse des prix des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 en octobre - AleaSoft Energy Forecasting","description":"Le mois d'octobre s'est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d'\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/","og_locale":"fr_FR","og_type":"article","og_title":"Baisse des prix des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 en octobre","og_description":"Le mois d'octobre s'est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d'\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente.","og_url":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2019-11-03T23:00:00+00:00","article_modified_time":"2020-02-12T18:02:48+00:00","og_image":[{"width":2373,"height":1639,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/11\/20191104-aleasoft-european-electricity-market-prices.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"\u00c9crit par":"AleaSoft Energy Forecasting","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"Baisse des prix des march\u00e9s europ\u00e9ens de l&rsquo;\u00e9lectricit\u00e9 en octobre","datePublished":"2019-11-03T23:00:00+00:00","dateModified":"2020-02-12T18:02:48+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/"},"wordCount":122,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/11\/20191104-aleasoft-european-electricity-market-prices.png","keywords":["nouvelles"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/","url":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/","name":"Baisse des prix des march\u00e9s europ\u00e9ens de l'\u00e9lectricit\u00e9 en octobre - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/11\/20191104-aleasoft-european-electricity-market-prices.png","datePublished":"2019-11-03T23:00:00+00:00","dateModified":"2020-02-12T18:02:48+00:00","description":"Le mois d'octobre s'est cl\u00f4tur\u00e9 sur des donn\u00e9es tr\u00e8s positives concernant la production d'\u00e9nergie solaire en Espagne, qui a augment\u00e9 de 29% par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/11\/20191104-aleasoft-european-electricity-market-prices.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2019\/11\/20191104-aleasoft-european-electricity-market-prices.png","width":2373,"height":1639},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/fr\/baisse-prix-marches-europeens-electricite-octobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/"},{"@type":"ListItem","position":2,"name":"Baisse des prix des march\u00e9s europ\u00e9ens de l&#8217;\u00e9lectricit\u00e9 en octobre"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/78656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/comments?post=78656"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/posts\/78656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media\/73561"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/media?parent=78656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/categories?post=78656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/fr\/wp-json\/wp\/v2\/tags?post=78656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}