{"id":130880,"date":"2022-11-10T18:43:15","date_gmt":"2022-11-10T17:43:15","guid":{"rendered":"https:\/\/aleasoft.com\/?page_id=130880"},"modified":"2026-04-23T05:16:33","modified_gmt":"2026-04-23T03:16:33","slug":"alea-energy-database","status":"publish","type":"page","link":"https:\/\/aleasoft.com\/it\/servizi\/alea-energy-database\/","title":{"rendered":""},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"130880\" class=\"elementor elementor-130880\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a11e711 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a11e711\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0de3eed\" data-id=\"0de3eed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7a7c12 elementor-widget elementor-widget-heading\" data-id=\"d7a7c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Alea Energy DataBase<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-674c2eb elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-hidden-mobile elementor-hidden-tablet elementor-section-height-default\" data-id=\"674c2eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5fbc1d1\" data-id=\"5fbc1d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fe5a2d elementor-widget elementor-widget-heading\" data-id=\"8fe5a2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Alea Energy DataBase<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec38a48 elementor-widget elementor-widget-heading\" data-id=\"ec38a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lo strumento indispensabile per comprendere e padroneggiare i mercati dell'energia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f7d0ad5\" data-id=\"f7d0ad5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48521f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48521f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd6ca6f\" data-id=\"cd6ca6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1a3919 elementor-widget elementor-widget-spacer\" data-id=\"b1a3919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f59cb13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f59cb13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa12fb5\" data-id=\"aa12fb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c520115 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c520115\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87f8392\" data-id=\"87f8392\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9eaee3 elementor-widget elementor-widget-image\" data-id=\"d9eaee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/elementor\/thumbs\/pexels-cookiecutter-1148820-scaled-1-rmet7lu5f479ejuxxgrgdqoptkjntccaaa8k5r7jek.jpg\" title=\"pexels-cookiecutter-1148820-scaled.jpg\" alt=\"pexels-cookiecutter-1148820-scaled.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f2c27c3\" data-id=\"f2c27c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edfc07a elementor-widget elementor-widget-text-editor\" data-id=\"edfc07a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Alea Energy DataBase<\/strong> \u00e8 una piattaforma online che riunisce tutte le informazioni sui mercati energetici in un unico posto. Progettata per accelerare la <strong>digitalizzazione<\/strong>, favorire la <strong>conoscenza<\/strong> e promuovere lo sviluppo delle <strong>energie rinnovabili<\/strong>, offre accesso immediato a dati storici aggiornati e a strumenti avanzati di analisi e visualizzazione. Alea Energy DataBase \u00e8 offerta da <strong>AleaWhite<\/strong>, la divisione di AleaSoft Energy Forecasting che fornisce informazioni aggiornate sul settore energetico.<\/p><p>Questa piattaforma \u00e8 indispensabile per analisti, trader, investitori, produttori, distributori, amministratori delegati, direttori finanziari e giornalisti specializzati che necessitano di dati affidabili e precisi per prendere decisioni responsabili. Con Alea Energy DataBase, gli utenti possono operare sui mercati, effettuare operazioni di copertura, individuare opportunit\u00e0 commerciali e ottimizzare le proprie strategie energetiche.<\/p><p>Alea Energy DataBase organizza i dati in osservatori che coprono, tra l&#8217;altro, i prezzi di mercato, la domanda, la produzione per tecnologia, le temperature, i prezzi dei combustibili e le curve dei futures. Gli utenti possono personalizzare le proprie analisi utilizzando strumenti quali il confronto di serie storiche, il calcolo delle medie mobili, gli intervalli temporali dinamici e gli avvisi configurabili. Dispone inoltre di un&#8217;API che facilita l&#8217;integrazione dei dati nei modelli e nei sistemi propri.<\/p><p>Grazie alle serie storiche costantemente aggiornate, Alea Energy DataBase rappresenta una fonte di informazioni fondamentale per comprendere i principali fattori trainanti dei mercati energetici. La sua capacit\u00e0 di evidenziare le relazioni tra le variabili la rende una soluzione indispensabile per il trading, la copertura dei rischi e la pianificazione strategica.<\/p><p>Alea Energy DataBase \u00e8 disponibile tramite piani di abbonamento che consentono di scegliere il numero di utenti, gli osservatori disponibili e l&#8217;opzione di scaricare i dati. Creata da AleaSoft Energy Forecasting, con 27 anni di esperienza nel settore, la piattaforma unisce esperienza, tecnologia e competenza per sostenere la transizione energetica globale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0a3fc2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a0a3fc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE0NjM0MiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi informazioni<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1c87fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1c87fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8764b24\" data-id=\"8764b24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0eb3198 elementor-widget elementor-widget-spacer\" data-id=\"0eb3198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc341ba elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc341ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4fd7ba\" data-id=\"f4fd7ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36bda38 elementor-widget elementor-widget-image\" data-id=\"36bda38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1144\" height=\"208\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/06\/observatorios-it.png\" class=\"attachment-full size-full wp-image-146316\" alt=\"\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/06\/observatorios-it.png 1144w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/06\/observatorios-it-300x55.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/06\/observatorios-it-1024x186.png 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/06\/observatorios-it-150x27.png 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2024\/06\/observatorios-it-768x140.png 768w\" sizes=\"(max-width: 1144px) 100vw, 1144px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5a89b9 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5a89b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12fc57d\" data-id=\"12fc57d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-099f8ca elementor-cta--skin-cover elementor-cta--valign-middle e-transform elementor-widget elementor-widget-call-to-action\" data-id=\"099f8ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/aleasoft.com\/es\/mercados-energia\/mibel-espana-precios-demanda\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/09\/observatorios-sin-texto-movil.png);\" role=\"img\" aria-label=\"observatorios-sin-texto-movil.png\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<div style=\"margin-top: 1%;width: 75%;padding-left: 1%;text-align: center\">Osservatori dei mercati energetici in Spagna  <\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<div style=\"margin-top: -1%;margin-bottom: 1%;width: 75%;padding-left: 1%;text-align: center\">Visita l'osservatorio del mercato spagnolo per analizzare l'andamento delle principali variabili<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5464c8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5464c8f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bdbe98e\" data-id=\"bdbe98e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-797019e elementor-widget elementor-widget-spacer\" data-id=\"797019e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e50eb6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e50eb6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf8f0e3\" data-id=\"bf8f0e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74b123c elementor-widget elementor-widget-heading\" data-id=\"74b123c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/aleawhite\/\">Altri servizi per i mercati dell\u2019energia che potrebbero interessarti<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43d7e78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43d7e78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-946d825\" data-id=\"946d825\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa1d1ac elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"aa1d1ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1610b5f\" data-id=\"1610b5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1998ee9 elementor-widget elementor-widget-button\" data-id=\"1998ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/it\/servizi\/previsioni-dei-prezzi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsioni sui prezzi dei mercati dell'energia elettrica<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0de9125\" data-id=\"0de9125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bff0f1 elementor-widget elementor-widget-button\" data-id=\"7bff0f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/it\/prodotti-e-servizi\/previsioni-del-fabbisogno\/?tab=medio-termine\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsioni del fabbisogno elettrico a breve termine<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bac8a35 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"bac8a35\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-92fa206\" data-id=\"92fa206\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89fbfe6 elementor-widget elementor-widget-button\" data-id=\"89fbfe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/it\/servizi\/previsioni-prezzi-gas\/breve-termine\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsioni dei prezzi del gas a breve termine<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a84c6ca\" data-id=\"a84c6ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66a2b28 elementor-widget elementor-widget-button\" data-id=\"66a2b28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/it\/servizi\/previsioni-fabbisogno-gas\/breve-termine\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsioni del fabbisogno del gas a breve termine<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1838877 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"1838877\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb41d7a\" data-id=\"cb41d7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cff344 elementor-widget elementor-widget-button\" data-id=\"9cff344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/it\/servizi\/previsioni-energie-rinnovabili\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Previsioni delle energie rinnovabili a breve termine<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-958f6f8\" data-id=\"958f6f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bceb4d8 elementor-widget elementor-widget-button\" data-id=\"bceb4d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aleasoft.com\/it\/previsioni-casi\/rapporti-settore-llenergia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Report per il settore dell\u2019energia<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec00529 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec00529\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34220d7\" data-id=\"34220d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d173e4 elementor-widget elementor-widget-heading\" data-id=\"6d173e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/notizie\/\">Notizie principali<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-100e3ff elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"100e3ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afaacd9\" data-id=\"afaacd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1187fcd elementor-widget elementor-widget-template\" data-id=\"1187fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"144852\" class=\"elementor elementor-144852\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46705fbd elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46705fbd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-60f5c556\" data-id=\"60f5c556\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49c4b7ff elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49c4b7ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2b847b04\" data-id=\"2b847b04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76fe3c56 elementor-widget elementor-widget-image\" data-id=\"76fe3c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/elementor\/thumbs\/20240304-AleaSoft-Antonio-Delgado-Rigal-CEO-qkporw1gur332b0z0qd9nvsgal7729nucr9gcr2g2k.webp\" title=\"20240304-AleaSoft-Antonio-Delgado-Rigal-CEO\" alt=\"20240304-AleaSoft-Antonio-Delgado-Rigal-CEO\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14471353 elementor-widget elementor-widget-heading\" data-id=\"14471353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/intervista-a-antonio-delgado-rigal-dottore-in-intelligenza-artificiale-e-ceo-di-aleasoft-energy-forecasting\/\">Intervista a Antonio Delgado Rigal, dottore in intelligenza artificiale e ceo di Aleasoft Energy Forecasting<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f798d23 elementor-widget elementor-widget-heading\" data-id=\"3f798d23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/intervista-a-antonio-delgado-rigal-dottore-in-intelligenza-artificiale-e-ceo-di-aleasoft-energy-forecasting\/\"> Intervista con Ram\u00f3n Roca, direttore di \u201cEl Peri\u00f3dico de la Energ\u00eda\u201d, Antonio Delgado Rigal, Dottore in Intelligenza Artificiale...<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1222cfb3 elementor-widget elementor-widget-heading\" data-id=\"1222cfb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/intervista-a-antonio-delgado-rigal-dottore-in-intelligenza-artificiale-e-ceo-di-aleasoft-energy-forecasting\/\">Vedi altro&gt;&gt;<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33dbd444\" data-id=\"33dbd444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3dd4f657 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"3dd4f657\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6c34bad8\" data-id=\"6c34bad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f68341c elementor-widget elementor-widget-image\" data-id=\"5f68341c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/elementor\/thumbs\/20240422-AleaSoft-Precios-mercados-europeos-electricidad-qn32p7xjsq3r9x9qkp8w4vqu6xl6f7h0vhl8roerx8.png\" title=\"20240422-AleaSoft-Precios-mercados-europeos-electricidad\" alt=\"20240422-AleaSoft-Precios-mercados-europeos-electricidad\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0708df elementor-widget elementor-widget-heading\" data-id=\"2e0708df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/laumento-dei-prezzi-del-gas-e-della-cosub2-sub-trascina-i-mercati-europei-dellelettricita-ma-il-mercato-iberico-resiste\/\">L\u2019aumento dei prezzi del gas e della CO<sub>2<\/sub> trascina i mercati europei dell\u2019elettricit\u00e0, ma il mercato iberico resiste<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42de7806 elementor-widget elementor-widget-heading\" data-id=\"42de7806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/laumento-dei-prezzi-del-gas-e-della-cosub2-sub-trascina-i-mercati-europei-dellelettricita-ma-il-mercato-iberico-resiste\/\">Nella terza settimana di aprile, i prezzi della maggior parte dei principali mercati europei dell\u2019elettricit\u00e0 sono aumentati...<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f134204 elementor-widget elementor-widget-heading\" data-id=\"3f134204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/laumento-dei-prezzi-del-gas-e-della-cosub2-sub-trascina-i-mercati-europei-dellelettricita-ma-il-mercato-iberico-resiste\/\">Vedi altro&gt;&gt;<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-16449f83\" data-id=\"16449f83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29b9fd41 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"29b9fd41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-52083145\" data-id=\"52083145\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-760104ad elementor-widget elementor-widget-image\" data-id=\"760104ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/elementor\/thumbs\/20240322-AleaSoft-Main-topics-energy-markets-2024-EY-qllvqg4xp44etgoll1cziu9pim0r8gbr08wdgmm50c.png\" title=\"20240322-AleaSoft-Main-topics-energy-markets-2024-EY\" alt=\"20240322-AleaSoft-Main-topics-energy-markets-2024-EY\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-253ba08c elementor-widget elementor-widget-heading\" data-id=\"253ba08c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/il-fabbisogno-la-grande-dimenticanza-della-transizione-energetica\/\">Il fabbisogno, la grande dimenticanza della transizione energetica<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6092206c elementor-widget elementor-widget-spacer\" data-id=\"6092206c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ef8ad05 elementor-widget elementor-widget-heading\" data-id=\"4ef8ad05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/il-fabbisogno-la-grande-dimenticanza-della-transizione-energetica\/\">Nel webinar di AleaSoft Energy Forecasting, con la partecipazione di EY, \u00e8 stata evidenziata...<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5d18c9 elementor-widget elementor-widget-heading\" data-id=\"5e5d18c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/aleasoft.com\/it\/il-fabbisogno-la-grande-dimenticanza-della-transizione-energetica\/\">Vedi altro&gt;&gt;<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c07c3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c07c3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da5171d\" data-id=\"da5171d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee85069 elementor-widget elementor-widget-shortcode\" data-id=\"ee85069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><article class=\"noticia-card-fija \"><div class=\"noticia-card-imagen-wrapper\"><a href=\"https:\/\/aleasoft.com\/it\/intervista-giornale-energia-antonio-delgado-rigal-30032026\/\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-scaled.jpg\" class=\"noticia-card-imagen wp-post-image\" alt=\"Intervista di El Peri\u00f3dico de la Energ\u00eda ad Antonio Delgado Rigal, dottore in Intelligenza Artificiale e amministratore delegato di AleaSoft Energy Forecasting\" loading=\"lazy\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-scaled.jpg 2048w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-300x225.jpg 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-1024x768.jpg 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-150x113.jpg 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-768x576.jpg 768w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/03\/Antonio-Delgado-Rigal-CEO-AleaSoft-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/div><div class=\"card-contenido\"><h3 class=\"elementor-heading-title elementor-size-default card-titulo\"><a href=\"https:\/\/aleasoft.com\/it\/intervista-giornale-energia-antonio-delgado-rigal-30032026\/\">Intervista di El Peri\u00f3dico de la Energ\u00eda ad Antonio Delgado Rigal, dottore in Intelligenza Artificiale e amministratore delegato di AleaSoft Energy Forecasting<\/a><\/h3><div class=\"card-bloque-inferior\"><p class=\"card-descripcion\">AleaSoft Energy Forecasting, 30 marzo 2026. Intervista di Ram\u00f3n Roca, direttore di El Peri\u00f3dico de la\u2026<\/p><a href=\"https:\/\/aleasoft.com\/it\/intervista-giornale-energia-antonio-delgado-rigal-30032026\/\" class=\"card-ver-mas\">Vedi Altro &gt;&gt;<\/a><\/div><\/div><\/article><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-88315d7\" data-id=\"88315d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d2cf0d elementor-widget elementor-widget-shortcode\" data-id=\"0d2cf0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><article class=\"noticia-card-fija \"><div class=\"noticia-card-imagen-wrapper\"><a href=\"https:\/\/aleasoft.com\/it\/minimo-storico-prezzo-giornaliero-mercato-elettrico-francese\/\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"509\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/05\/20260504-AleaSoft-European-electricity-market-prices.png\" class=\"noticia-card-imagen wp-post-image\" alt=\"Minimo storico giornaliero in Francia nell&#8217;ultima settimana di aprile, con rialzi sui mercati elettrici europei\" loading=\"lazy\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/05\/20260504-AleaSoft-European-electricity-market-prices.png 730w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/05\/20260504-AleaSoft-European-electricity-market-prices-300x209.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/05\/20260504-AleaSoft-European-electricity-market-prices-150x105.png 150w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div class=\"card-contenido\"><h3 class=\"elementor-heading-title elementor-size-default card-titulo\"><a href=\"https:\/\/aleasoft.com\/it\/minimo-storico-prezzo-giornaliero-mercato-elettrico-francese\/\">Minimo storico giornaliero in Francia nell&#8217;ultima settimana di aprile, con rialzi sui mercati elettrici europei<\/a><\/h3><div class=\"card-bloque-inferior\"><p class=\"card-descripcion\">AleaSoft Energy Forecasting, 4 maggio 2026. Nell&#8217;ultima settimana di aprile, i prezzi medi settimanali della maggior\u2026<\/p><a href=\"https:\/\/aleasoft.com\/it\/minimo-storico-prezzo-giornaliero-mercato-elettrico-francese\/\" class=\"card-ver-mas\">Vedi Altro &gt;&gt;<\/a><\/div><\/div><\/article><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-601f91c\" data-id=\"601f91c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bf0e42 elementor-widget elementor-widget-shortcode\" data-id=\"7bf0e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><article class=\"noticia-card-fija \"><div class=\"noticia-card-imagen-wrapper\"><a href=\"https:\/\/aleasoft.com\/it\/spagna-centri-dati-investimenti-digitali-energia-rinnovabile\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/04\/20260430-AleaSoft-Espanna-centros-datos-inversion-digital-energia-renovable.png\" class=\"noticia-card-imagen wp-post-image\" alt=\"La Spagna rischia di perdere la pi\u00f9 grande opportunit\u00e0 industriale del secolo: i centri dati\" loading=\"lazy\" srcset=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/04\/20260430-AleaSoft-Espanna-centros-datos-inversion-digital-energia-renovable.png 1536w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/04\/20260430-AleaSoft-Espanna-centros-datos-inversion-digital-energia-renovable-300x200.png 300w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/04\/20260430-AleaSoft-Espanna-centros-datos-inversion-digital-energia-renovable-1024x683.png 1024w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/04\/20260430-AleaSoft-Espanna-centros-datos-inversion-digital-energia-renovable-150x100.png 150w, https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/04\/20260430-AleaSoft-Espanna-centros-datos-inversion-digital-energia-renovable-768x512.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/a><\/div><div class=\"card-contenido\"><h3 class=\"elementor-heading-title elementor-size-default card-titulo\"><a href=\"https:\/\/aleasoft.com\/it\/spagna-centri-dati-investimenti-digitali-energia-rinnovabile\/\">La Spagna rischia di perdere la pi\u00f9 grande opportunit\u00e0 industriale del secolo: i centri dati<\/a><\/h3><div class=\"card-bloque-inferior\"><p class=\"card-descripcion\">AleaSoft Energy Forecasting, 30 aprile 2026. La Spagna si trova di fronte a una decisione strategica\u2026<\/p><a href=\"https:\/\/aleasoft.com\/it\/spagna-centri-dati-investimenti-digitali-energia-rinnovabile\/\" class=\"card-ver-mas\">Vedi Altro &gt;&gt;<\/a><\/div><\/div><\/article><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Alea Energy DataBase Alea Energy DataBase Lo strumento indispensabile per comprendere e padroneggiare i mercati dell&#8217;energia Alea Energy DataBase \u00e8 una piattaforma online che riunisce tutte le informazioni sui mercati energetici in un unico posto. Progettata per accelerare la digitalizzazione, favorire la conoscenza e promuovere lo sviluppo delle energie rinnovabili, offre accesso immediato a dati [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":157188,"parent":143015,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-130880","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alea Energy DataBase - AleaWhite - AleaSoft<\/title>\n<meta name=\"description\" content=\"Piattaforma online di dati sui mercati dell&#039;energia che alimenta tre vettori di sviluppo essenziali in Europa: digitalizzazione, conoscenza e rinnovabili\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:description\" content=\"Piattaforma online di dati sui mercati dell&#039;energia che alimenta tre vettori di sviluppo essenziali in Europa: digitalizzazione, conoscenza e rinnovabili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T03:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/05\/pexels-cookiecutter-1148820-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/servizi\\\/alea-energy-database\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/\",\"name\":\"Alea Energy DataBase - AleaWhite - AleaSoft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/pexels-cookiecutter-1148820-scaled.jpg\",\"datePublished\":\"2022-11-10T17:43:15+00:00\",\"dateModified\":\"2026-04-23T03:16:33+00:00\",\"description\":\"Piattaforma online di dati sui mercati dell'energia che alimenta tre vettori di sviluppo essenziali in Europa: digitalizzazione, conoscenza e rinnovabili\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/pexels-cookiecutter-1148820-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/pexels-cookiecutter-1148820-scaled.jpg\",\"width\":2048,\"height\":1367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/previsioni-casi\\\/alea-energy-database-aleaapp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/services\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alea Energy DataBase - AleaWhite - AleaSoft","description":"Piattaforma online di dati sui mercati dell'energia che alimenta tre vettori di sviluppo essenziali in Europa: digitalizzazione, conoscenza e rinnovabili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/","og_locale":"it_IT","og_type":"article","og_description":"Piattaforma online di dati sui mercati dell'energia che alimenta tre vettori di sviluppo essenziali in Europa: digitalizzazione, conoscenza e rinnovabili","og_url":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_modified_time":"2026-04-23T03:16:33+00:00","og_image":[{"width":2048,"height":1367,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/05\/pexels-cookiecutter-1148820-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/it\/servizi\/alea-energy-database\/","url":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/","name":"Alea Energy DataBase - AleaWhite - AleaSoft","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/05\/pexels-cookiecutter-1148820-scaled.jpg","datePublished":"2022-11-10T17:43:15+00:00","dateModified":"2026-04-23T03:16:33+00:00","description":"Piattaforma online di dati sui mercati dell'energia che alimenta tre vettori di sviluppo essenziali in Europa: digitalizzazione, conoscenza e rinnovabili","breadcrumb":{"@id":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/05\/pexels-cookiecutter-1148820-scaled.jpg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/05\/pexels-cookiecutter-1148820-scaled.jpg","width":2048,"height":1367},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/it\/previsioni-casi\/alea-energy-database-aleaapp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/"},{"@type":"ListItem","position":2,"name":"Servizi","item":"https:\/\/aleasoft.com\/services\/"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/pages\/130880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/comments?post=130880"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/pages\/130880\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/pages\/143015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media\/157188"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media?parent=130880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}