{"id":100944,"date":"2020-09-01T18:26:36","date_gmt":"2020-09-01T16:26:36","guid":{"rendered":"https:\/\/aleasoft.com\/?p=100944"},"modified":"2020-09-03T12:18:20","modified_gmt":"2020-09-03T10:18:20","slug":"agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/","title":{"rendered":"In agosto i prezzi dei mercati europei dell&#8217;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019"},"content":{"rendered":"<p><strong>AleaSoft, 1 settembre 2020. I prezzi dei mercati europei dell&#8217;energia elettrica sono aumentati in agosto rispetto a quelli di luglio. Tuttavia, nella maggior parte dei casi sono ancora inferiori a quelli dell&#8217;agosto 2019. Una delle cause di questo comportamento \u00e8 il prezzo del gas, che si \u00e8 ripreso rispetto a luglio, ma \u00e8 ancora inferiore a quello dell&#8217;agosto 2019. Un dato positivo \u00e8 l&#8217;aumento di anno in anno della produzione di energia eolica e solare in tutti i mercati. D&#8217;altra parte, la domanda \u00e8 diminuita rispetto a quella dell&#8217;agosto 2019 a causa della coronacrisia.<\/strong><\/p>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/'>Notizie in inglese<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 1 settembre 2020. I prezzi dei mercati europei dell&#8217;energia elettrica sono aumentati in agosto rispetto a quelli di luglio. Tuttavia, nella maggior parte dei casi sono ancora inferiori a quelli dell&#8217;agosto 2019. Una delle cause di questo comportamento \u00e8 il prezzo del gas, che si \u00e8 ripreso rispetto a luglio, ma \u00e8 ancora inferiore [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[634],"class_list":["post-100944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>In agosto i prezzi dei mercati europei dell&#039;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019 - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"I prezzi dei mercati europei dell&#039;energia elettrica sono aumentati in agosto rispetto a quelli di luglio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In agosto i prezzi dei mercati europei dell&#039;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019\" \/>\n<meta property=\"og:description\" content=\"I prezzi dei mercati europei dell&#039;energia elettrica sono aumentati in agosto rispetto a quelli di luglio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T16:26:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-03T10:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/09\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"In agosto i prezzi dei mercati europei dell&#8217;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019\",\"datePublished\":\"2020-09-01T16:26:36+00:00\",\"dateModified\":\"2020-09-03T10:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/\"},\"wordCount\":104,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"keywords\":[\"notizie\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/\",\"name\":\"In agosto i prezzi dei mercati europei dell'energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019 - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"datePublished\":\"2020-09-01T16:26:36+00:00\",\"dateModified\":\"2020-09-03T10:18:20+00:00\",\"description\":\"I prezzi dei mercati europei dell'energia elettrica sono aumentati in agosto rispetto a quelli di luglio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"width\":2282,\"height\":1582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In agosto i prezzi dei mercati europei dell&#8217;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In agosto i prezzi dei mercati europei dell'energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019 - AleaSoft Energy Forecasting","description":"I prezzi dei mercati europei dell'energia elettrica sono aumentati in agosto rispetto a quelli di luglio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/","og_locale":"it_IT","og_type":"article","og_title":"In agosto i prezzi dei mercati europei dell'energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019","og_description":"I prezzi dei mercati europei dell'energia elettrica sono aumentati in agosto rispetto a quelli di luglio.","og_url":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2020-09-01T16:26:36+00:00","article_modified_time":"2020-09-03T10:18:20+00:00","og_image":[{"width":2282,"height":1582,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/09\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Scritto da":"AleaSoft Energy Forecasting"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"In agosto i prezzi dei mercati europei dell&#8217;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019","datePublished":"2020-09-01T16:26:36+00:00","dateModified":"2020-09-03T10:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/"},"wordCount":104,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/09\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png","keywords":["notizie"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/","url":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/","name":"In agosto i prezzi dei mercati europei dell'energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019 - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/09\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png","datePublished":"2020-09-01T16:26:36+00:00","dateModified":"2020-09-03T10:18:20+00:00","description":"I prezzi dei mercati europei dell'energia elettrica sono aumentati in agosto rispetto a quelli di luglio.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/09\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/09\/20200901-AleaSoft-Monthly-electricity-market-prices-Europe.png","width":2282,"height":1582},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/it\/agosto-prezzi-mercati-europei-dellenergia-elettrica-hanno-recuperato-anche-continuano-senza-raggiungere-livelli-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/it\/"},{"@type":"ListItem","position":2,"name":"In agosto i prezzi dei mercati europei dell&#8217;energia elettrica hanno recuperato, anche se continuano senza raggiungere i livelli del 2019"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts\/100944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/comments?post=100944"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts\/100944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media\/100896"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media?parent=100944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/categories?post=100944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/tags?post=100944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}