{"id":135751,"date":"2023-07-17T14:27:50","date_gmt":"2023-07-17T12:27:50","guid":{"rendered":"https:\/\/aleasoft.com\/?p=135751"},"modified":"2023-07-18T05:10:29","modified_gmt":"2023-07-18T03:10:29","slug":"calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/","title":{"rendered":"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 17 luglio 2023. Nella seconda settimana di luglio i prezzi del gas sono scesi e, di conseguenza, sono scesi i prezzi dei mercati elettrici europei. Questa tendenza \u00e8 stata favorita anche dalla minore domanda di energia elettrica nella maggior parte dei mercati, dalla maggiore produzione di energia eolica in alcuni casi e dai prezzi della CO<sub>2<\/sub> stabili, mediamente inferiori a quelli della settimana precedente. Nella Spagna continentale, il record di produzione fotovoltaica \u00e8 stato nuovamente battuto il 14 luglio con 159 GWh.<\/strong><\/p>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/'>Notizie in inglese<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 17 luglio 2023. Nella seconda settimana di luglio i prezzi del gas sono scesi e, di conseguenza, sono scesi i prezzi dei mercati elettrici europei. Questa tendenza \u00e8 stata favorita anche dalla minore domanda di energia elettrica nella maggior parte dei mercati, dalla maggiore produzione di energia eolica in alcuni casi e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":135693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[7512],"class_list":["post-135751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-analisi-mercato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica - AleaSoft Energy Forecasting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica\" \/>\n<meta property=\"og:description\" content=\"AleaSoft Energy Forecasting, 17 luglio 2023. Nella seconda settimana di luglio i prezzi del gas sono scesi e, di conseguenza, sono scesi i prezzi dei mercati elettrici europei. Questa tendenza \u00e8 stata favorita anche dalla minore domanda di energia elettrica nella maggior parte dei mercati, dalla maggiore produzione di energia eolica in alcuni casi e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-17T12:27:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-18T03:10:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2023\/07\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\"},\"headline\":\"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica\",\"datePublished\":\"2023-07-17T12:27:50+00:00\",\"dateModified\":\"2023-07-18T03:10:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/\"},\"wordCount\":103,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"keywords\":[\"analisi di mercato\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/\",\"name\":\"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"datePublished\":\"2023-07-17T12:27:50+00:00\",\"dateModified\":\"2023-07-18T03:10:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png\",\"width\":2048,\"height\":1426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica - AleaSoft Energy Forecasting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/","og_locale":"it_IT","og_type":"article","og_title":"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica","og_description":"AleaSoft Energy Forecasting, 17 luglio 2023. Nella seconda settimana di luglio i prezzi del gas sono scesi e, di conseguenza, sono scesi i prezzi dei mercati elettrici europei. Questa tendenza \u00e8 stata favorita anche dalla minore domanda di energia elettrica nella maggior parte dei mercati, dalla maggiore produzione di energia eolica in alcuni casi e [&hellip;]","og_url":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2023-07-17T12:27:50+00:00","article_modified_time":"2023-07-18T03:10:29+00:00","og_image":[{"width":2282,"height":1589,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2023\/07\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Scritto da":"AleaSoft Energy Forecasting","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61"},"headline":"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica","datePublished":"2023-07-17T12:27:50+00:00","dateModified":"2023-07-18T03:10:29+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/"},"wordCount":103,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2023\/07\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png","keywords":["analisi di mercato"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/","url":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/","name":"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2023\/07\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png","datePublished":"2023-07-17T12:27:50+00:00","dateModified":"2023-07-18T03:10:29+00:00","breadcrumb":{"@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2023\/07\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2023\/07\/20230717-AleaSoft-Precios-mercados-europeos-electricidad.png","width":2048,"height":1426},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/it\/calo-prezzi-gas-trascina-ribasso-mercati-elettrici-europei-mentre-spagna-viene-battuto-record-produzione-fotovoltaica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/"},{"@type":"ListItem","position":2,"name":"Il calo dei prezzi del gas trascina al ribasso i mercati elettrici europei mentre in Spagna viene battuto il record di produzione fotovoltaica"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"}}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts\/135751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/comments?post=135751"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts\/135751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media\/135693"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media?parent=135751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/categories?post=135751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/tags?post=135751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}