{"id":93027,"date":"2020-05-25T19:39:31","date_gmt":"2020-05-25T17:39:31","guid":{"rendered":"https:\/\/aleasoft.com\/?p=93027"},"modified":"2020-05-26T18:21:21","modified_gmt":"2020-05-26T16:21:21","slug":"prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/","title":{"rendered":"I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#8217;elevata produzione di energia rinnovabile"},"content":{"rendered":"<p><strong>AleaSoft, 25 maggio 2020. Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati , del mercato N2EX e del mercato danese, appartenente al Nord Pool. La produzione di energia eolica, che si \u00e8 ripresa dopo una settimana con valori bassi, la produzione di energia solare che \u00e8 aumentata in tutti i mercati e la minore domanda di elettricit\u00e0 nel fine settimana hanno portato a questi prezzi. I prezzi del gas TTF hanno continuato a scendere ai minimi durante la terza settimana di maggio.<\/strong><\/p>\n<a style='color:#0047c8;' href='https:\/\/aleasoft.com\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/'>Notizie in inglese<\/a>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft, 25 maggio 2020. Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati , del mercato N2EX e del mercato danese, appartenente al Nord Pool. La produzione di energia eolica, che si \u00e8 ripresa dopo una settimana con valori bassi, la produzione di energia solare che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":92943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[634],"class_list":["post-93027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#039;elevata produzione di energia rinnovabile - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati EPEX SPOT, del mercato N2EX e del mercato danese, appartenente al Nord Pool.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#039;elevata produzione di energia rinnovabile\" \/>\n<meta property=\"og:description\" content=\"Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati EPEX SPOT, del mercato N2EX e del mercato danese, appartenente al Nord Pool.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T17:39:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-26T16:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/05\/20200525-AleaSoft-European-electricity-market-prices.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2372\" \/>\n\t<meta property=\"og:image:height\" content=\"1638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#8217;elevata produzione di energia rinnovabile\",\"datePublished\":\"2020-05-25T17:39:31+00:00\",\"dateModified\":\"2020-05-26T16:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/\"},\"wordCount\":104,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200525-AleaSoft-European-electricity-market-prices.png\",\"keywords\":[\"notizie\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/\",\"name\":\"I prezzi negativi sono tornati in gran parte dei mercati a causa dell'elevata produzione di energia rinnovabile - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200525-AleaSoft-European-electricity-market-prices.png\",\"datePublished\":\"2020-05-25T17:39:31+00:00\",\"dateModified\":\"2020-05-26T16:21:21+00:00\",\"description\":\"Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati EPEX SPOT, del mercato N2EX e del mercato danese, appartenente al Nord Pool.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200525-AleaSoft-European-electricity-market-prices.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/20200525-AleaSoft-European-electricity-market-prices.png\",\"width\":2372,\"height\":1638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/it\\\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#8217;elevata produzione di energia rinnovabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I prezzi negativi sono tornati in gran parte dei mercati a causa dell'elevata produzione di energia rinnovabile - AleaSoft Energy Forecasting","description":"Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati EPEX SPOT, del mercato N2EX e del mercato danese, appartenente al Nord Pool.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/","og_locale":"it_IT","og_type":"article","og_title":"I prezzi negativi sono tornati in gran parte dei mercati a causa dell'elevata produzione di energia rinnovabile","og_description":"Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati EPEX SPOT, del mercato N2EX e del mercato danese, appartenente al Nord Pool.","og_url":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2020-05-25T17:39:31+00:00","article_modified_time":"2020-05-26T16:21:21+00:00","og_image":[{"width":2372,"height":1638,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/05\/20200525-AleaSoft-European-electricity-market-prices.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Scritto da":"AleaSoft Energy Forecasting"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#8217;elevata produzione di energia rinnovabile","datePublished":"2020-05-25T17:39:31+00:00","dateModified":"2020-05-26T16:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/"},"wordCount":104,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/05\/20200525-AleaSoft-European-electricity-market-prices.png","keywords":["notizie"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/","url":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/","name":"I prezzi negativi sono tornati in gran parte dei mercati a causa dell'elevata produzione di energia rinnovabile - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/05\/20200525-AleaSoft-European-electricity-market-prices.png","datePublished":"2020-05-25T17:39:31+00:00","dateModified":"2020-05-26T16:21:21+00:00","description":"Da venerd\u00ec 22 maggio a domenica 24 maggio si sono registrati prezzi negativi in alcune ore dei mercati EPEX SPOT, del mercato N2EX e del mercato danese, appartenente al Nord Pool.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/05\/20200525-AleaSoft-European-electricity-market-prices.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/05\/20200525-AleaSoft-European-electricity-market-prices.png","width":2372,"height":1638},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/it\/prezzi-negativi-sono-tornati-gran-parte-mercati-causa-dellelevata-produzione-energia-rinnovabile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/"},{"@type":"ListItem","position":2,"name":"I prezzi negativi sono tornati in gran parte dei mercati a causa dell&#8217;elevata produzione di energia rinnovabile"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts\/93027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/comments?post=93027"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/posts\/93027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media\/92943"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/media?parent=93027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/categories?post=93027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/it\/wp-json\/wp\/v2\/tags?post=93027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}