{"id":125914,"date":"2022-03-04T14:50:26","date_gmt":"2022-03-04T13:50:26","guid":{"rendered":"https:\/\/aleasoft.com\/?p=125914"},"modified":"2022-03-09T12:26:33","modified_gmt":"2022-03-09T11:26:33","slug":"necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/","title":{"rendered":"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 4 de Mar\u00e7o de 2022. Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica. Isto sublinha a import\u00e2ncia de Espanha e da Uni\u00e3o Europeia alcan\u00e7arem a independ\u00eancia energ\u00e9tica. A solu\u00e7\u00e3o a longo prazo reside nas energias renov\u00e1veis e no hidrog\u00e9nio verde, pelo que \u00e9 importante multiplicar os esfor\u00e7os para promover o seu desenvolvimento.<\/strong><\/p>\n<p><a style='color:#0047c8;' href='https:\/\/aleasoft.com\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/'>Not\u00edcias em ingl\u00eas<\/a><br \/>\n&nbsp;<br \/>\n<script type=\"text\/javascript\">\nwindow.addEventListener('load', function(event){\n        document.getElementById('alea-banner-elementor-template').remove();\n    }\n)\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 4 de Mar\u00e7o de 2022. Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica. Isto sublinha a import\u00e2ncia de Espanha e da Uni\u00e3o Europeia alcan\u00e7arem a independ\u00eancia energ\u00e9tica. A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":125909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7514],"tags":[7513],"class_list":["post-125914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-analise-mercado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica\" \/>\n<meta property=\"og:description\" content=\"Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-04T13:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-09T11:26:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2303\" \/>\n\t<meta property=\"og:image:height\" content=\"1603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\"},\"headline\":\"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica\",\"datePublished\":\"2022-03-04T13:50:26+00:00\",\"dateModified\":\"2022-03-09T11:26:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/\"},\"wordCount\":124,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png\",\"keywords\":[\"an\u00e1lise de mercado\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/\",\"name\":\"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png\",\"datePublished\":\"2022-03-04T13:50:26+00:00\",\"dateModified\":\"2022-03-09T11:26:33+00:00\",\"description\":\"Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png\",\"width\":2303,\"height\":1603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/99ee8b0f2ecbd56ba78005c6b7864d67\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica - AleaSoft Energy Forecasting","description":"Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/","og_locale":"pt_PT","og_type":"article","og_title":"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica","og_description":"Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica.","og_url":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2022-03-04T13:50:26+00:00","article_modified_time":"2022-03-09T11:26:33+00:00","og_image":[{"width":2303,"height":1603,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67"},"headline":"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica","datePublished":"2022-03-04T13:50:26+00:00","dateModified":"2022-03-09T11:26:33+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/"},"wordCount":124,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png","keywords":["an\u00e1lise de mercado"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/","url":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/","name":"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png","datePublished":"2022-03-04T13:50:26+00:00","dateModified":"2022-03-09T11:26:33+00:00","description":"Os pre\u00e7os dos mercados energ\u00e9ticos subiram ainda mais desde o in\u00edcio da invas\u00e3o russa da Ucr\u00e2nia, colocando os consumidores, especialmente os consumidores electro-intensivos, e a economia em geral numa situa\u00e7\u00e3o mais cr\u00edtica.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2022\/03\/20220304-AleaSoft-TTF-gas-m1-Brent-oil-m2-futures-prices.png","width":2303,"height":1603},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/pt\/necessidade-colocar-foco-nas-energias-renovaveis-hidrogenio-verde-para-criar-futuro-dependencia-energetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/pt\/"},{"@type":"ListItem","position":2,"name":"A necessidade de colocar o foco nas energias renov\u00e1veis e no hidrog\u00e9nio verde para criar um futuro sem depend\u00eancia energ\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/99ee8b0f2ecbd56ba78005c6b7864d67","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce8db70bda469bc8382df5990537888cf96f625c0fde5b0292ff5ab10560f88?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts\/125914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/comments?post=125914"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts\/125914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/media\/125909"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/media?parent=125914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/categories?post=125914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/tags?post=125914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}