{"id":155734,"date":"2025-04-01T18:22:20","date_gmt":"2025-04-01T16:22:20","guid":{"rendered":"https:\/\/aleasoft.com\/?p=155734"},"modified":"2025-05-07T17:21:09","modified_gmt":"2025-05-07T15:21:09","slug":"gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/pt\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/","title":{"rendered":"<div style=\"text-align: center;background-color: #004A9B;color: white;\">An\u00e1lise do primeiro trimestre <br>2025 <\/div><br>O g\u00e1s, o CO<sub>2<\/sub> e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 1 de abril de 2025. No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade. Em v\u00e1rios mercados, o pre\u00e7o m\u00e9dio trimestral foi o mais elevado desde o segundo trimestre de 2023. Um dos principais factores desta subida foi o aumento dos pre\u00e7os do g\u00e1s, cuja m\u00e9dia trimestral foi tamb\u00e9m a mais elevada desde essa data. O aumento dos pre\u00e7os do CO<sub>2<\/sub> e da demanda de eletricidade tamb\u00e9m contribuiu para a evolu\u00e7\u00e3o ascendente dos pre\u00e7os. A energia solar fotovoltaica registou n\u00edveis de produ\u00e7\u00e3o recorde para um primeiro trimestre nos principais mercados europeus, enquanto a produ\u00e7\u00e3o de energia e\u00f3lica diminuiu em rela\u00e7\u00e3o ao ano anterior.<\/strong><\/p>\n<h2>Produ\u00e7\u00e3o de energia solar fotovoltaica e e\u00f3lica<\/h2>\n<p>No primeiro trimestre de 2025, <strong>a produ\u00e7\u00e3o de energia solar fotovoltaica<\/strong> aumentou em rela\u00e7\u00e3o ao ano anterior nos principais mercados europeus, com aumentos que variaram entre 13% em Espanha e 33% na Alemanha e em Fran\u00e7a. Este crescimento permitiu que todos estes mercados atingissem n\u00edveis recorde de produ\u00e7\u00e3o de energia fotovoltaica para um primeiro trimestre: Alemanha com 11 238 GWh, Espanha com 8322 GWh, It\u00e1lia com 5276 GWh, Fran\u00e7a com 5092 GWh e Portugal com 1011 GWh.<\/p>\n<p>Al\u00e9m disso, a produ\u00e7\u00e3o de energia solar fotovoltaica tamb\u00e9m superou a do trimestre anterior nos mercados analisados no <strong>AleaSoft Energy Forecasting<\/strong>, com aumentos que variaram entre 15% em Espanha e Portugal e 81% na Alemanha.<\/p>\n<p>Durante os primeiros tr\u00eas meses de 2025, foram adicionados 1077 MW de nova capacidade de energia solar fotovoltaica no sistema continental espanhol. Em Portugal, at\u00e9 fevereiro, a capacidade instalada desta tecnologia aumentou 112 MW em rela\u00e7\u00e3o a dezembro de 2024.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Monthly solar photovoltaic energy production electricity Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-solar-photovoltaic-energy-production-electricity-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-solar-photovoltaic-energy-production-electricity-Europe.png' alt='AleaSoft - Monthly solar photovoltaic energy production electricity Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado por AleaSoft Energy Forecasting utilizando dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica e TERNA.<\/span><\/div>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Solar photovoltaic production profile Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Solar-photovoltaic-production-profile-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Solar-photovoltaic-production-profile-Europe.png' alt='AleaSoft - Solar photovoltaic production profile Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado por AleaSoft Energy Forecasting utilizando dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica e TERNA.<\/span><\/div>\n<p><strong>A produ\u00e7\u00e3o de energia e\u00f3lica<\/strong> registou uma queda hom\u00f3loga no primeiro trimestre de 2025 nos principais mercados europeus, com quedas que variaram entre 2,6% no mercado portugu\u00eas e 29% no mercado alem\u00e3o.<\/p>\n<p>No entanto, ao comparar a produ\u00e7\u00e3o do primeiro trimestre de 2025 com a produ\u00e7\u00e3o do quarto trimestre de 2024, a maioria dos mercados analisados no <strong>AleaSoft Energy Forecasting<\/strong> registou aumentos. O maior aumento foi no mercado espanhol, 16%, enquanto o menor aumento foi em Portugal, 2,9%. Em contrapartida, na Alemanha, a produ\u00e7\u00e3o de energia e\u00f3lica registou um decr\u00e9scimo de 13% em rela\u00e7\u00e3o ao trimestre anterior.<\/p>\n<p>Entre janeiro e mar\u00e7o de 2025, foram instalados 111 MW de energia e\u00f3lica em Espanha Continental. Entretanto, em Portugal, at\u00e9 ao final de fevereiro, a capacidade instalada desta tecnologia manteve-se inalterada face a dezembro de 2024.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Monthly wind energy production electricity Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-wind-energy-production-electricity-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-wind-energy-production-electricity-Europe.png' alt='AleaSoft - Monthly wind energy production electricity Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado por AleaSoft Energy Forecasting utilizando dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica e TERNA.<\/span><\/div>\n<h2>Demanda de eletricidade<\/h2>\n<p>No primeiro trimestre de 2025, <strong>a demanda de eletricidade<\/strong> aumentou face ao mesmo per\u00edodo do ano anterior nos principais mercados europeus. O mercado franc\u00eas registou o maior aumento, 5,6%, seguido dos mercados portugu\u00eas e brit\u00e2nico, que registaram aumentos de 3,7% e 3,5% em cada caso. A demanda aumentou 1,1% no mercado espanhol e 2,5% no mercado alem\u00e3o. Os mercados belga e italiano registaram os menores crescimentos, 0,4% e 0,5%, respetivamente.<\/p>\n<p>Em compara\u00e7\u00e3o com o quarto trimestre de 2024, a demanda aumentou durante o primeiro trimestre de 2025 em todos os mercados europeus analisados. O mercado franc\u00eas registou o maior aumento, 14%. Seguiu-se o mercado ib\u00e9rico, com um aumento de 8,2% em Portugal e de 7,1% em Espanha. Os mercados italiano, alem\u00e3o, belga e brit\u00e2nico registaram aumentos que variaram entre 4,0% em It\u00e1lia e 5,9% na Gr\u00e3-Bretanha.<\/p>\n<p>No primeiro trimestre de 2025, Portugal atingiu um recorde ao registar a sua maior demanda trimestral de eletricidade at\u00e9 \u00e0 data, 14 TWh. Entretanto, a Gr\u00e3-Bretanha, a Alemanha e a Fran\u00e7a atingiram os seus valores mais elevados desde o primeiro trimestre de 2022, que foram de 66 TWh, 124 TWh e 130 TWh, respetivamente.<\/p>\n<p>A evolu\u00e7\u00e3o hom\u00f3loga das <strong>temperaturas m\u00e9dias<\/strong> registou uma tend\u00eancia descendente na compara\u00e7\u00e3o entre os primeiros trimestres de 2025 e 2024. As temperaturas m\u00e9dias diminu\u00edram em todos os mercados analisados, com descidas que variaram entre 0,5 \u00b0C em It\u00e1lia e 2,0 \u00b0C na B\u00e9lgica e na Alemanha.<\/p>\n<p>Em compara\u00e7\u00e3o com o quarto trimestre de 2024, as temperaturas m\u00e9dias no primeiro trimestre de 2025 diminu\u00edram em todos os mercados analisados. Estas descidas variaram entre 2,8 \u00b0C em It\u00e1lia e 3,4 \u00b0C em Espanha.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Monthly electricity demand Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-demand-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-demand-Europe.png' alt='AleaSoft - Monthly electricity demand Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado por AleaSoft Energy Forecasting utilizando dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica, TERNA, National Grid e ELIA.<\/span><\/div>\n<h2>Mercados europeus da eletricidade<\/h2>\n<p>No primeiro trimestre de 2025, o pre\u00e7o m\u00e9dio trimestral excedeu 85 euros\/MWh na maioria dos principais mercados europeus de eletricidade. A exce\u00e7\u00e3o foi o <strong>mercado Nord Pool<\/strong> dos pa\u00edses n\u00f3rdicos, onde a m\u00e9dia foi de 45,50 EUR\/MWh. O <strong>mercado N2EX<\/strong> do Reino Unido e o <strong>mercado IPEX<\/strong> de It\u00e1lia registaram os pre\u00e7os trimestrais mais elevados, 125,50 \u20ac\/MWh e 137,57 \u20ac\/MWh, respetivamente. Nos restantes mercados analisados no <strong>AleaSoft Energy Forecasting<\/strong>, as m\u00e9dias variaram entre os 85,12\u20ac\/MWh no <strong>mercado MIBEL<\/strong> de Portugal e os 111,94\u20ac\/MWh no <strong>mercado <\/strong> da Alemanha.<\/p>\n<p>Em compara\u00e7\u00e3o com o trimestre anterior, no primeiro trimestre de 2025, os pre\u00e7os aumentaram na maioria dos mercados europeus de eletricidade analisados no <strong>AleaSoft Energy Forecasting<\/strong>. As excep\u00e7\u00f5es foram os mercados espanhol e portugu\u00eas, com uma queda m\u00e9dia trimestral de pre\u00e7os de 10% em ambos os casos. Em contrapartida, o mercado n\u00f3rdico registou o maior aumento, 47%. Os restantes mercados registaram aumentos que variaram entre 7,8% no mercado neerland\u00eas e 15% nos mercados brit\u00e2nico e franc\u00eas.<\/p>\n<p>Comparando os pre\u00e7os m\u00e9dios do primeiro trimestre de 2025 com os registados no mesmo trimestre de 2024, os pre\u00e7os tamb\u00e9m subiram na maioria dos mercados analisados. Neste caso, a exce\u00e7\u00e3o foi o mercado n\u00f3rdico, com uma queda de 22%. Em contrapartida, os mercados espanhol e portugu\u00eas registaram os maiores aumentos, de 90% e 91%, respetivamente. Nos outros mercados, os aumentos oscilaram entre 50% no mercado italiano e 67% no mercado brit\u00e2nico.<\/p>\n<p>Em resultado destes aumentos de pre\u00e7os, a m\u00e9dia do primeiro trimestre de 2025 foi a mais elevada desde o segundo trimestre de 2023 nos mercados alem\u00e3o, belga, brit\u00e2nico, franc\u00eas, italiano e neerland\u00eas. No mercado n\u00f3rdico, a m\u00e9dia do primeiro trimestre de 2025 foi a mais elevada desde o segundo trimestre de 2024.<\/p>\n<p>No primeiro trimestre de 2025, os pre\u00e7os mais elevados do g\u00e1s e das licen\u00e7as de emiss\u00e3o de CO<sub>2<\/sub> e o aumento da demanda em quase todos os mercados conduziram a pre\u00e7os mais elevados nos mercados europeus da eletricidade, em compara\u00e7\u00e3o com o trimestre anterior. Para al\u00e9m disso, no caso do mercado alem\u00e3o, a produ\u00e7\u00e3o de energia e\u00f3lica diminuiu.<\/p>\n<p>Em compara\u00e7\u00e3o com o primeiro trimestre de 2024, os pre\u00e7os do g\u00e1s e das licen\u00e7as de emiss\u00e3o de CO<sub>2<\/sub> tamb\u00e9m subiram. Al\u00e9m disso, a demanda de eletricidade aumentou em quase todos os mercados e a produ\u00e7\u00e3o de energia e\u00f3lica diminuiu. Como resultado destes factores, a maioria dos mercados registou aumentos de pre\u00e7os anuais superiores a 50%.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Monthly electricity market prices Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png' alt='AleaSoft - Monthly electricity market prices Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado por AleaSoft Energy Forecasting utilizando dados do OMIE, , Nord Pool e GME.<\/span><\/div>\n<h2>Brent, combust\u00edveis e CO<sub>2<\/sub><\/h2>\n<p>Os futuros do <strong>petr\u00f3leo Brent<\/strong> para o Front-Month no <strong>mercado ICE<\/strong> registaram um pre\u00e7o m\u00e9dio trimestral de $74,98\/bbl no primeiro trimestre de 2025. Este valor foi superior em 1,3% ao pre\u00e7o dos futuros Front-Month do trimestre anterior, $74,01\/bbl. No entanto, foi 8,3% inferior ao pre\u00e7o m\u00e9dio correspondente aos futuros Front-Month transaccionados no primeiro trimestre de 2024, $81,76\/bbl.<\/p>\n<p>As preocupa\u00e7\u00f5es com a evolu\u00e7\u00e3o da demanda mundial de petr\u00f3leo, causadas pelas pol\u00edticas tarif\u00e1rias dos EUA, levaram a uma descida hom\u00f3loga dos pre\u00e7os dos futuros do petr\u00f3leo Brent no primeiro trimestre de 2025. O abrandamento da instabilidade no M\u00e9dio Oriente durante as \u00faltimas tr\u00e9guas no conflito entre Israel e o Hamas, bem como a possibilidade de um acordo de paz para a Ucr\u00e2nia, tamb\u00e9m exerceram uma influ\u00eancia descendente sobre os pre\u00e7os. Al\u00e9m disso, a perspetiva de aumento da produ\u00e7\u00e3o em pa\u00edses como os Estados Unidos e o Iraque, bem como os aumentos de produ\u00e7\u00e3o da OPEP+ previstos para os pr\u00f3ximos trimestres, tamb\u00e9m pesaram sobre os pre\u00e7os. No entanto, as san\u00e7\u00f5es \u00e0s exporta\u00e7\u00f5es do Ir\u00e3o e da Venezuela, bem como os est\u00edmulos \u00e0 economia chinesa, contribu\u00edram para limitar a descida dos pre\u00e7os, que, em m\u00e9dia, foram ligeiramente superiores aos do trimestre anterior.<\/p>\n<p>Quanto aos futuros de <strong>g\u00e1s TTF<\/strong> no mercado ICE para o Front-Month, o valor m\u00e9dio registado durante o primeiro trimestre de 2025 para estes futuros foi de 46,77\u20ac\/MWh. Face ao pre\u00e7o m\u00e9dio dos futuros Front-Month negociados no trimestre anterior, \u20ac43,34\/MWh, a m\u00e9dia registou um aumento de 7,9%. Em rela\u00e7\u00e3o aos futuros Front-Month negociados no mesmo trimestre de 2024, em que o pre\u00e7o m\u00e9dio era de \u20ac27,56\/MWh, registou-se uma subida de 70%. Como consequ\u00eancia destes aumentos, no primeiro trimestre de 2025, o pre\u00e7o m\u00e9dio foi o mais elevado desde o segundo trimestre de 2023.<\/p>\n<p>No primeiro trimestre de 2025, as baixas temperaturas e o fim do fornecimento de g\u00e1s russo atrav\u00e9s da Ucr\u00e2nia conduziram a pre\u00e7os mais elevados. As preocupa\u00e7\u00f5es com os baixos n\u00edveis das reservas europeias tamb\u00e9m contribu\u00edram para o aumento dos pre\u00e7os dos futuros do g\u00e1s TTF. No entanto, as conversa\u00e7\u00f5es para p\u00f4r fim \u00e0 guerra na Ucr\u00e2nia exerceram uma influ\u00eancia descendente sobre os pre\u00e7os, com a possibilidade de o fim da guerra poder levar a um aumento do fornecimento de g\u00e1s russo. No final do trimestre, as temperaturas mais amenas tamb\u00e9m contribu\u00edram para limitar a subida do pre\u00e7o m\u00e9dio trimestral.<\/p>\n<p>Relativamente aos futuros de <strong>licen\u00e7as de emiss\u00e3o de CO<sub>2<\/sub><\/strong> no <strong>mercado EEX<\/strong> para o contrato de refer\u00eancia de dezembro de 2025, estes atingiram um pre\u00e7o m\u00e9dio de 75,17\u20ac\/t no primeiro trimestre de 2025, 10% superior \u00e0 m\u00e9dia do trimestre anterior, que foi de 68,10\u20ac\/t. Em compara\u00e7\u00e3o com a m\u00e9dia do mesmo trimestre de 2024, 63,90 \u20ac\/t, a m\u00e9dia do primeiro trimestre de 2025 foi 18% superior.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Prices gas coal Brent oil CO2' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png' alt='AleaSoft - Prices gas coal Brent oil CO2' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado por AleaSoft Energy Forecasting utilizando dados da ICE e EEX.<\/span><\/div>\n<h2>An\u00e1lise da AleaSoft Energy Forecasting sobre armazenamento de energia<\/h2>\n<p>A divis\u00e3o <strong>AleaStorage<\/strong> da <strong>AleaSoft Energy Forecasting<\/strong> fornece relat\u00f3rios de previs\u00e3o para a otimiza\u00e7\u00e3o e gest\u00e3o de sistemas <strong>de armazenamento de energia<\/strong>. <a href=\"https:\/\/aleasoft.com\/pt\/aleastorage-servicos\/\">Os servi\u00e7os <strong>do AleaStorage<\/strong><\/a> incluem o c\u00e1lculo das receitas e da rentabilidade dos sistemas com armazenamento de energia, bem como o dimensionamento \u00f3timo das baterias para sistemas h\u00edbridos com energias renov\u00e1veis. Estes servi\u00e7os est\u00e3o dispon\u00edveis para projectos <strong>de baterias<\/strong> aut\u00f3nomas, sistemas h\u00edbridos de <strong>tecnologias renov\u00e1veis<\/strong>, como a energia <strong>e\u00f3lica<\/strong> e <strong>solar<\/strong>, com baterias, sistemas h\u00edbridos de <strong>autoconsumo<\/strong> com baterias e outros sistemas h\u00edbridos, como a <strong>hidr\u00e1ulica<\/strong>, <strong>a bombagem revers\u00edvel<\/strong> e <strong>a cogera\u00e7\u00e3o<\/strong>.<\/p>\n<p>Fonte: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 1 de abril de 2025. No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade. Em v\u00e1rios mercados, o pre\u00e7o m\u00e9dio trimestral foi o mais elevado desde o segundo trimestre de 2023. Um dos principais factores desta subida foi o aumento dos pre\u00e7os do g\u00e1s, cuja [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":155724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7637,7514],"tags":[7602,7601,7600,7599,7604,7605,7603],"class_list":["post-155734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analise-trimestral","category-noticias","tag-demanda-eletrica","tag-energia-eolica","tag-energia-fotovoltaica","tag-mercados-eletricos-europeus","tag-precos-brent","tag-precos-co2","tag-precos-gas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos\" \/>\n<meta property=\"og:description\" content=\"No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T16:22:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T15:21:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\"},\"headline\":\"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos\",\"datePublished\":\"2025-04-01T16:22:20+00:00\",\"dateModified\":\"2025-05-07T15:21:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/\"},\"wordCount\":1971,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"keywords\":[\"Demanda\",\"E\u00f3lica\",\"Fotovoltaica\",\"Mercados\",\"Pre\u00e7os Brent\",\"Pre\u00e7os CO2\",\"Pre\u00e7os g\u00e1s\"],\"articleSection\":[\"An\u00e1lise trimestral\",\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/\",\"name\":\"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"datePublished\":\"2025-04-01T16:22:20+00:00\",\"dateModified\":\"2025-05-07T15:21:09+00:00\",\"description\":\"No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png\",\"width\":2282,\"height\":1582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/#\\\/schema\\\/person\\\/e83ba5c714f71473e3096e6f5bffcd61\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos - AleaSoft Energy Forecasting","description":"No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/","og_locale":"pt_PT","og_type":"article","og_title":"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos","og_description":"No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade.","og_url":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2025-04-01T16:22:20+00:00","article_modified_time":"2025-05-07T15:21:09+00:00","og_image":[{"width":2282,"height":1582,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tempo estimado de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/pt\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61"},"headline":"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos","datePublished":"2025-04-01T16:22:20+00:00","dateModified":"2025-05-07T15:21:09+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/pt\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/"},"wordCount":1971,"publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png","keywords":["Demanda","E\u00f3lica","Fotovoltaica","Mercados","Pre\u00e7os Brent","Pre\u00e7os CO2","Pre\u00e7os g\u00e1s"],"articleSection":["An\u00e1lise trimestral","Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/pt\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/","url":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/","name":"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png","datePublished":"2025-04-01T16:22:20+00:00","dateModified":"2025-05-07T15:21:09+00:00","description":"No primeiro trimestre de 2025, os pre\u00e7os subiram na maioria dos principais mercados europeus de eletricidade.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2025\/04\/20250401-AleaSoft-Monthly-electricity-market-prices-Europe.png","width":2282,"height":1582},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/gas-co2-demanda-precos-mercados-european-q1-maximo-2-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/pt\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lise do primeiro trimestre 2025 O g\u00e1s, o CO2 e a demanda levam os pre\u00e7os do mercado europeu da eletricidade no primeiro trimestre a atingir m\u00e1ximos de dois anos"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/#website","url":"https:\/\/aleasoft.com\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/#\/schema\/person\/e83ba5c714f71473e3096e6f5bffcd61","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f3c80a49711746195eaa8b9dac85dd25b10ed81cf9cd40ba1c909b7c8d60bfb?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"}}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts\/155734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/comments?post=155734"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts\/155734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/media\/155724"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/media?parent=155734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/categories?post=155734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/tags?post=155734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}