{"id":168369,"date":"2026-06-29T14:52:55","date_gmt":"2026-06-29T12:52:55","guid":{"rendered":"https:\/\/aleasoft.com\/?p=168369"},"modified":"2026-06-30T10:47:55","modified_gmt":"2026-06-30T08:47:55","slug":"onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho","status":"publish","type":"post","link":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/","title":{"rendered":"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho"},"content":{"rendered":"<p><strong>AleaSoft Energy Forecasting, 29 de junho de 2026. Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh. A menor produ\u00e7\u00e3o de energia e\u00f3lica na Alemanha e em It\u00e1lia tamb\u00e9m contribuiu para esta tend\u00eancia. A Alemanha e a Espanha estabeleceram recordes de produ\u00e7\u00e3o de energia solar fotovoltaica, enquanto os futuros do g\u00e1s TTF e os futuros do Brent atingiram os seus n\u00edveis mais baixos desde abril e fevereiro, respetivamente.<\/strong><\/p>\n<h2>Produ\u00e7\u00e3o de energia solar fotovoltaica e e\u00f3lica<\/h2>\n<p>Na semana de 22 de junho, a <strong>produ\u00e7\u00e3o de energia solar fotovoltaica<\/strong> aumentou na maioria dos principais mercados el\u00e9tricos europeus em compara\u00e7\u00e3o com a semana anterior. A Alemanha registou o maior aumento, 16%, enquanto a Espanha registou a menor subida, 0.5%. Ambos os mercados registaram a sua segunda semana consecutiva de crescimento. A Fran\u00e7a aumentou 2.5% e registou a sua terceira subida semanal consecutiva. Em contrapartida, a It\u00e1lia e Portugal registaram descidas de 5.1% e 22%, respetivamente, invertendo a tend\u00eancia ascendente das duas semanas anteriores.<\/p>\n<p>Durante a semana, a Alemanha e a Espanha atingiram recordes de produ\u00e7\u00e3o de energia solar fotovoltaica. A 24 de junho, a Alemanha registou a sua maior produ\u00e7\u00e3o de energia solar fotovoltaica para um dia de junho, com 489&nbsp;GWh, um valor que representou a segunda maior produ\u00e7\u00e3o da sua hist\u00f3ria. A Espanha, por seu lado, atingiu o seu m\u00e1ximo hist\u00f3rico de produ\u00e7\u00e3o de energia solar fotovoltaica na sexta-feira, 26 de junho, com 267&nbsp;GWh.<\/p>\n<p>Para a semana de 29 de junho, as <a href=\"https:\/\/aleasoft.com\/pt\/produtos-e-servicos\/previsoes-de-energia-solar\/\">previs\u00f5es de energia solar<\/a> da <strong>AleaSoft Energy Forecasting<\/strong> apontam para um aumento no mercado italiano. Em contrapartida, a produ\u00e7\u00e3o de energia solar diminuir\u00e1 nos mercados espanhol e alem\u00e3o.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Photovoltaic energy production electricity Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Photovoltaic-energy-production-electricity-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Photovoltaic-energy-production-electricity-Europe.png' alt='AleaSoft - Photovoltaic energy production electricity Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado pela AleaSoft Energy Forecasting com dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica e TERNA.<\/span><\/div>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Solar photovoltaic production profile Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Solar-photovoltaic-production-profile-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Solar-photovoltaic-production-profile-Europe.png' alt='AleaSoft - Solar photovoltaic production profile Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado pela AleaSoft Energy Forecasting com dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica e TERNA.<\/span><\/div>\n<p>Na \u00faltima semana de junho, a <strong>produ\u00e7\u00e3o de energia e\u00f3lica<\/strong> aumentou na maioria dos principais mercados el\u00e9tricos europeus em compara\u00e7\u00e3o com a semana anterior. Portugal registou o maior aumento, 54%, seguido pela Fran\u00e7a e pela Espanha, com aumentos de 32% e 23%, respetivamente. Em contrapartida, a It\u00e1lia e a Alemanha acumularam a sua segunda semana consecutiva de descidas. Desta vez, a produ\u00e7\u00e3o de energia e\u00f3lica caiu 10% em It\u00e1lia e 40% na Alemanha.<\/p>\n<p>Para a primeira semana de julho, as <a href=\"https:\/\/aleasoft.com\/pt\/produtos-e-servicos\/previsoes-de-energia-eolica\/\">previs\u00f5es de energia e\u00f3lica<\/a> da <strong>AleaSoft Energy Forecasting<\/strong> apontam para aumentos generalizados nos principais mercados el\u00e9tricos europeus analisados.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Wind energy production electricity Europe' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Wind-energy-production-electricity-Europe.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Wind-energy-production-electricity-Europe.png' alt='AleaSoft - Wind energy production electricity Europe' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado pela AleaSoft Energy Forecasting com dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica e TERNA.<\/span><\/div>\n<h2>Procura de eletricidade<\/h2>\n<p>Na \u00faltima semana de junho, a <strong>procura de eletricidade<\/strong> aumentou nos principais mercados el\u00e9tricos europeus em compara\u00e7\u00e3o com a semana anterior. A It\u00e1lia registou o maior aumento, 10%, seguida pela Fran\u00e7a, com 9.9%, e pela B\u00e9lgica, com 7.3%. Portugal registou a menor subida, 0.1%. A Espanha, a Gr\u00e3-Bretanha e a Alemanha registaram aumentos que variaram entre 3.1% em Espanha e 6.0% na Alemanha. A procura na Gr\u00e3-Bretanha cresceu pela segunda semana consecutiva, enquanto a procura na Alemanha, em Fran\u00e7a, em Portugal, em It\u00e1lia e na B\u00e9lgica acumulou o seu terceiro aumento semanal consecutivo. Em Espanha, a procura registou a sua sexta subida semanal consecutiva.<\/p>\n<p>Durante a semana, as <strong>temperaturas m\u00e9dias<\/strong> aumentaram em todos os mercados analisados. A Alemanha registou o maior aumento, 5.2&nbsp;\u00b0C, enquanto Portugal registou o menor, 0.7&nbsp;\u00b0C. Em Espanha, em It\u00e1lia, em Fran\u00e7a, na B\u00e9lgica e na Gr\u00e3-Bretanha, as temperaturas m\u00e9dias subiram entre 1.1&nbsp;\u00b0C em Espanha e 4.7&nbsp;\u00b0C na Gr\u00e3-Bretanha.<\/p>\n<p>Este aumento das temperaturas coincidiu com epis\u00f3dios de calor nos mercados analisados. A Fran\u00e7a, a It\u00e1lia, a B\u00e9lgica e a Alemanha enfrentaram condi\u00e7\u00f5es de onda de calor durante a segunda metade de junho, enquanto a Espanha registou uma onda de calor entre 21 e 24 de junho. A Gr\u00e3-Bretanha registou um epis\u00f3dio de calor intenso entre 24 e 28 de junho, em especial em Inglaterra e no Pa\u00eds de Gales. Em Portugal, as temperaturas elevadas impulsionaram igualmente a procura de eletricidade, embora a procura semanal tenha crescido de forma mais moderada do que no resto dos mercados analisados.<\/p>\n<p>Para a primeira semana de julho, as <a href=\"https:\/\/aleasoft.com\/pt\/servicos\/previsoes-demanda-energia\/\">previs\u00f5es de procura<\/a> da <strong>AleaSoft Energy Forecasting<\/strong> indicam descidas nos mercados el\u00e9tricos de Espanha, It\u00e1lia, Fran\u00e7a, Alemanha, B\u00e9lgica e Gr\u00e3-Bretanha. Por outro lado, a procura aumentar\u00e1 no mercado portugu\u00eas face \u00e0s temperaturas elevadas durante esses dias.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Electricity demand European countries' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Electricity-demand-European-countries.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Electricity-demand-European-countries.png' alt='AleaSoft - Electricity demand European countries' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado pela AleaSoft Energy Forecasting com dados da ENTSO-E, RTE, REN, Red El\u00e9ctrica, TERNA, National Grid e ELIA.<\/span><\/div>\n<h2>Mercados el\u00e9tricos europeus<\/h2>\n<p>Os pre\u00e7os di\u00e1rios nos principais mercados europeus aumentaram acentuadamente durante os primeiros dias da quarta semana de junho. Embora os pre\u00e7os tenham descido posteriormente, os pre\u00e7os m\u00e9dios semanais aumentaram em compara\u00e7\u00e3o com a semana anterior em todos os mercados el\u00e9tricos europeus. O mercado portugu\u00eas registou a menor subida de pre\u00e7os, 2.1%. Em contrapartida, o mercado franc\u00eas registou a maior subida percentual de pre\u00e7os, 39%. No resto dos mercados analisados na <strong>AleaSoft Energy Forecasting<\/strong>, os pre\u00e7os subiram entre 5.1% no mercado espanhol e 37% no mercado belga.<\/p>\n<p>Na semana de 22 de junho, as m\u00e9dias semanais ultrapassaram \u20ac115\/MWh na maioria dos mercados el\u00e9tricos europeus. As exce\u00e7\u00f5es inclu\u00edram o mercado n\u00f3rdico, com uma m\u00e9dia de \u20ac68.24\/MWh, e os mercados espanhol e portugu\u00eas, ambos com uma m\u00e9dia de \u20ac87.37\/MWh. Em contrapartida, o mercado belga registou a m\u00e9dia semanal mais elevada, \u20ac148.34\/MWh. No resto dos mercados analisados na <strong>AleaSoft Energy Forecasting<\/strong>, os pre\u00e7os variaram entre \u20ac115.75\/MWh no mercado franc\u00eas e \u20ac144.67\/MWh no mercado italiano.<\/p>\n<p>Quanto aos pre\u00e7os di\u00e1rios, o mercado n\u00f3rdico registou pre\u00e7os inferiores a \u20ac100\/MWh ao longo de toda a quarta semana de junho. Os pre\u00e7os nos mercados espanhol e portugu\u00eas mantiveram-se igualmente abaixo de \u20ac100\/MWh durante quase toda a semana, exceto na ter\u00e7a-feira, 23 de junho. Na segunda-feira, 22 de junho, o mercado n\u00f3rdico registou a m\u00e9dia di\u00e1ria mais baixa da semana entre os mercados analisados, \u20ac35.29\/MWh.<\/p>\n<p>Por outro lado, os pre\u00e7os di\u00e1rios ultrapassaram \u20ac120\/MWh ao longo de toda a quarta semana de junho no mercado italiano. Os pre\u00e7os ultrapassaram tamb\u00e9m este n\u00edvel nos mercados alem\u00e3o, belga, brit\u00e2nico e neerland\u00eas de segunda a sexta-feira, e no mercado franc\u00eas em tr\u00eas ocasi\u00f5es durante a quarta semana de junho. A 24 de junho, o mercado belga registou a m\u00e9dia di\u00e1ria mais elevada da semana entre os mercados analisados, \u20ac257.55\/MWh. Este valor marcou o seu pre\u00e7o mais elevado desde 13 de dezembro de 2024. Nesse dia, o mercado neerland\u00eas atingiu tamb\u00e9m o seu pre\u00e7o mais elevado desde 13 de dezembro de 2024, \u20ac227.99\/MWh. Por seu lado, os mercados franc\u00eas e brit\u00e2nico atingiram os seus pre\u00e7os mais elevados desde janeiro de 2025, \u20ac157.87\/MWh e \u20ac184.65\/MWh, respetivamente, enquanto o mercado alem\u00e3o registou o seu pre\u00e7o mais elevado desde novembro de 2025, \u20ac207.84\/MWh. O mercado italiano registou o seu pre\u00e7o mais elevado desde mar\u00e7o de 2026, \u20ac162.66\/MWh. Os mercados espanhol e portugu\u00eas atingiram igualmente o seu pre\u00e7o mais elevado desde mar\u00e7o de 2026, \u20ac112.42\/MWh em ambos os casos, mas a 23 de junho.<\/p>\n<p>Na semana de 22 de junho, a maior procura fez subir os pre\u00e7os nos mercados el\u00e9tricos europeus. A menor produ\u00e7\u00e3o de energia e\u00f3lica na Alemanha e em It\u00e1lia, bem como a menor produ\u00e7\u00e3o de energia solar em Espanha, em It\u00e1lia e em Portugal, contribu\u00edram tamb\u00e9m para as subidas de pre\u00e7os nestes mercados.<\/p>\n<p>As <a href=\"https:\/\/aleasoft.com\/pt\/servicos\/previsoes-precos-energia\/\">previs\u00f5es de pre\u00e7os<\/a> da <strong>AleaSoft Energy Forecasting<\/strong> indicam que, na primeira semana de julho, os pre\u00e7os descer\u00e3o nos mercados el\u00e9tricos europeus, impulsionados por uma maior produ\u00e7\u00e3o de energia e\u00f3lica e por uma menor procura na maioria dos mercados. Al\u00e9m disso, a produ\u00e7\u00e3o de energia solar aumentar\u00e1 em It\u00e1lia. No entanto, a evolu\u00e7\u00e3o dos pre\u00e7os do g\u00e1s influenciar\u00e1 tamb\u00e9m os pre\u00e7os dos mercados el\u00e9tricos europeus.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - European electricity market prices' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png' alt='AleaSoft - European electricity market prices' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado pela AleaSoft Energy Forecasting com dados da OMIE, RTE, Nord Pool e GME.<\/span><\/div>\n<h2>Brent, combust\u00edveis e CO<sub>2<\/sub><\/h2>\n<p>Os futuros do <strong>petr\u00f3leo Brent<\/strong> para o Front\u2011Month no <strong>mercado ICE<\/strong> atingiram o seu pre\u00e7o de fecho m\u00e1ximo semanal, $77.90\/bbl, na segunda-feira, 22 de junho. No entanto, este pre\u00e7o situava-se j\u00e1 3.3% abaixo do pre\u00e7o da sexta-feira anterior. Estes futuros registaram descidas de pre\u00e7o em quase todas as sess\u00f5es da quarta semana de junho. Como resultado, na sexta-feira, 26 de junho, atingiram o seu pre\u00e7o de fecho m\u00ednimo semanal, $71.99\/bbl. De acordo com os dados analisados na <strong>AleaSoft Energy Forecasting<\/strong>, este pre\u00e7o situava-se 11% abaixo do pre\u00e7o da sexta-feira anterior e marcou o n\u00edvel mais baixo desde 27 de fevereiro.<\/p>\n<p>Durante a quarta semana de junho, os pre\u00e7os dos futuros do petr\u00f3leo Brent desceram sob a press\u00e3o do aumento do tr\u00e1fego atrav\u00e9s do Estreito de Ormuz e dos progressos nas negocia\u00e7\u00f5es entre os Estados Unidos e o Ir\u00e3o para alcan\u00e7ar um acordo de paz que ponha fim ao conflito.<\/p>\n<p>Quanto aos futuros do <strong>g\u00e1s TTF<\/strong> no mercado ICE para o Front\u2011Month, atingiram o seu pre\u00e7o de fecho m\u00e1ximo semanal, \u20ac42.01\/MWh, na ter\u00e7a-feira, 23 de junho. Durante o resto da semana, os pre\u00e7os mantiveram-se abaixo de \u20ac41\/MWh. Na quinta-feira, 25 de junho, estes futuros registaram o seu pre\u00e7o de fecho m\u00ednimo semanal, \u20ac40.41\/MWh. De acordo com os dados analisados na <strong>AleaSoft Energy Forecasting<\/strong>, este pre\u00e7o marcou o n\u00edvel mais baixo desde 21 de abril. Na sexta-feira, 26 de junho, o pre\u00e7o de fecho subiu ligeiramente para \u20ac40.78\/MWh. Este pre\u00e7o situava-se ainda 3.1% abaixo do n\u00edvel da sexta-feira anterior.<\/p>\n<p>O aumento do tr\u00e1fego atrav\u00e9s do Estreito de Ormuz fez descer os pre\u00e7os dos futuros do g\u00e1s TTF na quarta semana de junho. No entanto, os baixos n\u00edveis das reservas e a maior procura na Europa contribu\u00edram para manter os pre\u00e7os acima de \u20ac40\/MWh.<\/p>\n<p>Relativamente aos futuros das <strong>licen\u00e7as de emiss\u00e3o<\/strong> de <strong>CO<sub>2<\/sub><\/strong> no <strong>mercado EEX<\/strong> para o contrato de refer\u00eancia de dezembro de 2026, registaram o seu pre\u00e7o de fecho m\u00ednimo semanal, \u20ac76.17\/t, na ter\u00e7a-feira, 23 de junho. Depois de subirem 1.8% em compara\u00e7\u00e3o com ter\u00e7a-feira, estes futuros atingiram o seu pre\u00e7o de fecho m\u00e1ximo semanal, \u20ac77.52\/t, a 24 de junho. Nas \u00faltimas sess\u00f5es da quarta semana de junho, os pre\u00e7os de fecho desceram, mas mantiveram-se acima de \u20ac77\/t. Na sexta-feira, 26 de junho, o pre\u00e7o de fecho atingiu \u20ac77.17\/t. De acordo com os dados analisados na <strong>AleaSoft Energy Forecasting<\/strong>, este pre\u00e7o situava-se 4.2% abaixo do n\u00edvel da sexta-feira anterior.<\/p>\n<div style='margin-top: 20px;margin-bottom: 20px;'><a title='AleaSoft - Prices gas coal Brent oil CO2' href='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png'><img class='aligncenter' src='https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-Prices-gas-coal-Brent-oil-CO2.png' alt='AleaSoft - Prices gas coal Brent oil CO2' width='740'\/><\/a><span style='font-size: small;'>Fonte: Elaborado pela AleaSoft Energy Forecasting com dados da ICE e EEX.<\/span><\/div>\n<h2>A an\u00e1lise da AleaSoft Energy Forecasting sobre as perspetivas dos mercados de energia na Europa<\/h2>\n<p>Na quinta-feira, 9 de julho, a <strong>AleaSoft Energy Forecasting<\/strong> realizar\u00e1 a <a href=\"https:\/\/aleasoft.com\/webinars\/markets-ppa-financing-storage-july-2026\/\">68.<sup>a<\/sup> edi\u00e7\u00e3o<\/a> da sua <a href=\"https:\/\/aleasoft.com\/webinars\/\">s\u00e9rie de webinars mensais<\/a>. Al\u00e9m da evolu\u00e7\u00e3o e das perspetivas dos <strong>mercados de energia<\/strong> europeus, esta edi\u00e7\u00e3o analisar\u00e1 a situa\u00e7\u00e3o atual e as perspetivas dos <strong>PPA<\/strong>, do <strong>financiamento de projetos de energias renov\u00e1veis e de armazenamento<\/strong>, bem como as perspetivas do <strong>armazenamento de energia<\/strong> e as oportunidades de <strong>hibridiza\u00e7\u00e3o<\/strong> com as <strong>energias renov\u00e1veis<\/strong> e o <strong>autoconsumo<\/strong>. A mesa de an\u00e1lise do webinar em espanhol contar\u00e1 com Pedro Gonz\u00e1lez, Diretor-Geral da AEGE, e Roger Font, Managing Director Project Finance Energy no Banco Sabadell.<\/p>\n<p>Fonte: <strong>AleaSoft Energy Forecasting<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AleaSoft Energy Forecasting, 29 de junho de 2026. Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh. A menor produ\u00e7\u00e3o de energia e\u00f3lica na Alemanha e em It\u00e1lia tamb\u00e9m contribuiu [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":168337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7598,7514],"tags":[7602,7601,7600,7599,7604,7605,7603],"class_list":["post-168369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analise-semanal","category-noticias","tag-demanda-eletrica","tag-energia-eolica","tag-energia-fotovoltaica","tag-mercados-eletricos-europeus","tag-precos-brent","tag-precos-co2","tag-precos-gas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho - AleaSoft Energy Forecasting<\/title>\n<meta name=\"description\" content=\"Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho\" \/>\n<meta property=\"og:description\" content=\"Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/\" \/>\n<meta property=\"og:site_name\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AleaSoft\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-29T12:52:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T08:47:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"AleaSoft Energy Forecasting\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@AleaSoftEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AleaSoft Energy Forecasting\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/\"},\"author\":{\"name\":\"AleaSoft Energy Forecasting\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#\\\/schema\\\/person\\\/a04e0c08213b14a8b93a577183bdeaf0\"},\"headline\":\"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho\",\"datePublished\":\"2026-06-29T12:52:55+00:00\",\"dateModified\":\"2026-06-30T08:47:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/\"},\"wordCount\":2096,\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260629-AleaSoft-European-electricity-market-prices.png\",\"keywords\":[\"Demanda\",\"E\u00f3lica\",\"Fotovoltaica\",\"Mercados\",\"Pre\u00e7os Brent\",\"Pre\u00e7os CO2\",\"Pre\u00e7os g\u00e1s\"],\"articleSection\":[\"An\u00e1lise semanal\",\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/\",\"name\":\"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho - AleaSoft Energy Forecasting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260629-AleaSoft-European-electricity-market-prices.png\",\"datePublished\":\"2026-06-29T12:52:55+00:00\",\"dateModified\":\"2026-06-30T08:47:55+00:00\",\"description\":\"Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\\\/MWh.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260629-AleaSoft-European-electricity-market-prices.png\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260629-AleaSoft-European-electricity-market-prices.png\",\"width\":730,\"height\":509},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/\",\"name\":\"AleaSoft Energy Forecasting\",\"description\":\"Energy Forecasting\",\"publisher\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#organization\",\"name\":\"AleaSoft Energy Forecasting\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"contentUrl\":\"https:\\\/\\\/aleasoft.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-alea-25.svg\",\"width\":7047,\"height\":1416,\"caption\":\"AleaSoft Energy Forecasting\"},\"image\":{\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AleaSoft\\\/\",\"https:\\\/\\\/x.com\\\/AleaSoftEnergy\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aleasoft\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aleasoft.com\\\/pt\\\/#\\\/schema\\\/person\\\/a04e0c08213b14a8b93a577183bdeaf0\",\"name\":\"AleaSoft Energy Forecasting\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed06b57a5c50e4941e805c13a40b4f0c833747a8db3a9d8d16929cbf232e8e0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed06b57a5c50e4941e805c13a40b4f0c833747a8db3a9d8d16929cbf232e8e0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed06b57a5c50e4941e805c13a40b4f0c833747a8db3a9d8d16929cbf232e8e0a?s=96&d=mm&r=g\",\"caption\":\"AleaSoft Energy Forecasting\"},\"sameAs\":[\"http:\\\/\\\/aleasoft.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho - AleaSoft Energy Forecasting","description":"Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/","og_locale":"pt_PT","og_type":"article","og_title":"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho","og_description":"Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh.","og_url":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/","og_site_name":"AleaSoft Energy Forecasting","article_publisher":"https:\/\/www.facebook.com\/AleaSoft\/","article_published_time":"2026-06-29T12:52:55+00:00","article_modified_time":"2026-06-30T08:47:55+00:00","og_image":[{"width":730,"height":509,"url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png","type":"image\/png"}],"author":"AleaSoft Energy Forecasting","twitter_card":"summary_large_image","twitter_creator":"@AleaSoftEnergy","twitter_site":"@AleaSoftEnergy","twitter_misc":{"Escrito por":"AleaSoft Energy Forecasting","Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#article","isPartOf":{"@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/"},"author":{"name":"AleaSoft Energy Forecasting","@id":"https:\/\/aleasoft.com\/pt\/#\/schema\/person\/a04e0c08213b14a8b93a577183bdeaf0"},"headline":"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho","datePublished":"2026-06-29T12:52:55+00:00","dateModified":"2026-06-30T08:47:55+00:00","mainEntityOfPage":{"@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/"},"wordCount":2096,"publisher":{"@id":"https:\/\/aleasoft.com\/pt\/#organization"},"image":{"@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png","keywords":["Demanda","E\u00f3lica","Fotovoltaica","Mercados","Pre\u00e7os Brent","Pre\u00e7os CO2","Pre\u00e7os g\u00e1s"],"articleSection":["An\u00e1lise semanal","Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/","url":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/","name":"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho - AleaSoft Energy Forecasting","isPartOf":{"@id":"https:\/\/aleasoft.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#primaryimage"},"image":{"@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png","datePublished":"2026-06-29T12:52:55+00:00","dateModified":"2026-06-30T08:47:55+00:00","description":"Na quarta semana de junho, a onda de calor marcou os mercados el\u00e9tricos europeus ao fazer subir a procura e ao impulsionar os pre\u00e7os m\u00e9dios semanais, com a maioria dos mercados a ultrapassar \u20ac115\/MWh.","breadcrumb":{"@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#primaryimage","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2026\/06\/20260629-AleaSoft-European-electricity-market-prices.png","width":730,"height":509},{"@type":"BreadcrumbList","@id":"https:\/\/aleasoft.com\/pt\/onda-calor-faz-subir-procura-precos-mercados-eletricos-europeus-ultima-semana-junho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aleasoft.com\/pt\/"},{"@type":"ListItem","position":2,"name":"A onda de calor faz subir a procura e os pre\u00e7os nos mercados el\u00e9tricos europeus na \u00faltima semana de junho"}]},{"@type":"WebSite","@id":"https:\/\/aleasoft.com\/pt\/#website","url":"https:\/\/aleasoft.com\/pt\/","name":"AleaSoft Energy Forecasting","description":"Energy Forecasting","publisher":{"@id":"https:\/\/aleasoft.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aleasoft.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aleasoft.com\/pt\/#organization","name":"AleaSoft Energy Forecasting","url":"https:\/\/aleasoft.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aleasoft.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","contentUrl":"https:\/\/aleasoft.com\/wp-content\/uploads\/2020\/01\/logo-alea-25.svg","width":7047,"height":1416,"caption":"AleaSoft Energy Forecasting"},"image":{"@id":"https:\/\/aleasoft.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AleaSoft\/","https:\/\/x.com\/AleaSoftEnergy","https:\/\/www.linkedin.com\/company\/aleasoft\/"]},{"@type":"Person","@id":"https:\/\/aleasoft.com\/pt\/#\/schema\/person\/a04e0c08213b14a8b93a577183bdeaf0","name":"AleaSoft Energy Forecasting","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/ed06b57a5c50e4941e805c13a40b4f0c833747a8db3a9d8d16929cbf232e8e0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed06b57a5c50e4941e805c13a40b4f0c833747a8db3a9d8d16929cbf232e8e0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed06b57a5c50e4941e805c13a40b4f0c833747a8db3a9d8d16929cbf232e8e0a?s=96&d=mm&r=g","caption":"AleaSoft Energy Forecasting"},"sameAs":["http:\/\/aleasoft.com"]}]}},"_links":{"self":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts\/168369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/comments?post=168369"}],"version-history":[{"count":0,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/posts\/168369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/media\/168337"}],"wp:attachment":[{"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/media?parent=168369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/categories?post=168369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleasoft.com\/pt\/wp-json\/wp\/v2\/tags?post=168369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}